{"id":932,"date":"2020-01-10T03:53:16","date_gmt":"2020-01-10T03:53:16","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=932"},"modified":"2020-01-10T03:53:16","modified_gmt":"2020-01-10T03:53:16","slug":"mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/","title":{"rendered":"Mali : Le budget pr\u00e9visionnel 2020 de l\u2019INPS, s\u2019\u00e9l\u00e8ve \u00e0 plus de 200 milliards de FCFA"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">La 92 session ordinaire du Conseil d\u2019administration de l\u2019institut\nnational de pr\u00e9voyance sociale (INPS), s\u2019est tenue le lundi 30 d\u00e9cembre\n2019,&nbsp; dans les locaux de la direction. Elle a \u00e9t\u00e9 Pr\u00e9sid\u00e9e par le\npr\u00e9sident du conseil d\u2019administration, Mamadou Sinsy COULIBALY,&nbsp; en pr\u00e9sence de la directrice de l\u2019INPS, Mme\nSIDIBE Zamilatou CISSE et des administrateurs.<\/h4>\n\n\n\n<p>Le projet de\nbudget 2020 s\u2019inspire du mod\u00e8le de budget en mode programme r\u00e9cemment introduit\ndans le budget d\u2019\u00c9tat 2020. Par cette m\u00e9thode, l\u2019objectif vis\u00e9 est la gestion\nrecherch\u00e9e sur les r\u00e9sultats et les performances des structures, \u00e0 en croire<strong> <\/strong>le pr\u00e9sident\ndu conseil d\u2019administration, Mamadou Sinsy COULIBALY.<\/p>\n\n\n\n<p>L\u2019ordre du jour de\ncette session ordinaire portait sur l\u2019examen et l\u2019adoption du projet de Budget\n2020, le programme d\u2019activit\u00e9s 2020, mais aussi celui de la gestion d\u00e9l\u00e9gu\u00e9e de\nl\u2019Assurance Maladie Obligatoire (AMO). <\/p>\n\n\n\n<p>Mamadou Sinsy\nCOULIBALY a indiqu\u00e9 que cette 92i\u00e8me session du conseil d\u2019administration de\nl\u2019institut se tient \u00e0 une \u00e9tape importante de l\u2019\u00e9volution de la politique\nnationale de protection sociale marqu\u00e9e par la volont\u00e9 des plus hautes\nautorit\u00e9s de renforcer le socle de la protection sociale \u00e0 travers l\u2019extension\ndes prestations sociales \u00e0 plus grande couche de la population et par la mise\nen route du R\u00e9gime d\u2019Assurance Maladie Universelle (RAMU) offrant la facilit\u00e9\nd\u2019acc\u00e8s aux soins de sant\u00e9 \u00e0 l\u2019ensemble de la population.<\/p>\n\n\n\n<p>Selon lui, le\nprojet de budget 2020 est donc adoss\u00e9 \u00e0 un programme d\u2019activit\u00e9s d\u00e9clin\u00e9 en\nquatre axes et en activit\u00e9s reparties par structure.<em><br>\nLe budget 2020 de l\u2019Institut National de Pr\u00e9voyance Social est arr\u00eat\u00e9 en\nrecettes \u00e0 Deux Cent Milliards Quatre-Vingt \u2013Dix \u2013Sept Millions Deux Cent\nQuatre \u2013Vingt \u2013Douze Mille Cent Quatre \u2013Vingt \u2013Quinze (200 097 292 195)francs\nCFA et en d\u00e9penses \u00e0 Cent Soixante \u2013Six Milliards Deux Cent Quatre-Vingt\n-Quatorze Millions Six Cent Quarante \u2013Neuf Mille Deux Cent Quarante -Un (166 294\n649 241) francs CFA avec un solde d\u2019exploitation pr\u00e9visionnel de Trente \u2013Trois\nMilliards Huit Cent Deux Millions Six Cent Quarante-Deux Mille Neuf Cent\nCinquante -Quatre (33 802 642 954) francs CFA. Ce budget est en augmentation\npar rapport \u00e0 2019 de 9,54% au titre des recettes et de 0,69% au titre des\nd\u00e9penses.<\/em><em><\/em><\/p>\n\n\n\n<p><em>\u00ab&nbsp;Concernant\nl\u2019Assurance Maladie Obligatoire (AMO), le projet de budget 2020 est en\naugmentation par rapport au budget 2019, de 6,61% au titre des cotisations,\nsoit 36 348 000 000 FCFA et de 9,09% au titre des prestations servies, soit 18\n000 000 000FCFA&nbsp;\u00bb <\/em>a pr\u00e9cis\u00e9 le\npr\u00e9sident du conseil d\u2019administration de l\u2019INPS<\/p>\n\n\n\n<p>Pour lui,c<em>es r\u00e9sultats seront r\u00e9alis\u00e9s gr\u00e2ce\n\u00e0 la mise en \u0153uvre r\u00e9ussie d\u2019un plan de maitrise des charges techniques et des\ncharges fonctionnement. Dans le m\u00eame temps des actions seront entreprises en\nvue d\u2019augmenter les performances de recouvrement des cotisations de diversifier\nles ressources par la rentabilisation des structures sanitaires et de\nplacements de fonds, l\u2019accroissement des revenus tir\u00e9s des immeubles de\nrapport.&nbsp;<\/em><em><\/em><\/p>\n\n\n\n<p>A noter que les\naxes strat\u00e9giques retenus dans le plan strat\u00e9gique sont les suivants : Axe 1 :\nL\u2019\u00e9largissement du champ d\u2019application personnel ; Axe 2 : L\u2019am\u00e9lioration des\nprestations servies : Axe 3 : Le financement des branches : Axe 4 :\nL\u2019organisation et le fonctionnement de l\u2019INPS. Ces axes sont d\u00e9clin\u00e9s en 21\nactivit\u00e9s reparties par structure suivant le principe de l\u2019imputabilit\u00e9.<strong>Isabelle\nDOVI<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 92 session ordinaire du Conseil d\u2019administration de l\u2019institut national de pr\u00e9voyance sociale (INPS), s\u2019est tenue le lundi 30 d\u00e9cembre<\/p>\n","protected":false},"author":1,"featured_media":933,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali : Le budget pr\u00e9visionnel 2020 de l\u2019INPS, s\u2019\u00e9l\u00e8ve \u00e0 plus de 200 milliards de FCFA - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali : Le budget pr\u00e9visionnel 2020 de l\u2019INPS, s\u2019\u00e9l\u00e8ve \u00e0 plus de 200 milliards de FCFA - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"La 92 session ordinaire du Conseil d\u2019administration de l\u2019institut national de pr\u00e9voyance sociale (INPS), s\u2019est tenue le lundi 30 d\u00e9cembre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-10T03:53:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/01\/INPS-Photo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1372\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/01\\\/10\\\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/01\\\/10\\\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali : Le budget pr\u00e9visionnel 2020 de l\u2019INPS, s\u2019\u00e9l\u00e8ve \u00e0 plus de 200 milliards de FCFA\",\"datePublished\":\"2020-01-10T03:53:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/01\\\/10\\\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\\\/\"},\"wordCount\":581,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/01\\\/10\\\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/INPS-Photo.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/01\\\/10\\\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/01\\\/10\\\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/01\\\/10\\\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\\\/\",\"name\":\"Mali : Le budget pr\u00e9visionnel 2020 de l\u2019INPS, s\u2019\u00e9l\u00e8ve \u00e0 plus de 200 milliards de FCFA - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/01\\\/10\\\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/01\\\/10\\\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/INPS-Photo.jpg\",\"datePublished\":\"2020-01-10T03:53:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/01\\\/10\\\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/01\\\/10\\\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/01\\\/10\\\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/INPS-Photo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/INPS-Photo.jpg\",\"width\":1372,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/01\\\/10\\\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali : Le budget pr\u00e9visionnel 2020 de l\u2019INPS, s\u2019\u00e9l\u00e8ve \u00e0 plus de 200 milliards de FCFA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali : Le budget pr\u00e9visionnel 2020 de l\u2019INPS, s\u2019\u00e9l\u00e8ve \u00e0 plus de 200 milliards de FCFA - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali : Le budget pr\u00e9visionnel 2020 de l\u2019INPS, s\u2019\u00e9l\u00e8ve \u00e0 plus de 200 milliards de FCFA - REUSSITE INFO","og_description":"La 92 session ordinaire du Conseil d\u2019administration de l\u2019institut national de pr\u00e9voyance sociale (INPS), s\u2019est tenue le lundi 30 d\u00e9cembre","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/","og_site_name":"REUSSITE INFO","article_published_time":"2020-01-10T03:53:16+00:00","og_image":[{"width":1372,"height":600,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/01\/INPS-Photo.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali : Le budget pr\u00e9visionnel 2020 de l\u2019INPS, s\u2019\u00e9l\u00e8ve \u00e0 plus de 200 milliards de FCFA","datePublished":"2020-01-10T03:53:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/"},"wordCount":581,"commentCount":0,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/01\/INPS-Photo.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/","name":"Mali : Le budget pr\u00e9visionnel 2020 de l\u2019INPS, s\u2019\u00e9l\u00e8ve \u00e0 plus de 200 milliards de FCFA - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/01\/INPS-Photo.jpg","datePublished":"2020-01-10T03:53:16+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/01\/INPS-Photo.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/01\/INPS-Photo.jpg","width":1372,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/01\/10\/mali-le-budget-previsionnel-2020-de-linps-seleve-a-plus-de-200-milliards-de-fcfa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali : Le budget pr\u00e9visionnel 2020 de l\u2019INPS, s\u2019\u00e9l\u00e8ve \u00e0 plus de 200 milliards de FCFA"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=932"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/933"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}