{"id":830,"date":"2020-06-12T03:03:00","date_gmt":"2020-06-12T03:03:00","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=830"},"modified":"2020-06-12T03:03:00","modified_gmt":"2020-06-12T03:03:00","slug":"mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/","title":{"rendered":"Mali: La qualit\u00e9 des ressources humaines au centre des pr\u00e9occupations"},"content":{"rendered":"\n<p><strong><em>Le probl\u00e8me des ressources humaines de qualit\u00e9 se\npose avec acuit\u00e9 au Mali.&nbsp; A l\u2019occasion des\njourn\u00e9es nationales des ressources humaines&nbsp;\n(JNRH), qui seront c\u00e9l\u00e9br\u00e9es les 5 et 6 d\u00e9cembre 2019 \u00e0 l\u2019h\u00f4tel&nbsp; du cinquantenaire de Sikasso, en pr\u00e9sence des\ndirecteurs des ressources humaines,&nbsp; des\ngestionnaires experts et professionnels RH, des directeurs g\u00e9n\u00e9raux&nbsp; et chefs d\u2019entreprise, des cadres dirigeants\nd\u2019organisation; votre journal sp\u00e9cialis\u00e9 en \u00e9ducation et en entreprenariat \u2018\u2019La\nR\u00e9ussite Mali\u2019\u2019 a rencontr\u00e9 pour vous le pr\u00e9sident du conseil national des\nBureaux de placement et Entreprises de Travail temporaire du Mali (CONABEM):&nbsp; &nbsp;Boubacar\nToutou KANTE, non moins 2eme vice pr\u00e9sident Tr\u00e9sorier du conseil national du\nPatronat du Mali (CNPM), et parrain de la pr\u00e9sente \u00e9dition des JNRH.<\/em><\/strong><\/p>\n\n\n\n<p><strong>La R\u00e9ussite Mali: Veuillez nous pr\u00e9senter votre\nstructure le CONABEM<\/strong><\/p>\n\n\n\n<p><strong>Boubacar Toutou KANTE: <\/strong>Le conseil\nnational des Bureaux de placement et Entreprises de Travail temporaire du Mali\n(CONABEM)&nbsp; est une association des\nstructures et cabinets conseils en ressources humaines du Mali.&nbsp; Cr\u00e9\u00e9e depuis 2006, il compte aujourd\u2019hui 60\ncabinets tous priv\u00e9s. Il est dirig\u00e9 par un bureau de 12 membres qui couvre tout\nle territoire national.&nbsp; Tous les\nsecteurs des ressources humaines dont le recrutement, la&nbsp; formation, la gestion administrative du\npersonnel,&nbsp; le coaching et tout ce qui a\ntrait aux ressources humaines y figurent. Certains cabinets membres du CANABEM\nop\u00e8rent seulement au niveau local, tandis que &nbsp;d\u2019autres couvrent tout le territoire national,\nr\u00e9gional et international. Nous sommes affili\u00e9s au conseil national du Patronat\ndu Mali (CNPM).<\/p>\n\n\n\n<p><strong>La R\u00e9ussite\nMali: A l\u2019 occasion de la journ\u00e9e des Rh, le RH Mag et l\u2019Association Malienne\ndes Gestionnaires des Ressources Humaines (AMAGRH) organisent une rencontre \u00e0\nSikasso pour d\u00e9battre des th\u00e8mes relatifs \u00e0 ce m\u00e9tier.&nbsp; \u00cates-vous associ\u00e9 \u00e0 cela?&nbsp; <\/strong><\/p>\n\n\n\n<p><strong>Boubacar Toutou\nKANTE<\/strong>:\nComme par le pass\u00e9, j\u2019ai toujours \u00e9t\u00e9 associ\u00e9 aux JNRH \u00e0 deux&nbsp; titres: En tant qu\u2019employeur, mon entreprise\nUPS-RH a \u00e9t\u00e9 sollicit\u00e9e pour le sponsoring de l\u2019\u00e9v\u00e8nement. Ce que j\u2019ai toujours\nfait avec plaisir. En tant que Pr\u00e9sident du conseil national des Bureaux de placement\net Entreprises de Travail temporaire du Mali (CONABEM). Mon invitation de cette\nann\u00e9e est sp\u00e9ciale, car je suis le parrain de la pr\u00e9sente \u00e9dition. Mais del\u00e0 de\nl\u2019\u00e9v\u00e8nement, je voudrais rappeler quel\u2019AMAGRH\net le CONABEM sont deux poumons d\u2019un m\u00eame corps, et les deux &nbsp;organisations travaillent sur la m\u00eame mati\u00e8re\n(l\u2019homme), dans le m\u00eame espace (l\u2019entreprise) avec les m\u00eames outils (Les\nressources Humaines). Pour moi, les JNRH constituent&nbsp;la foire des\nprofessionnels des ressources Humaines en entreprise, et les consultants et\ncabinets en dehors de l\u2019entreprise.<\/p>\n\n\n\n<p><strong>La R\u00e9ussite\nMali&nbsp;: Quelle est la probl\u00e9matique des RH, emploi et formation au Mali? <\/strong><\/p>\n\n\n\n<p><strong>Boubacar\nToutou KANTE: <\/strong>La probl\u00e9matique des RH, de l\u2019emploi et\nde la formation au Mali est complexe. D\u2019un c\u00f4t\u00e9, elle est domin\u00e9e par la\nquestion de l\u2019ad\u00e9quation formation emploi. Les entreprises ont du mal \u00e0 trouver\nles comp\u00e9tences n\u00e9cessaires, car les formations d\u2019aujourd\u2019hui ne r\u00e9pondent\npas&nbsp; aux besoins des entreprises, c\u2019est\nun probl\u00e8me fondamental. De l\u2019autre c\u00f4t\u00e9, le ch\u00f4mage des jeunes qui manquent\nd\u2019exp\u00e9riences. Concernant la formation professionnelle, les entreprises sont\noblig\u00e9s d\u2019investir dans la formation de leur personnel, afin d\u2019atteindre leurs\nobjectifs. Sur le plan institutionnel, la mise en place des textes\nd\u2019application du code du travail est en cours. L\u2019accord tripartite&nbsp; sign\u00e9 entre l\u2019union nationale des\nTravailleurs du Mali (UNTM), le conseil national du Patronat du Mali (CNPM) et\nle gouvernement du Mali, a abouti \u00e0 un rel\u00e8vement de l\u2019\u00e2ge de d\u00e9part \u00e0 la\nretraite, dans le secteur public et \u00e0 des augmentations de salaire dans\ncertains secteurs.<\/p>\n\n\n\n<p><strong>La\nR\u00e9ussite Mali: Pourquoi il y a tant de ch\u00f4meurs au Mali, et pourtant chaque\nann\u00e9e, ce sont 300&nbsp;000 ch\u00f4meurs qui sont d\u00e9vers\u00e9s sur le march\u00e9 de\nl\u2019emploi&nbsp;?<\/strong><\/p>\n\n\n\n<p><strong>Boubacar\nToutou KANTE: <\/strong>Le taux \u00e9lev\u00e9 de ch\u00f4mage au Mali est la\ncons\u00e9quence de plusieurs facteurs combin\u00e9s. D\u2019abord, les universit\u00e9s et les\n\u00e9coles produisent chaque ann\u00e9e plus de 300.000 dipl\u00f4m\u00e9s qui n\u2019arrivent pas \u00e0\ns\u2019ins\u00e9rer sur le march\u00e9 du travail en raison de l\u2019inad\u00e9quation\nformation\/emploi. L\u2019\u00e9conomie malienne est bas\u00e9e sur l\u2019agriculture, l\u2019\u00e9levage,\nles mines. Dans les panoplies des structures de formation, il y a tr\u00e8s peu\nde&nbsp; structures qui s\u2019occupent de la\nformation en agriculture, en \u00e9levage, en p\u00eache et dans les m\u00e9tiers des mines.\nC\u2019est ce qui explique que les gens qui sortent des universit\u00e9s maliennes avec\ndes formations,&nbsp; ne sont pas employables\nsur le march\u00e9 du travail. Pour lutter contre ce ph\u00e9nom\u00e8ne, il faudra former les\ngens&nbsp; en fonction des besoins du march\u00e9\nde l\u2019emploi. Et ce march\u00e9 du travail aujourd\u2019hui, c\u2019est l\u2019agriculture, c\u2019est\nl\u2019\u00e9levage, c\u2019est la p\u00eache et les m\u00e9tiers des mines. Voil\u00e0 les mamelles essentielles\nde l\u2019\u00e9conomie malienne. Tous les programmes de formations doivent tenir compte\nde ces r\u00e9alit\u00e9s l\u00e0. Ensuite, la persistance de l\u2019ins\u00e9curit\u00e9 paralyse le pays.\nCe qui aboutit \u00e0 un ralentissement de l\u2019activit\u00e9 \u00e9conomique. Certains secteurs\nsont presque \u00e0 l\u2019arr\u00eat (h\u00f4tellerie et la restauration, les agences de voyages\net tourisme). Enfin, l\u2019exode rural vide les campagnes de bras valides qui\nviennent grossi le lot de ch\u00f4meurs dans les villes.<\/p>\n\n\n\n<p><strong>La\nR\u00e9ussite Mali: A qui incombe cette responsabilit\u00e9&nbsp;<\/strong>?<\/p>\n\n\n\n<p><strong>Boubacar\nToutou KANTE: <\/strong>C\u2019est une question de la politique de\nl\u2019\u00e9ducation au niveau nationale. Heureusement, il y a des reformes qui sont en\ntrain d\u2019\u00eatre faites en ce moment, et qui commencent \u00e0 corriger ces\ninsuffisances. Et tout r\u00e9cemment, il y a un projet de construction d\u2019une \u00e9cole\ndes mines qui est en cours. Aussi, certaines \u00e9coles maliennes commencent \u00e0 se sp\u00e9cialiser\nen agriculture, en \u00e9levage et en p\u00e8che. Ce sont des orientations tr\u00e8s int\u00e9ressantes\net tr\u00e8s b\u00e9n\u00e9fiques pour notre pays.<\/p>\n\n\n\n<p>Mais,\nseule une relance de l\u2019\u00e9conomie adoss\u00e9e sur un ambitieux programme d\u2019insertion\ndes jeunes pourrait absorb\u00e9e le ch\u00f4mage. Ce sont les grands travaux d\u2019infrastructures,\nl\u2019industrialisation, la cr\u00e9ation d\u2019industries de transformation des produits\nlocaux (coton, riz, karit\u00e9, fruits et l\u00e9gumes etc) qui offrent des opportunit\u00e9s\nde recrutements massifs pour des emplois \u00e0 long terme. L\u2019installation des\njeunes dans les activit\u00e9s agricoles pourrait absorb\u00e9e un grand nombre de\nch\u00f4meurs.<\/p>\n\n\n\n<p><strong>La\nR\u00e9ussite Mali: Quel est votre dernier mot&nbsp;?<\/strong>\n<\/p>\n\n\n\n<p><strong>Boubacar\nToutou KANTE: <\/strong>Je souhaite plein succ\u00e8s aux travaux des\nJNRH 2019 et vivement l\u2019\u00e9dition 2020<\/p>\n\n\n\n<p><strong>Propos\nrecueillis par <\/strong><strong>Isabelle DOVI<\/strong><strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le probl\u00e8me des ressources humaines de qualit\u00e9 se pose avec acuit\u00e9 au Mali.&nbsp; A l\u2019occasion des journ\u00e9es nationales des ressources<\/p>\n","protected":false},"author":1,"featured_media":831,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avis-dexpert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali: La qualit\u00e9 des ressources humaines au centre des pr\u00e9occupations - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali: La qualit\u00e9 des ressources humaines au centre des pr\u00e9occupations - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"Le probl\u00e8me des ressources humaines de qualit\u00e9 se pose avec acuit\u00e9 au Mali.&nbsp; A l\u2019occasion des journ\u00e9es nationales des ressources\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-12T03:03:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2019\/12\/Boubakar-Toutou-Kante.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"303\" \/>\n\t<meta property=\"og:image:height\" content=\"448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/06\\\/12\\\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/06\\\/12\\\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali: La qualit\u00e9 des ressources humaines au centre des pr\u00e9occupations\",\"datePublished\":\"2020-06-12T03:03:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/06\\\/12\\\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\\\/\"},\"wordCount\":1196,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/06\\\/12\\\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Boubakar-Toutou-Kante.jpg\",\"articleSection\":[\"AVIS D'EXPERT\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/06\\\/12\\\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/06\\\/12\\\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/06\\\/12\\\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\\\/\",\"name\":\"Mali: La qualit\u00e9 des ressources humaines au centre des pr\u00e9occupations - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/06\\\/12\\\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/06\\\/12\\\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Boubakar-Toutou-Kante.jpg\",\"datePublished\":\"2020-06-12T03:03:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/06\\\/12\\\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/06\\\/12\\\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/06\\\/12\\\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Boubakar-Toutou-Kante.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Boubakar-Toutou-Kante.jpg\",\"width\":303,\"height\":448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/06\\\/12\\\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali: La qualit\u00e9 des ressources humaines au centre des pr\u00e9occupations\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali: La qualit\u00e9 des ressources humaines au centre des pr\u00e9occupations - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali: La qualit\u00e9 des ressources humaines au centre des pr\u00e9occupations - REUSSITE INFO","og_description":"Le probl\u00e8me des ressources humaines de qualit\u00e9 se pose avec acuit\u00e9 au Mali.&nbsp; A l\u2019occasion des journ\u00e9es nationales des ressources","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/","og_site_name":"REUSSITE INFO","article_published_time":"2020-06-12T03:03:00+00:00","og_image":[{"width":303,"height":448,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2019\/12\/Boubakar-Toutou-Kante.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali: La qualit\u00e9 des ressources humaines au centre des pr\u00e9occupations","datePublished":"2020-06-12T03:03:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/"},"wordCount":1196,"commentCount":0,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2019\/12\/Boubakar-Toutou-Kante.jpg","articleSection":["AVIS D'EXPERT"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/","name":"Mali: La qualit\u00e9 des ressources humaines au centre des pr\u00e9occupations - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2019\/12\/Boubakar-Toutou-Kante.jpg","datePublished":"2020-06-12T03:03:00+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2019\/12\/Boubakar-Toutou-Kante.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2019\/12\/Boubakar-Toutou-Kante.jpg","width":303,"height":448},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/06\/12\/mali-la-qualite-des-ressources-humaines-au-centre-des-preoccupations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali: La qualit\u00e9 des ressources humaines au centre des pr\u00e9occupations"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=830"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/830\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/831"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}