{"id":827,"date":"2019-12-04T19:36:19","date_gmt":"2019-12-04T19:36:19","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=827"},"modified":"2019-12-04T19:36:19","modified_gmt":"2019-12-04T19:36:19","slug":"mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/","title":{"rendered":"Mali: \u00ab La lutte contre la corruption se gagne aussi \u00e0 travers la promotion de la citoyennet\u00e9 \u00bb Dixit le Pr\u00e9sident de la CNJM Ismayila Yoro DICKO"},"content":{"rendered":"\n<p><strong><em>Au Mali, la corruption a atteint&nbsp; des\nproportions si inqui\u00e9tantes, que l\u2019on parle sans ambages de \u2018\u2019pathologie\nsociale\u2019\u2019 ou de \u2018\u2019fl\u00e9au culturel\u2019\u2019. Ainsi <\/em><\/strong><strong><em>la lutte contre la corruption au Mali est devenue une affaire de tous. La <\/em><\/strong><strong><em>convention nationale\ndes Juristes du Mali (CNJM), une association apolitique \u00e0 but non lucratif <\/em><\/strong><strong><em>&nbsp;cr\u00e9\u00e9e il y a bient\u00f4t 20 ans,<\/em><\/strong><strong><em> entend&nbsp; b\u00e2tir un v\u00e9ritable Etat de droit et de d\u00e9mocratie\nau Mali \u00e0 travers la promotion des id\u00e9aux r\u00e9publicains et le d\u00e9veloppement par\nl\u2019\u00e9dification d\u2019une d\u00e9mocratie de responsabilit\u00e9 et de redevabilit\u00e9; dans tous\nles actes de la vie sociale, \u00e9conomique et culturelle. Votre journal sp\u00e9cialis\u00e9\nen \u00e9ducation et en entreprenariat \u2018\u2019La r\u00e9ussite Mali\u2019\u2019 a rencontr\u00e9 son Pr\u00e9sident\nIsmayila Yoro DICKO, non moins <\/em><\/strong><strong><em>membre de\nl\u2019Association des Juristes Africains pr\u00e9sid\u00e9e par le Professeur SECK du\nS\u00e9n\u00e9gal. Il est aussi membre du corps&nbsp; pr\u00e9fectoral.\nIl nous a pr\u00e9sent\u00e9 le r\u00f4le que joue la CNJM<\/em><\/strong><strong><em> dans la lutte contre la corruption au\nMali.<\/em><\/strong><\/p>\n\n\n\n<p><strong>La R\u00e9ussite Mali: Qu\u2019est ce qui vous a pouss\u00e9 \u00e0 cr\u00e9er\nla CNJM&nbsp;?<\/strong><\/p>\n\n\n\n<p><strong>Ismayila\nYoro DICKO<\/strong>: Pour avoir \u00e9t\u00e9 acteur de l\u2019av\u00e8nement de la d\u00e9mocratie au Mali en 1991,\npour plus de libert\u00e9 et de justice, il est de notre devoir de nous investir\npour faire de cette d\u00e9mocratie une r\u00e9alit\u00e9. Par exemple, selon l\u2019article 15 de la\nConstitution du Mali, l\u2019environnement doit \u00eatre prot\u00e9g\u00e9 et pr\u00e9serv\u00e9 par tout\ncitoyen. Ainsi, notre conviction au niveau de la CNJM, c\u2019est qu\u2019on ne peut pas\nb\u00e2tir une nation d\u00e9mocratique&nbsp; sans des\ncitoyens bien form\u00e9s et&nbsp; bien inform\u00e9s\nsur leurs droits et devoirs, et qui font tout pour s\u2019acquitter de leurs\ndevoirs, notamment en payant leurs imp\u00f4ts et&nbsp;\ntaxes. <\/p>\n\n\n\n<p>En retour\nils seront en droit de s\u2019informer sur la destination de leurs contributions\nfiscales. C\u2019est le principe de redevabilit\u00e9 qui leur permet de dire:&nbsp;\u00ab&nbsp;\nNous avons pay\u00e9 nos imp\u00f4ts, donc nous avons le droit de poser des questions aux\ndirigeants pour savoir quelle direction notre &nbsp;argent a prise&nbsp;\u00bb.Cela est d\u2019autant plus\ncompr\u00e9hensible, qu\u2019un citoyen qui participe activement \u00e0 l\u2019\u00e9dification d\u2019un projet,\naccepte difficilement de jouer le spectateur indiff\u00e9rent, quand des forces\nr\u00e9trogrades essayent de d\u00e9truire le fruit de ses labeurs. Au constat, nous\nassistons au fait que la pr\u00e9servation du bien public int\u00e9resse tr\u00e8s peu de Maliens.\nExemple, \u00e0 longueur de journ\u00e9e, la SOMAGEP perd de l\u2019eau et EDM d\u2019\u00e9lectricit\u00e9\nface \u00e0 l\u2019indiff\u00e9rence des populations.<\/p>\n\n\n\n<p><strong>La R\u00e9ussite Mali: <\/strong><strong>Quels sont les objectifs vis\u00e9s par la CNJM&nbsp;?<\/strong><\/p>\n\n\n\n<p><strong>Ismayila Yoro DICKO<\/strong>: La convention nationale\ndes Juristes du Mali (CNJM) a aussi pour objectif de&nbsp; promouvoir la citoyennet\u00e9 et la tol\u00e9rance.\nL\u2019association s\u2019investit aussi au &nbsp;quotidien \u00e0 faire en sorte que les Maliens et\nparticuli\u00e8rement les jeunes s\u2019int\u00e9ressent \u00e0 la marche de leur nation en y\napportant des contributions de qualit\u00e9 et en pr\u00e9servant le bien public.<\/p>\n\n\n\n<p>&nbsp;La CNJM s\u2019emploie aussi \u00e0 poser des actes\nsusceptibles de fortifier l\u2019autorit\u00e9 de l\u2019Etat par la sensibilisation et\nl\u2019information de la population et des d\u00e9tenteurs de l\u2019autorit\u00e9. Pour cela nous\nmettons \u0153uvre un vaste programme d\u2019enseignement de l\u2019Education civique et\nmorale \u00e0 l\u2019\u00e9cole d\u00e8s le pr\u00e9scolaire. <\/p>\n\n\n\n<p>Nos &nbsp;actions sont orient\u00e9es aussi vers l\u2019ancrage de\nnotre processus de d\u00e9centralisation. A cet effet, nous comptons poursuivre\nnotre partenariat &nbsp;avec les \u00e9lus sur\nl\u2019ensemble du territoire national en mettant \u00e0 leur disposition des juristes ou\ndes para- juristes pour pouvoir de r\u00e9pondre \u00e0 leurs pr\u00e9occupations juridiques\net judiciaires.<\/p>\n\n\n\n<p>Pour la CNJM,\nchaque village, fraction ou quartier malien doit avoir sa <strong>\u00ab&nbsp;Boutique Juridique <em>(Centre\nd\u2019accueil, d\u2019information et d\u2019orientation juridiqu<\/em><\/strong>e)&nbsp;\u00bb. Notre\nsouhait est de rendre disponible l\u2019information juridique \u00e0 tous les citoyens\nmaliens car le droit ne&nbsp; doit pas rester\nsimplement, une affaire de professionnels. Il faut donc casser la barri\u00e8re\nentre les populations et les r\u00e8gles de droit. Il reste entendu que nous ne\nsommes ni juges, ni avocats, ni notaires, ni huissiers, ni commissaires-priseurs,\nni policiers, ni gendarmes&nbsp;; mais nous demeurons des juristes d\u00e9terminit\u00e9s\n\u00e0 vulgariser le droit de fa\u00e7on tr\u00e8s large au b\u00e9n\u00e9fice des citoyens.<\/p>\n\n\n\n<p>La convention\nmet en outre un accent particulier sur le r\u00f4le des&nbsp; jeunes et des femmes pour promouvoir la\ncitoyennet\u00e9 et la vulgarisation du &nbsp;Droit.\nElle s\u2019engage aussi &nbsp;&nbsp;\u00e0 approfondir la\nr\u00e9flexion sur la port\u00e9e et le sens du vote dans le choix&nbsp; des hommes et des femmes&nbsp; qui auront en charge la gestion des affaires\npubliques.<\/p>\n\n\n\n<p><strong>La R\u00e9ussite Mali: Comment expliquez\nvous alors le fait que le Mali semble aller \u00e0 vau-l\u2019eau et que la corruption devienne\nla pratique de tous?<\/strong><\/p>\n\n\n\n<p><strong>Ismayila\nYoro DICKO<\/strong>: Notre association a toujours attir\u00e9 l\u2019attention des gouvernants et des\ncitoyens&nbsp; sur les effets d\u00e9vastateurs de\nla &nbsp;corruption, car elle est en train de\nd\u00e9truire les fondements m\u00eames de la nation malienne. Il faut, par exemple\naujourhui, jeter un regard prospectif sur l\u2019\u00e9tat de notre \u00e9cole, notre h\u00f4pital,\nnotre administration, notre arm\u00e9e, notre justice, on a juste le c\u0153ur meurtri. <\/p>\n\n\n\n<p>La raison\nest simple, une minorit\u00e9 de Maliens sans \u00e2me s\u2019est donn\u00e9e une libert\u00e9 de porter\natteinte aux biens publics. La situation doit donc changer. Imaginer un haut\nfonctionnaire malien voler un poulet dans son village natal, c\u2019est la honte de\nsa vie. Paradoxalement il d\u00e9tourne des milliards et il y a des gens qui\ntrouvent cela normal. <\/p>\n\n\n\n<p>&nbsp;En effet au Mali, les gens courent apr\u00e8s les\npostes sans mesurer les cons\u00e9quences et les tenants et aboutissants, quand on\nles nomme \u00e0 des postes importants, ils sont en face d\u2019une r\u00e9alit\u00e9 \u00e0 laquelle\nils n\u2019ont pas pens\u00e9e. C\u2019est pour cette raison que nous apportons&nbsp; un soutien sans r\u00e9serve \u00e0 notre justice et en\nparticulier au <strong>Garde des Sceau, Malik COULIBALY <\/strong>dans l\u2019accomplissement de\nses missions dans l\u2019int\u00e9r\u00eat du pays.<\/p>\n\n\n\n<p>Pour la\nd\u00e9fense des droits humains, nous ne doutons point que les juges fassent sienne,\nl\u2019assertion selon laquelle, dans les proc\u00e9dures judiciaires, la libert\u00e9 est le\nprincipe et la d\u00e9tention l\u2019exception. Pour cela, les droits des pr\u00e9venus et\nceux des personnes condamn\u00e9es doivent \u00eatre pr\u00e9serv\u00e9s. En effet, il est\nimportant de rappeler \u00e0 l\u2019opinion que les personnes plac\u00e9es sous mandat de\nd\u00e9p\u00f4ts sont &nbsp;pr\u00e9sum\u00e9es innocentes jusqu\u2019\u00e0\nce qu\u2019une d\u00e9cision de justice en d\u00e9cide autrement. &nbsp;Nous nous battons \u00e0 travers la sensibilisation\net l\u2019information pour que les gens&nbsp;\nn\u2019aillent pas en prison. Ainsi, nous sommes en train de faire un travail\nqui va d\u00e9sormais nous amener \u00e0 accompagner les prisonniers dans le suivi de\nleurs dossiers judiciaires, car il y a des prisonniers qui sont enferm\u00e9s sans\nsavoir pourquoi ils sont incarc\u00e9r\u00e9s et &nbsp;parfois on les oublie m\u00eame. <\/p>\n\n\n\n<p>Courant\n2020, nous entendons finaliser le montage d\u2019un projet tr\u00e8s important qui\nconsiste \u00e0 mettre les nouvelles technologies de l\u2019information et de la\ncommunication au service du droit et de la promotion de la citoyennet\u00e9. En\ncomptant d\u2019abord sur nous-m\u00eames, nous sommes ouverts \u00e0 l\u2019accompagnement des\npartenaires, nationaux et internationaux. A cet effet, nous saluons d\u00e9j\u00e0\nl\u2019engagement des membres d\u2019honneur de la CNJM (Fousseyni CAMARA \u00e0 Paris, Sidi DANIOKO\nen Suisse, le Doyen Salah Nadjim BABY \u00e0 Bamako, nos ambassadeurs&nbsp;: Master\nSoumi, au Mali et Sidi DANIOKO, notre Expert NTIC aux Etats &#8211; Unis d\u2019Am\u00e9rique).\nVous pouvez leur emboiter le pas&nbsp;!<\/p>\n\n\n\n<p><strong>La R\u00e9ussite Mali: Parlez nous de vos\nactivit\u00e9s<\/strong><\/p>\n\n\n\n<p><strong>Ismayila\nYoro DICKO<\/strong>: Nos activit\u00e9s, comme indiqu\u00e9, tournent autour de la cr\u00e9ation et \u00e0\nl\u2019animation de Boutiques juridiques au service des &nbsp;populations, les conf\u00e9rences- contributions\nsur la promotion du droit, les rencontres d\u2019\u00e9changes dans les \u00e9coles, les\nuniversit\u00e9s, espaces r\u00e9serv\u00e9s aux organisations de la Soci\u00e9t\u00e9 civile, &nbsp;les a\u00e9roports ( pour informer les voyageurs sur\nnotre droit positif et le droit communautaire), programmes d\u2019assistance\njuridique aux Entr\u00e9prises Maliennes et&nbsp;\ndes s\u00e9ances de renforcement des capacit\u00e9s des sortants de nos universit\u00e9s.<\/p>\n\n\n\n<p>C\u2019est\nainsi qu\u2019en 2003 nous avions b\u00e9n\u00e9fici\u00e9 d\u2019un appui financier d\u2019un programme du\nPNUD pour ouvrir une boutique juridique \u00e0 BANCONI, un quartier populaire de la\nCommune I du District de Bamako. En deux &nbsp;ans d\u2019activit\u00e9s, les administrateurs de la\nboutique ont accueilli, inform\u00e9 et orient\u00e9 plus de 19&nbsp;000 personnes\ncompos\u00e9es en grande partie de femmes et de jeunes.<\/p>\n\n\n\n<p>&nbsp;Le besoin d\u2019information juridique \u00e9tait tr\u00e8s\npressant que les citoyens finalement, venaient de toutes les communes de\nBamako.Ils exigeaient l\u2019ouverture d\u2019autres boutiques juridiques dans leurs\nlocalit\u00e9s respectives. Nos moyens \u00e9tant limit\u00e9s, les besoins demeurent encore\npartout au Mali. Il reste que nous continuons d\u2019envoyer nos \u00ab&nbsp; <strong>JURISTES\nSAC A DOS&nbsp;\u00bb<\/strong>dans les quartiers, villages et zones rurales pour\nsensibiliser les populations sur leurs droits et devoirs, et chose surprenante,\nce sont les maires, les chefs de village qui les prennent en charge, car il y a\nune r\u00e9alit\u00e9 locale qui est diff\u00e9rente de la r\u00e9alit\u00e9 de la capitale.<\/p>\n\n\n\n<p><strong>La R\u00e9ussite Mali: Votre dernier mot<\/strong><\/p>\n\n\n\n<p><strong>Ismayila Yoro\nDICKO<\/strong>: Je\nremercie votre journal pour tout le travail abattu, c\u2019est un bon journal tres\ndynamique avec beaucoup d\u2019informations. J\u2019invite en outre, toute la population\n\u00e0 participer activement \u00e0 notre &nbsp;grande conf\u00e9rence\nCitoyenne qui se tiendra ce Samedi, 07 D\u00e9cembre 2019 \u00e0 partir de 09 Heures 30mn,\nau Centre OlympAfrica situ\u00e9 non loin &nbsp;du\nmarch\u00e9 de Banankabougou et de la Cour d\u2019Appel de Bamako. Le th\u00e8me est relatif \u00e0\nla lutte contre l\u2019indiff\u00e9rence au Mali en soutien \u00e0 notre arm\u00e9e et \u00e0 notre &nbsp;la justice<strong>.<\/strong><\/p>\n\n\n\n<p>Enfin,\nlancer un appel \u00e0 l\u2019ensemble des Juristes du Mali et toutes personnes\nint\u00e9ress\u00e9es par les questions juridiques \u00e0 prendre contact avec le Bureau\nEx\u00e9cutif National de la &nbsp;CNJM \u00e0 notre Si\u00e8ge,\nImmeuble Master Com. (Agence de Communication Globale), Badalabougou- SEMA\nGEXCO non loin de la Pharmacie du 2<sup>\u00e8me<\/sup> pont. <\/p>\n\n\n\n<p>Mail&nbsp;: <a href=\"mailto:conjuristemali@gmail.com-\">conjuristemali@gmail.com-<\/a>Tel&nbsp;:\n(00223) 77 77 40 64.<\/p>\n\n\n\n<p><strong>Propos\nrecueillis par Cheick Oumar KANTE<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au Mali, la corruption a atteint&nbsp; des proportions si inqui\u00e9tantes, que l\u2019on parle sans ambages de \u2018\u2019pathologie sociale\u2019\u2019 ou de<\/p>\n","protected":false},"author":1,"featured_media":828,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avis-dexpert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali: \u00ab La lutte contre la corruption se gagne aussi \u00e0 travers la promotion de la citoyennet\u00e9 \u00bb Dixit le Pr\u00e9sident de la CNJM Ismayila Yoro DICKO - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali: \u00ab La lutte contre la corruption se gagne aussi \u00e0 travers la promotion de la citoyennet\u00e9 \u00bb Dixit le Pr\u00e9sident de la CNJM Ismayila Yoro DICKO - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"Au Mali, la corruption a atteint&nbsp; des proportions si inqui\u00e9tantes, que l\u2019on parle sans ambages de \u2018\u2019pathologie sociale\u2019\u2019 ou de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-04T19:36:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2019\/12\/IMG-20191202-WA0012-Copie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"538\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2019\\\/12\\\/04\\\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2019\\\/12\\\/04\\\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali: \u00ab La lutte contre la corruption se gagne aussi \u00e0 travers la promotion de la citoyennet\u00e9 \u00bb Dixit le Pr\u00e9sident de la CNJM Ismayila Yoro DICKO\",\"datePublished\":\"2019-12-04T19:36:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2019\\\/12\\\/04\\\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\\\/\"},\"wordCount\":1813,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2019\\\/12\\\/04\\\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/IMG-20191202-WA0012-Copie.jpg\",\"articleSection\":[\"AVIS D'EXPERT\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2019\\\/12\\\/04\\\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2019\\\/12\\\/04\\\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2019\\\/12\\\/04\\\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\\\/\",\"name\":\"Mali: \u00ab La lutte contre la corruption se gagne aussi \u00e0 travers la promotion de la citoyennet\u00e9 \u00bb Dixit le Pr\u00e9sident de la CNJM Ismayila Yoro DICKO - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2019\\\/12\\\/04\\\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2019\\\/12\\\/04\\\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/IMG-20191202-WA0012-Copie.jpg\",\"datePublished\":\"2019-12-04T19:36:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2019\\\/12\\\/04\\\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2019\\\/12\\\/04\\\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2019\\\/12\\\/04\\\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/IMG-20191202-WA0012-Copie.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/IMG-20191202-WA0012-Copie.jpg\",\"width\":538,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2019\\\/12\\\/04\\\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali: \u00ab La lutte contre la corruption se gagne aussi \u00e0 travers la promotion de la citoyennet\u00e9 \u00bb Dixit le Pr\u00e9sident de la CNJM Ismayila Yoro DICKO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali: \u00ab La lutte contre la corruption se gagne aussi \u00e0 travers la promotion de la citoyennet\u00e9 \u00bb Dixit le Pr\u00e9sident de la CNJM Ismayila Yoro DICKO - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali: \u00ab La lutte contre la corruption se gagne aussi \u00e0 travers la promotion de la citoyennet\u00e9 \u00bb Dixit le Pr\u00e9sident de la CNJM Ismayila Yoro DICKO - REUSSITE INFO","og_description":"Au Mali, la corruption a atteint&nbsp; des proportions si inqui\u00e9tantes, que l\u2019on parle sans ambages de \u2018\u2019pathologie sociale\u2019\u2019 ou de","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/","og_site_name":"REUSSITE INFO","article_published_time":"2019-12-04T19:36:19+00:00","og_image":[{"width":538,"height":640,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2019\/12\/IMG-20191202-WA0012-Copie.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali: \u00ab La lutte contre la corruption se gagne aussi \u00e0 travers la promotion de la citoyennet\u00e9 \u00bb Dixit le Pr\u00e9sident de la CNJM Ismayila Yoro DICKO","datePublished":"2019-12-04T19:36:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/"},"wordCount":1813,"commentCount":0,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2019\/12\/IMG-20191202-WA0012-Copie.jpg","articleSection":["AVIS D'EXPERT"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/","name":"Mali: \u00ab La lutte contre la corruption se gagne aussi \u00e0 travers la promotion de la citoyennet\u00e9 \u00bb Dixit le Pr\u00e9sident de la CNJM Ismayila Yoro DICKO - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2019\/12\/IMG-20191202-WA0012-Copie.jpg","datePublished":"2019-12-04T19:36:19+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2019\/12\/IMG-20191202-WA0012-Copie.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2019\/12\/IMG-20191202-WA0012-Copie.jpg","width":538,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2019\/12\/04\/mali-la-lutte-contre-la-corruption-se-gagne-aussi-a-travers-la-promotion-de-la-citoyennete-dixit-le-president-de-la-cnjm-ismayila-yoro-dicko\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali: \u00ab La lutte contre la corruption se gagne aussi \u00e0 travers la promotion de la citoyennet\u00e9 \u00bb Dixit le Pr\u00e9sident de la CNJM Ismayila Yoro DICKO"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=827"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/827\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/828"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}