{"id":5877,"date":"2025-10-20T10:03:57","date_gmt":"2025-10-20T10:03:57","guid":{"rendered":"https:\/\/www.reussiteinfo.com\/?p=5877"},"modified":"2025-10-20T11:53:53","modified_gmt":"2025-10-20T11:53:53","slug":"mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/","title":{"rendered":"Mali\u00a0: Une avant\u2011premi\u00e8re prometteuse pour la 2\u1d49\u202f\u00e9dition du Salon des Arts, du Design et de la D\u00e9coration \u00e0 Bamako"},"content":{"rendered":"\n<p>La capitale malienne s\u2019appr\u00eate \u00e0 accueillir la deuxi\u00e8me \u00e9dition du Salon des Arts, du Design et de la D\u00e9coration (SADDEC) du 6 au 9 novembre 2025 \u00e0 Bamako. En pr\u00e9lude au lancement des festivit\u00e9s, un pr\u00e9\u2011\u00e9v\u00e9nement riche en \u00e9changes, en r\u00e9seaux et en cr\u00e9ativit\u00e9 a \u00e9t\u00e9 organis\u00e9 le samedi 18 octobre 2025, au showroom \u00ab&nbsp;Paradis du Sommeil&nbsp;\u00bb de l\u2019industrie&nbsp;Matelas DODO sis \u00e0 Sotuba. Cet avant\u2011go\u00fbt a permis de poser les jalons de ce qui s\u2019annonce comme un moment fort pour les acteurs maliens et africains de l\u2019art, du design et de la d\u00e9coration.<\/p>\n\n\n\n<p>L\u2019objectif du pr\u00e9\u2011\u00e9v\u00e9nement est de permettre aux organisateurs, exposants, partenaires et m\u00e9dias de se rencontrer, d\u2019\u00e9changer autour du th\u00e8me, de la programmation et des enjeux de la seconde \u00e9dition.<\/p>\n\n\n\n<p>Selon l\u2019organisateur en chef, Ander Baba DIARRA, il faut valoriser le savoir\u2011faire local malien au travers des artisans, designers, d\u00e9corateurs\u2026, en leur offrant une plateforme de visibilit\u00e9 avant le salon principal.<\/p>\n\n\n\n<p>\u00ab&nbsp;<em>Nous allons cr\u00e9er des synergies entre les acteurs locaux et internationaux, afin de favoriser les collaborations et d\u2019accro\u00eetre la dimension r\u00e9gionale voire continentale du salon<\/em>&nbsp;\u00bb a insist\u00e9 Baba DIARRA.<\/p>\n\n\n\n<p>Le directeur-G\u00e9rant de l\u2019industrie Matelas Dodo, Hassane Jamil et la responsable du Showroom Paradis du Sommeil se disent tr\u00e8s heureux d\u2019\u00eatre le partenaire privil\u00e9gi\u00e9 de cet \u00e9v\u00e8nement.<\/p>\n\n\n\n<p><strong>Temps forts de l\u2019\u00e9v\u00e8nement<\/strong><\/p>\n\n\n\n<p>Une conf\u00e9rence de presse anim\u00e9e par les organisateurs du salon a permis de pr\u00e9senter le th\u00e8me de la deuxi\u00e8me \u00e9dition, les objectifs strat\u00e9giques, le calendrier et les modalit\u00e9s d\u2019exposition. Des ateliers\u2011rencontres \u00e9taient l\u2019occasion pour les artisans, designers et d\u00e9corateurs d\u2019\u00e9changer avec des experts sur des sujets tels que l\u2019innovation dans le design, l\u2019usage des mat\u00e9riaux locaux, la d\u00e9coration d\u2019int\u00e9rieur \u00e0 l\u2019\u00e8re africaine, ou encore la commercialisation des cr\u00e9ations. Une mini\u2011exposition ou un \u00ab\u202fshowroom\u202f\u00bb d\u2019avant\u2011garde : quelques pi\u00e8ces de design et de d\u00e9coration, notamment de Maya D\u00e9cor ont \u00e9t\u00e9 expos\u00e9es pour illustrer la th\u00e9matique du salon \u00e0 venir. Un moment de d\u00e9gustation et de networking a permis aux partenaires institutionnels, sponsors, m\u00e9dias et cr\u00e9ateurs de nouer des contacts, envisager des coop\u00e9rations et poser les bases d\u2019une meilleure visibilit\u00e9 du salon.<\/p>\n\n\n\n<p>A noter que ce pr\u00e9\u2011\u00e9v\u00e9nement pour la deuxi\u00e8me \u00e9dition du salon va permettre de cr\u00e9dibiliser le salon aupr\u00e8s des acteurs avant l\u2019ouverture officielle, en donnant un avant\u2011go\u00fbt et en mobilisant les parties prenantes. Il va \u00e9galement favoriser la visibilit\u00e9 locale, en impliquant directement les artisans, cr\u00e9ateurs et d\u00e9corateurs maliens. Il ouvre ainsi la voie \u00e0 des partenariats durables.<\/p>\n\n\n\n<p><strong>Charles MESSE<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La capitale malienne s\u2019appr\u00eate \u00e0 accueillir la deuxi\u00e8me \u00e9dition du Salon des Arts, du Design et de la D\u00e9coration (SADDEC)<\/p>\n","protected":false},"author":1,"featured_media":5886,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali\u00a0: Une avant\u2011premi\u00e8re prometteuse pour la 2\u1d49\u202f\u00e9dition du Salon des Arts, du Design et de la D\u00e9coration \u00e0 Bamako - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali\u00a0: Une avant\u2011premi\u00e8re prometteuse pour la 2\u1d49\u202f\u00e9dition du Salon des Arts, du Design et de la D\u00e9coration \u00e0 Bamako - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"La capitale malienne s\u2019appr\u00eate \u00e0 accueillir la deuxi\u00e8me \u00e9dition du Salon des Arts, du Design et de la D\u00e9coration (SADDEC)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-20T10:03:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-20T11:53:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2025\/10\/105967484_2662427380665741_3567305212197665138_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2025\\\/10\\\/20\\\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2025\\\/10\\\/20\\\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali\u00a0: Une avant\u2011premi\u00e8re prometteuse pour la 2\u1d49\u202f\u00e9dition du Salon des Arts, du Design et de la D\u00e9coration \u00e0 Bamako\",\"datePublished\":\"2025-10-20T10:03:57+00:00\",\"dateModified\":\"2025-10-20T11:53:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2025\\\/10\\\/20\\\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\\\/\"},\"wordCount\":497,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2025\\\/10\\\/20\\\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/105967484_2662427380665741_3567305212197665138_n.jpg\",\"articleSection\":[\"BUSINESS\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2025\\\/10\\\/20\\\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2025\\\/10\\\/20\\\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\\\/\",\"name\":\"Mali\u00a0: Une avant\u2011premi\u00e8re prometteuse pour la 2\u1d49\u202f\u00e9dition du Salon des Arts, du Design et de la D\u00e9coration \u00e0 Bamako - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2025\\\/10\\\/20\\\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2025\\\/10\\\/20\\\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/105967484_2662427380665741_3567305212197665138_n.jpg\",\"datePublished\":\"2025-10-20T10:03:57+00:00\",\"dateModified\":\"2025-10-20T11:53:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2025\\\/10\\\/20\\\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2025\\\/10\\\/20\\\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2025\\\/10\\\/20\\\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/105967484_2662427380665741_3567305212197665138_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/105967484_2662427380665741_3567305212197665138_n.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2025\\\/10\\\/20\\\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali\u00a0: Une avant\u2011premi\u00e8re prometteuse pour la 2\u1d49\u202f\u00e9dition du Salon des Arts, du Design et de la D\u00e9coration \u00e0 Bamako\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali\u00a0: Une avant\u2011premi\u00e8re prometteuse pour la 2\u1d49\u202f\u00e9dition du Salon des Arts, du Design et de la D\u00e9coration \u00e0 Bamako - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali\u00a0: Une avant\u2011premi\u00e8re prometteuse pour la 2\u1d49\u202f\u00e9dition du Salon des Arts, du Design et de la D\u00e9coration \u00e0 Bamako - REUSSITE INFO","og_description":"La capitale malienne s\u2019appr\u00eate \u00e0 accueillir la deuxi\u00e8me \u00e9dition du Salon des Arts, du Design et de la D\u00e9coration (SADDEC)","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/","og_site_name":"REUSSITE INFO","article_published_time":"2025-10-20T10:03:57+00:00","article_modified_time":"2025-10-20T11:53:53+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2025\/10\/105967484_2662427380665741_3567305212197665138_n.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali\u00a0: Une avant\u2011premi\u00e8re prometteuse pour la 2\u1d49\u202f\u00e9dition du Salon des Arts, du Design et de la D\u00e9coration \u00e0 Bamako","datePublished":"2025-10-20T10:03:57+00:00","dateModified":"2025-10-20T11:53:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/"},"wordCount":497,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2025\/10\/105967484_2662427380665741_3567305212197665138_n.jpg","articleSection":["BUSINESS"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/","name":"Mali\u00a0: Une avant\u2011premi\u00e8re prometteuse pour la 2\u1d49\u202f\u00e9dition du Salon des Arts, du Design et de la D\u00e9coration \u00e0 Bamako - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2025\/10\/105967484_2662427380665741_3567305212197665138_n.jpg","datePublished":"2025-10-20T10:03:57+00:00","dateModified":"2025-10-20T11:53:53+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2025\/10\/105967484_2662427380665741_3567305212197665138_n.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2025\/10\/105967484_2662427380665741_3567305212197665138_n.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2025\/10\/20\/mali-le-chef-du-gouvernement-recoit-une-delegation-des-douanes-de-laes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali\u00a0: Une avant\u2011premi\u00e8re prometteuse pour la 2\u1d49\u202f\u00e9dition du Salon des Arts, du Design et de la D\u00e9coration \u00e0 Bamako"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/5877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=5877"}],"version-history":[{"count":2,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/5877\/revisions"}],"predecessor-version":[{"id":5891,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/5877\/revisions\/5891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/5886"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=5877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=5877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=5877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}