{"id":4476,"date":"2023-01-17T17:42:36","date_gmt":"2023-01-17T17:42:36","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=4476"},"modified":"2023-01-17T17:42:36","modified_gmt":"2023-01-17T17:42:36","slug":"promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/","title":{"rendered":"Promotion de la citoyennet\u00e9 active : 33 \u2018\u2019citoyens mod\u00e8les\u2019\u2019 prim\u00e9s en commune I"},"content":{"rendered":"\n<p>\u00ab Citoyennet\u00e9, un facteur de d\u00e9veloppement \u00bb, tel \u00e9tait le th\u00e8me de la 2e \u00e9dition de la c\u00e9r\u00e9monie de distinction des Citoyens mod\u00e8les de la commune I du district de Bamako, organis\u00e9e par le Mouvement des jeunes pour le d\u00e9veloppement du Mali (MJDM) en collaboration avec l\u2019Agence de communication \u2018\u2019Planet-com\u2019\u2019. Au total, 33 citoyens ont \u00e9t\u00e9 identifi\u00e9s comme \u2018\u2019mod\u00e8le\u2019\u2019 \u00e0 travers leurs actions citoyennes au titre de l\u2019ann\u00e9e 2022. Ces laur\u00e9ats compos\u00e9s des \u00e9lus municipaux, des anciens ministres, des hommes m\u00e9dia, des th\u00e9rapeutes ; des directeurs d\u2019\u00e9tablissement sup\u00e9rieur priv\u00e9, des commissaires de police, ont tous b\u00e9n\u00e9fici\u00e9 des m\u00e9dailles et des attestations de reconnaissance.<\/p>\n\n\n\n<p>La c\u00e9r\u00e9monie de distinction a eu lieu, ce samedi 14 janvier 2023, \u00e0 Muso Kunda, \u00e0 Korofina. L\u2019\u00e9v\u00e9nement \u00e9tait plac\u00e9 sous la pr\u00e9sidence du maire de la commune I, Oumar TOGO ; en pr\u00e9sence du pr\u00e9sident de la commission d\u2019organisation du \u2018\u2019citoyen mod\u00e8le\u2019\u2019, Ousmane TOURE dit Tonton et plusieurs autres personnalit\u00e9s de la commune I, notamment, le repr\u00e9sentant des Chefs de quartiers ; du repr\u00e9sentant des imams ; des \u00c9glises catholique et protestante ; etc.<br>Dans son intervention, Ousmane TOURE dit Tonton a signal\u00e9 qu\u2019il \u00e9tait tr\u00e8s bon souvent de reconnaitre le travail bien fait de certaines personnes. Il a insist\u00e9 qu\u2019il ne faudrait pas attendre le d\u00e9c\u00e8s d\u2019un citoyen mod\u00e8le pour le d\u00e9corer. C\u2019est dans ce sens, selon lui, que le Mouvement des jeunes pour le d\u00e9veloppement du Mali (MJDM) a constat\u00e9 que des citoyens s\u2019investissent dans les quartiers pour l\u2019\u00e9panouissement de la commune sans le tambour ni la trompette.<br>Au retour, ajoute-t-il, la population doit \u00eatre reconnaissante envers ces patriotes.<br>Toutefois, Ousmane TOURE a indiqu\u00e9 que cette c\u00e9r\u00e9monie de distinction du citoyen mod\u00e8le \u00e9tait une activit\u00e9 \u00e0 but non lucratif.<br>Il a pr\u00e9cis\u00e9 qu\u2019en plus des personnes de bonne volont\u00e9, les membres du Mouvement et l\u2019Agence de Communication \u2018\u2019Planet-com\u2019\u2019 contribuaient financi\u00e8rement pour la r\u00e9ussite de l\u2019\u00e9v\u00e8nement.<br>Cela ne veut pas dire, soutient le pr\u00e9sident TOURE, que les partenaires sont exclus. Il a d\u00e9plor\u00e9 que les partenaires ne soient pas int\u00e9ress\u00e9s \u00e0 cette distinction noble qui n\u2019\u00e9tait pas \u00e0 caract\u00e8re festif.<\/p>\n\n\n\n<p>Concernant la s\u00e9lection du citoyen mod\u00e8le, selon Ousmane TOURE, une commission du Mouvement avait fait des investigations dans la commune sur les \u0153uvres des gens. Au titre de l\u2019ann\u00e9e 2022, sur une pr\u00e9s\u00e9lection de plus de 100 personnes, 33 personnes ont \u00e9t\u00e9 qualifi\u00e9es comme des \u2018\u2019citoyens mod\u00e8les\u2019\u2019 de la commune I, contre 17 \u2018\u2019citoyens mod\u00e8les\u2019\u2019 en 2021.<\/p>\n\n\n\n<p>Pour sa part, Oumar TOGO s\u2019est r\u00e9joui que des citoyens soient qualifi\u00e9s de mod\u00e8les dans sa commune I, qui constitue une fiert\u00e9 pour lui.<br>Au nom du conseil communal, il a f\u00e9licit\u00e9 les initiateurs de cette c\u00e9r\u00e9monie de distinction des personnalit\u00e9s comme des \u2018\u2019citoyens mod\u00e8les\u2019\u2019 de la commune I par rapport \u00e0 leur savoir-faire et \u00e0 leur soutien \u00e0 la commune.<br>Aux dires du maire Oumar TOGO, quand on est honor\u00e9 dans une action citoyenne, on doit pouvoir pr\u00e9server cet honneur. Il a invit\u00e9 les autres citoyens \u00e0 imiter ces Femmes et ces hommes qui sont parvenus \u00e0 avoir la m\u00e9daille du \u2018\u2019citoyen mod\u00e8le\u2019\u2019, pour le progr\u00e8s de la commune en particulier et du Mali en g\u00e9n\u00e9ral.<br>De son c\u00f4t\u00e9, le porte-parole des laur\u00e9ats, Modibo FOFANA, directeur de publication de \u2018\u2019Mali-24\u2019\u2019 et non moins Pr\u00e9sident de l\u2019Association de la presse en ligne du Mali (APPEL-Mali) s\u2019est r\u00e9joui, au nom de ses pairs, d\u2019\u00eatre choisis comme \u2018\u2019citoyen mod\u00e8le\u2019\u2019 de la commune I, par le Mouvement des jeunes pour le d\u00e9veloppement du Mali. Il a montr\u00e9 que cette initiative m\u00e9rite d\u2019\u00eatre salu\u00e9e non seulement par la population, mais aussi par les autorit\u00e9s communales.<br>Concernant le cas des hommes de m\u00e9dia, le Pr\u00e9sident de APPEL-Mali a soulign\u00e9 que les journalistes et autres communicateurs sont des cordonniers mal chauss\u00e9s. Car, dit-il, en longueur de journ\u00e9e, les journalistes font la promotion des uns et des autres, en s\u2019oubliant eux-m\u00eames. Une telle initiative, en faisant surtout la promotion des Hommes de m\u00e9dia, doit \u00eatre encourag\u00e9e et l\u2019accompagn\u00e9, a-t-il soutenu.<br>Enfin, le porte-parole le laur\u00e9at Modibo FOFANA a pris l\u2019engagement d\u2019initier \u00e0 l\u2019\u00e9criture web, \u00e0 l\u2019utilisation des m\u00e9dias sociaux et en essayant de comprendre l\u2019\u00e9thique et la d\u00e9ontologie de ce m\u00e9tier, tous les jeunes qui sont en commune I et qui sont int\u00e9ress\u00e9s \u00e0 la presse num\u00e9rique.<\/p>\n\n\n\n<p><strong>Par SABA BALLO<\/strong><\/p>\n\n\n\n<p><strong>Source : Info Matin<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Citoyennet\u00e9, un facteur de d\u00e9veloppement \u00bb, tel \u00e9tait le th\u00e8me de la 2e \u00e9dition de la c\u00e9r\u00e9monie de distinction<\/p>\n","protected":false},"author":1,"featured_media":4477,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Promotion de la citoyennet\u00e9 active : 33 \u2018\u2019citoyens mod\u00e8les\u2019\u2019 prim\u00e9s en commune I - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Promotion de la citoyennet\u00e9 active : 33 \u2018\u2019citoyens mod\u00e8les\u2019\u2019 prim\u00e9s en commune I - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"\u00ab Citoyennet\u00e9, un facteur de d\u00e9veloppement \u00bb, tel \u00e9tait le th\u00e8me de la 2e \u00e9dition de la c\u00e9r\u00e9monie de distinction\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-17T17:42:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2023\/01\/IMG-20221021-WA0032.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"862\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/17\\\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/17\\\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Promotion de la citoyennet\u00e9 active : 33 \u2018\u2019citoyens mod\u00e8les\u2019\u2019 prim\u00e9s en commune I\",\"datePublished\":\"2023-01-17T17:42:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/17\\\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\\\/\"},\"wordCount\":810,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/17\\\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG-20221021-WA0032.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/17\\\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/17\\\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\\\/\",\"name\":\"Promotion de la citoyennet\u00e9 active : 33 \u2018\u2019citoyens mod\u00e8les\u2019\u2019 prim\u00e9s en commune I - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/17\\\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/17\\\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG-20221021-WA0032.jpg\",\"datePublished\":\"2023-01-17T17:42:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/17\\\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/17\\\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/17\\\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG-20221021-WA0032.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG-20221021-WA0032.jpg\",\"width\":1080,\"height\":862},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/17\\\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Promotion de la citoyennet\u00e9 active : 33 \u2018\u2019citoyens mod\u00e8les\u2019\u2019 prim\u00e9s en commune I\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Promotion de la citoyennet\u00e9 active : 33 \u2018\u2019citoyens mod\u00e8les\u2019\u2019 prim\u00e9s en commune I - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/","og_locale":"fr_FR","og_type":"article","og_title":"Promotion de la citoyennet\u00e9 active : 33 \u2018\u2019citoyens mod\u00e8les\u2019\u2019 prim\u00e9s en commune I - REUSSITE INFO","og_description":"\u00ab Citoyennet\u00e9, un facteur de d\u00e9veloppement \u00bb, tel \u00e9tait le th\u00e8me de la 2e \u00e9dition de la c\u00e9r\u00e9monie de distinction","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/","og_site_name":"REUSSITE INFO","article_published_time":"2023-01-17T17:42:36+00:00","og_image":[{"width":1080,"height":862,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2023\/01\/IMG-20221021-WA0032.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Promotion de la citoyennet\u00e9 active : 33 \u2018\u2019citoyens mod\u00e8les\u2019\u2019 prim\u00e9s en commune I","datePublished":"2023-01-17T17:42:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/"},"wordCount":810,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2023\/01\/IMG-20221021-WA0032.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/","name":"Promotion de la citoyennet\u00e9 active : 33 \u2018\u2019citoyens mod\u00e8les\u2019\u2019 prim\u00e9s en commune I - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2023\/01\/IMG-20221021-WA0032.jpg","datePublished":"2023-01-17T17:42:36+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2023\/01\/IMG-20221021-WA0032.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2023\/01\/IMG-20221021-WA0032.jpg","width":1080,"height":862},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/17\/promotion-de-la-citoyennete-active-33-citoyens-modeles-primes-en-commune-i\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Promotion de la citoyennet\u00e9 active : 33 \u2018\u2019citoyens mod\u00e8les\u2019\u2019 prim\u00e9s en commune I"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/4476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=4476"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/4476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/4477"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=4476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=4476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=4476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}