{"id":4457,"date":"2023-01-10T02:49:12","date_gmt":"2023-01-10T02:49:12","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=4457"},"modified":"2023-01-10T02:49:12","modified_gmt":"2023-01-10T02:49:12","slug":"mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/","title":{"rendered":"Mali\u00a0: La DGCC renforce les capacit\u00e9s de ses personnels pour la lutte contre la hausse des prix"},"content":{"rendered":"\n<p>La Direction G\u00e9n\u00e9rale du Commerce et de la Concurrence ( DGCC ) a organis\u00e9 deux jours de formation le 05 et le 06 janvier 2023, \u00e0 l&rsquo;h\u00f4tel Millenium. L&rsquo;objectif vis\u00e9 est de renforcer la capacit\u00e9 des personnels de la DGCC pour l&rsquo;accomplissement de leur mission. La c\u00e9r\u00e9monie d&rsquo;ouverture a \u00e9t\u00e9 pr\u00e9sid\u00e9e par le chef de cabinet du minist\u00e8re du Commerce et d&rsquo;Industrie, Sidi Ahmed Ould Sidi SALEM. On notait \u00e0 ses c\u00f4t\u00e9s la pr\u00e9sence du directeur g\u00e9n\u00e9rale du Commerce et de la Concurrence, Boucadary DOUMBIA.<\/p>\n\n\n\n<p>La pr\u00e9sente session de cette s\u00e9rie de formation continue porte sur des th\u00e9matiques li\u00e9es \u00e0 la maitrise de la cha\u00eene d\u2019approvisionnement de notre pays. Elle permettra de disposer d&rsquo;un personnel qualifi\u00e9 pouvant aider favorablement le d\u00e9partement en charge du commerce \u00e0 mettre efficacement en \u0153uvre les mesures d\u2019ordre commercial adopt\u00e9es par le gouvernement pour contenir la hausse des prix et ses effets sur le pouvoir d\u2019achat des consommateurs. Ainsi, au cours de ces deux jours la formation s&rsquo;articule sur le fonctionnement du circuit de distribution des produits de premi\u00e8re n\u00e9cessit\u00e9 ; l\u2019op\u00e9rationnalisation du Guichet unique du commerce ext\u00e9rieur de la DGCC; la mise en \u0153uvre des mesures de facilitation des \u00e9changes. \u00ab \u00c0 l\u2019issue de cette formation, vous disposerez, j\u2019en suis convaincu, des capacit\u00e9s th\u00e9oriques et pratiques vous permettant d\u2019assurer convenablement vos missions en tant qu\u2019acteurs majeurs dans la mise en \u0153uvre des mesures de lutte contre la hausse injustifi\u00e9e des prix des produits de premi\u00e8re n\u00e9cessit\u00e9 \u00bb se rassure le chef du cabinet du minist\u00e8re du Commerce et d&rsquo;Industrie, Sidi Ahmed Ould Sidi SALEM.<\/p>\n\n\n\n<p>Cette session de formation concerne les agents techniques des structures centrales, r\u00e9gionales et subr\u00e9gionales du commerce, de la consommation et de la concurrence en g\u00e9n\u00e9ral \u00e9largie aux repr\u00e9sentants des autres structures techniques de mon d\u00e9partement ainsi qu\u2019aux membres du cabinet du minist\u00e8re du Commerce.<\/p>\n\n\n\n<p><strong>Falaye SISSOKO<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Direction G\u00e9n\u00e9rale du Commerce et de la Concurrence ( DGCC ) a organis\u00e9 deux jours de formation le 05<\/p>\n","protected":false},"author":1,"featured_media":4458,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali\u00a0: La DGCC renforce les capacit\u00e9s de ses personnels pour la lutte contre la hausse des prix - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali\u00a0: La DGCC renforce les capacit\u00e9s de ses personnels pour la lutte contre la hausse des prix - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"La Direction G\u00e9n\u00e9rale du Commerce et de la Concurrence ( DGCC ) a organis\u00e9 deux jours de formation le 05\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-10T02:49:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2023\/01\/dgccouivf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"561\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/10\\\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/10\\\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali\u00a0: La DGCC renforce les capacit\u00e9s de ses personnels pour la lutte contre la hausse des prix\",\"datePublished\":\"2023-01-10T02:49:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/10\\\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\\\/\"},\"wordCount\":365,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/10\\\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/dgccouivf.jpg\",\"articleSection\":[\"EDITORIAL\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/10\\\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/10\\\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\\\/\",\"name\":\"Mali\u00a0: La DGCC renforce les capacit\u00e9s de ses personnels pour la lutte contre la hausse des prix - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/10\\\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/10\\\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/dgccouivf.jpg\",\"datePublished\":\"2023-01-10T02:49:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/10\\\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/10\\\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/10\\\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/dgccouivf.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/dgccouivf.jpg\",\"width\":1000,\"height\":561},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2023\\\/01\\\/10\\\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali\u00a0: La DGCC renforce les capacit\u00e9s de ses personnels pour la lutte contre la hausse des prix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali\u00a0: La DGCC renforce les capacit\u00e9s de ses personnels pour la lutte contre la hausse des prix - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali\u00a0: La DGCC renforce les capacit\u00e9s de ses personnels pour la lutte contre la hausse des prix - REUSSITE INFO","og_description":"La Direction G\u00e9n\u00e9rale du Commerce et de la Concurrence ( DGCC ) a organis\u00e9 deux jours de formation le 05","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/","og_site_name":"REUSSITE INFO","article_published_time":"2023-01-10T02:49:12+00:00","og_image":[{"width":1000,"height":561,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2023\/01\/dgccouivf.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali\u00a0: La DGCC renforce les capacit\u00e9s de ses personnels pour la lutte contre la hausse des prix","datePublished":"2023-01-10T02:49:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/"},"wordCount":365,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2023\/01\/dgccouivf.jpg","articleSection":["EDITORIAL"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/","name":"Mali\u00a0: La DGCC renforce les capacit\u00e9s de ses personnels pour la lutte contre la hausse des prix - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2023\/01\/dgccouivf.jpg","datePublished":"2023-01-10T02:49:12+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2023\/01\/dgccouivf.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2023\/01\/dgccouivf.jpg","width":1000,"height":561},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2023\/01\/10\/mali-la-dgcc-renforce-les-capacites-de-ses-personnels-pour-la-lutte-contre-la-hausse-des-prix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali\u00a0: La DGCC renforce les capacit\u00e9s de ses personnels pour la lutte contre la hausse des prix"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/4457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=4457"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/4457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/4458"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=4457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=4457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=4457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}