{"id":4434,"date":"2022-12-27T04:08:51","date_gmt":"2022-12-27T04:08:51","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=4434"},"modified":"2022-12-27T04:08:51","modified_gmt":"2022-12-27T04:08:51","slug":"mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/","title":{"rendered":"Mali : La BCEAO a rendu public les comptes ext\u00e9rieurs du Mali pour l\u2019analyse des politiques \u00e9conomiques"},"content":{"rendered":"\n<p>La 15\u00e8 \u00e9dition de la journ\u00e9e de diffusion des Comptes ext\u00e9rieurs du Mali a eu lieu le mardi 20 d\u00e9cembre 2022, \u00e0 l\u2019h\u00f4tel Sheraton de Bamako sur le th\u00e8me : \u00ab La hausse des prix&nbsp;: origines, impacts et d\u00e9fis \u00bb. La c\u00e9r\u00e9monie d\u2019ouverture des travaux a \u00e9t\u00e9 pr\u00e9sid\u00e9e par le repr\u00e9sentant du minist\u00e8re de l\u2019\u00c9conomie et des Finances, Diakaridia DEMBELE en pr\u00e9sence du directeur national de la Banque centrale des \u00c9tats de l\u2019Afrique de l\u2019Ouest (BCEAO), Konzo TRAORE. Elle a enregistr\u00e9 la pr\u00e9sence des repr\u00e9sentants des institutions internationales et r\u00e9gionales, des services centraux de l\u2019\u00c9tat, des directeurs g\u00e9n\u00e9raux des soci\u00e9t\u00e9s, des banques et \u00e9tablissements financiers.<\/p>\n\n\n\n<p>Organis\u00e9e par la Banque centrale des \u00c9tats de l\u2019Afrique de l\u2019Ouest (BCEAO), cette journ\u00e9e est devenue un rendez-vous annuel inscrit dans l\u2019agenda national. C\u2019est pourquoi, le repr\u00e9sentant du minist\u00e8re de l\u2019\u00c9conomie et des Finances, Diakaridia DEMBELE, a f\u00e9licit\u00e9 les acteurs pour la r\u00e9gularit\u00e9 dans la production de la balance des paiements. \u00ab <em>Cet instrument fondamental pour l\u2019analyse, la d\u00e9cision et la formulation des politiques \u00e9conomiques est de mieux en mieux connue des d\u00e9cideurs politiques et des acteurs du secteur priv\u00e9<\/em> \u00bb a indiqu\u00e9 le repr\u00e9sentant du ministre. Selon lui, la production des statistiques sur la balance des paiements et des statistiques mon\u00e9taires fait partie int\u00e9grante du sch\u00e9ma directeur de la statistique 2020-2024. Elle vise \u00e0 doter le Mali d\u2019un syst\u00e8me statistique national performant \u00e0 m\u00eame de produire, analyser et diffuser des donn\u00e9es de qualit\u00e9 couvrant les besoins des diff\u00e9rents utilisateurs. Cette journ\u00e9e poursuit-il, va permettre de familiariser davantage les acteurs de la vie \u00e9conomique nationale aux concepts de balance des paiements et de renforcer le dialogue entre les secteurs public et priv\u00e9, dans le cadre de l\u2019analyse \u00e9conomique, de la d\u00e9finition des politiques \u00e9conomiques, notamment l\u2019am\u00e9lioration durable de la position ext\u00e9rieure. Il pr\u00e9cisera que le d\u00e9partement de l\u2019\u00e9conomie et des finances accorde une attention particuli\u00e8re \u00e0 la production des statistiques de balance des paiements.<\/p>\n\n\n\n<p>Pour le directeur national de la BCEAO, Konzo TRAORE, les exportations de biens se sont \u00e9lev\u00e9es \u00e0 2.693.8 milliards de FCFA, en repli de 2,4% par rapport \u00e0 2020, en liaison avec la baisse des ventes ext\u00e9rieures d\u2019or mon\u00e9taire. \u00ab&nbsp;<em>L\u2019or y repr\u00e9sente 79%, suivi du coton, avec 6%, pour des montants de 2.129 milliards et 157 milliards respectivement. Ces chiffres illustres la tr\u00e8s forte d\u00e9pendance du Mali par rapport aux exportations d\u2019or<\/em>&nbsp;\u00bb a soutenu Konzo TRAORE.<\/p>\n\n\n\n<p>Selon le premier responsable de la BCEAO, les importations des biens FOB, hors fret et assurance, se sont \u00e9tablies \u00e0 2,863 milliards de FCFA, en augmentation de 15.9% par rapport \u00e0 2020. \u00ab&nbsp;<em>Ce faisant, la balance commerciale qui repr\u00e9sente la diff\u00e9rence entre la valeur des biens export\u00e9s et celle des biens import\u00e9s, est ressortie d\u00e9ficitaire de de 169 milliards de FCFA, en d\u00e9gradation par rapport \u00e0 2020 o\u00f9 elle a affich\u00e9 un exc\u00e8dent de 290 milliards de FCFA. Cette \u00e9volution est imputable&nbsp;&nbsp; la forte progression des importations, parall\u00e8lement \u00e0 la baisse des exportations<\/em>&nbsp;\u00bb a comment\u00e9 Konzo TRAORE.<\/p>\n\n\n\n<p>Aux dires de directeur national, le solde courant est ressorti \u00e0 -814 milliards en 2021, apr\u00e8s -219 milliards en 2020, et repr\u00e9sente -7,7% du PIB. Le solde global s\u2019est \u00e9tabli \u00e0 -57,8 milliards de FCFA apr\u00e8s un exc\u00e9dent de 450,8 milliards l\u2019ann\u00e9e pr\u00e9c\u00e9dente. Selon lui, la d\u00e9t\u00e9rioration du solde global s\u2019explique essentiellement par celui du compte courant.<\/p>\n\n\n\n<p><strong>Charles MESSE<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 15\u00e8 \u00e9dition de la journ\u00e9e de diffusion des Comptes ext\u00e9rieurs du Mali a eu lieu le mardi 20 d\u00e9cembre<\/p>\n","protected":false},"author":1,"featured_media":4435,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali : La BCEAO a rendu public les comptes ext\u00e9rieurs du Mali pour l\u2019analyse des politiques \u00e9conomiques - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali : La BCEAO a rendu public les comptes ext\u00e9rieurs du Mali pour l\u2019analyse des politiques \u00e9conomiques - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"La 15\u00e8 \u00e9dition de la journ\u00e9e de diffusion des Comptes ext\u00e9rieurs du Mali a eu lieu le mardi 20 d\u00e9cembre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-27T04:08:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/12\/1-bceao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"690\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/12\\\/27\\\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/12\\\/27\\\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali : La BCEAO a rendu public les comptes ext\u00e9rieurs du Mali pour l\u2019analyse des politiques \u00e9conomiques\",\"datePublished\":\"2022-12-27T04:08:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/12\\\/27\\\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\\\/\"},\"wordCount\":628,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/12\\\/27\\\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/1-bceao.jpg\",\"articleSection\":[\"EDITORIAL\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/12\\\/27\\\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/12\\\/27\\\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\\\/\",\"name\":\"Mali : La BCEAO a rendu public les comptes ext\u00e9rieurs du Mali pour l\u2019analyse des politiques \u00e9conomiques - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/12\\\/27\\\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/12\\\/27\\\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/1-bceao.jpg\",\"datePublished\":\"2022-12-27T04:08:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/12\\\/27\\\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/12\\\/27\\\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/12\\\/27\\\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/1-bceao.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/1-bceao.jpg\",\"width\":690,\"height\":421},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/12\\\/27\\\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali : La BCEAO a rendu public les comptes ext\u00e9rieurs du Mali pour l\u2019analyse des politiques \u00e9conomiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali : La BCEAO a rendu public les comptes ext\u00e9rieurs du Mali pour l\u2019analyse des politiques \u00e9conomiques - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali : La BCEAO a rendu public les comptes ext\u00e9rieurs du Mali pour l\u2019analyse des politiques \u00e9conomiques - REUSSITE INFO","og_description":"La 15\u00e8 \u00e9dition de la journ\u00e9e de diffusion des Comptes ext\u00e9rieurs du Mali a eu lieu le mardi 20 d\u00e9cembre","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/","og_site_name":"REUSSITE INFO","article_published_time":"2022-12-27T04:08:51+00:00","og_image":[{"width":690,"height":421,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/12\/1-bceao.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali : La BCEAO a rendu public les comptes ext\u00e9rieurs du Mali pour l\u2019analyse des politiques \u00e9conomiques","datePublished":"2022-12-27T04:08:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/"},"wordCount":628,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/12\/1-bceao.jpg","articleSection":["EDITORIAL"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/","name":"Mali : La BCEAO a rendu public les comptes ext\u00e9rieurs du Mali pour l\u2019analyse des politiques \u00e9conomiques - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/12\/1-bceao.jpg","datePublished":"2022-12-27T04:08:51+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/12\/1-bceao.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/12\/1-bceao.jpg","width":690,"height":421},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/12\/27\/mali-la-bceao-a-rendu-public-les-comptes-exterieurs-du-mali-pour-lanalyse-des-politiques-economiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali : La BCEAO a rendu public les comptes ext\u00e9rieurs du Mali pour l\u2019analyse des politiques \u00e9conomiques"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/4434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=4434"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/4434\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/4435"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=4434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=4434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=4434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}