{"id":4237,"date":"2022-11-14T03:15:43","date_gmt":"2022-11-14T03:15:43","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=4237"},"modified":"2022-11-14T03:15:43","modified_gmt":"2022-11-14T03:15:43","slug":"mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/","title":{"rendered":"Mali : La 5\u00e8me \u00e9dition des journ\u00e9es d\u2019\u00e9changes Justice-Presse pour plus de synergie dans les rapports sur la corruption"},"content":{"rendered":"\n<p>Le minist\u00e8re de la Justice, des Droits de l\u2019Homme, garde des Sceaux en collaboration avec la maison de la Presse a pour la 5eme fois organis\u00e9 les journ\u00e9es d\u2019\u00e9changes Justice-Presse. C\u2019\u00e9tait sous la pr\u00e9sidence du secr\u00e9taire g\u00e9n\u00e9ral dudit d\u00e9partement, Dr Boubacar DIARRAH, le vendredi 11 Novembre 2022, dans la salle de conf\u00e9rence de la maison de la Presse de Bamako, en pr\u00e9sence du chef de la Coop\u00e9ration par int\u00e9rim de l\u2019ambassade du Canada au Mali, Marc LE BLANC, et du pr\u00e9sident de la maison de la Presse, Bandjougou DANTE.<\/p>\n\n\n\n<p>Cette rencontre a pour th\u00e8me la \u00ab <em>Synergie dans les rapports fonctionnels entre les structures de contr\u00f4le, de v\u00e9rification et de poursuites dans la lutte contre la corruption, la d\u00e9linquance \u00e9conomique et financi\u00e8re et pratiques assimil\u00e9es<\/em> \u00bb, et vise \u00e0 pr\u00f4ner l\u2019esprit d\u2019une compl\u00e9mentarit\u00e9 entre elles et la cha\u00eene judiciaire, notamment les autorit\u00e9s de poursuites, afin de d\u00e9masquer les d\u00e9linquants financiers, de fournir \u00e0 la justice les \u00e9l\u00e9ments de base pour l\u2019enqu\u00eate, et d\u2019appuyer la justice dans la recherche et la production des \u00e9l\u00e9ments de preuve \u00e0 l\u2019encontre des auteurs pr\u00e9sum\u00e9s d\u2019infractions \u00e0 la loi p\u00e9nale.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Le secr\u00e9taire g\u00e9n\u00e9ral dudit d\u00e9partement, Dr Boubacar DIARRAH a affirm\u00e9 avec fiert\u00e9, que les objectifs de ces journ\u00e9es ont \u00e9t\u00e9 atteints \u00ab&nbsp;<em>Car, par vos reportages, souvent en direct, vos \u00e9crits, vos commentaires et vos analyses, vous avez contribu\u00e9 \u00e0 \u00e9difier l\u2019opinion publique sur bien des aspects li\u00e9s aux th\u00e9matiques qui ont \u00e9t\u00e9 abord\u00e9es&nbsp;<\/em>\u00bb a soutenu Dr DIARRAH.<\/p>\n\n\n\n<p>A en croire ses propos, certaines actions sont en cours afin de renforcer la synergie, d\u2019une part, entre structures de contr\u00f4le, de v\u00e9rification et d\u2019inspection, et d\u2019autre part, entre celles-ci et la justice. \u00ab&nbsp;<em>Il s\u2019agit de la mise en place de trois cadres qui seront formalis\u00e9s par d\u00e9cret, en vue de donner une base juridique \u00e0 la collaboration entre les diff\u00e9rentes structures \u00e0 l\u2019effet de cr\u00e9er la compl\u00e9mentarit\u00e9 n\u00e9cessaire pour une gestion efficace des affaires de corruption et de d\u00e9linquance \u00e9conomique et financi\u00e8re<\/em>&nbsp;\u00bb, a indiqu\u00e9 le secr\u00e9taire g\u00e9n\u00e9ral dudit minist\u00e8re.<\/p>\n\n\n\n<p>Pour le pr\u00e9sident de la maison de la Presse, Bandjougou DANTE, ces journ\u00e9es sont la volont\u00e9 des plus hautes autorit\u00e9s du pays pour permettre aux journalistes d\u2019\u00eatre en contact avec la justice, afin de donner la bonne information \u00e0 la population pour lutter contre la corruption et la d\u00e9linquance financi\u00e8re.<br><br><\/p>\n\n\n\n<p>S\u2019agissant du chef de la Coop\u00e9ration par int\u00e9rim de l\u2019ambassade du Canada au Mali, Marc LE BLANC, il a avou\u00e9 clairement que le Canada est particuli\u00e8rement int\u00e9ress\u00e9 par le th\u00e8me, qui met en exergue le lien logique, entre les \u00e9l\u00e9ments d\u2019un maillon important de la lutte contre la corruption qui sont le contr\u00f4le, la v\u00e9rification et la poursuite. Selon Marc LE BLANC, la distribution d\u2019une bonne justice est largement tributaire de la mise en \u0153uvre efficace du travail combien important qui doit se faire en amont \u00e0 travers cette cha\u00eene.<\/p>\n\n\n\n<p>Apr\u00e8s les discours officiels et la communication du directeur national des Affaires Judiciaires et des Sceaux (DNAJES), Mohamed Maouloud NADJIM, sur le th\u00e8me central de cette 5eme \u00e9dition des journ\u00e9es d\u2019\u00e9changes Justice Presse, l\u2019on retient que pour la lutte contre la corruption et la d\u00e9linquance \u00e9conomique et financi\u00e8re au Mali, il y a trop de structures de contr\u00f4le, de v\u00e9rification et de poursuite. Elles sont au nombre de 16 inspections d\u00e9partementales et chaque structure est comp\u00e9tente et autonome. C\u2019est pourquoi, le chef de la DNAJES a recommand\u00e9 qu\u2019il y ait une synergie d\u2019actions avec la mise en place d\u2019un cadre de concertation pour mieux structurer les actions de contr\u00f4le et de v\u00e9rification.<\/p>\n\n\n\n<p>Dans un d\u00e9bat contradictoire, le chef de service juridique du bureau du v\u00e9rificateur g\u00e9n\u00e9ral, Satigui TRAORE a r\u00e9torqu\u00e9 que toutes ces structures cit\u00e9es par le DNAJES ne sont pas pour le contr\u00f4le g\u00e9n\u00e9ral, mais interne \u00e0 chaque d\u00e9partement. Ce qui veut dire selon lui, qu\u2019il n\u2019y a que 2 structures de contr\u00f4le g\u00e9n\u00e9rales et plus de 3000 services de contr\u00f4le public interne au Mali.<\/p>\n\n\n\n<p>Ces d\u00e9bats contradictoires ont permis \u00e0 beaucoup de journalistes et patrons de presse, de trouver des failles pour poser des questions de construction qui m\u00e9ritent une r\u00e9flexion approfondie, vu la complexit\u00e9 de la forme de la collaboration devant exister entre les structures de contr\u00f4le ou de v\u00e9rification et la justice.<\/p>\n\n\n\n<p><strong>Charles le Bon MESSE<\/strong><strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le minist\u00e8re de la Justice, des Droits de l\u2019Homme, garde des Sceaux en collaboration avec la maison de la Presse<\/p>\n","protected":false},"author":1,"featured_media":4238,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali : La 5\u00e8me \u00e9dition des journ\u00e9es d\u2019\u00e9changes Justice-Presse pour plus de synergie dans les rapports sur la corruption - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali : La 5\u00e8me \u00e9dition des journ\u00e9es d\u2019\u00e9changes Justice-Presse pour plus de synergie dans les rapports sur la corruption - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"Le minist\u00e8re de la Justice, des Droits de l\u2019Homme, garde des Sceaux en collaboration avec la maison de la Presse\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-14T03:15:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/11\/20221111_093103-800x445-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/14\\\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/14\\\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali : La 5\u00e8me \u00e9dition des journ\u00e9es d\u2019\u00e9changes Justice-Presse pour plus de synergie dans les rapports sur la corruption\",\"datePublished\":\"2022-11-14T03:15:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/14\\\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\\\/\"},\"wordCount\":836,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/14\\\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/20221111_093103-800x445-1.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/14\\\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/14\\\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\\\/\",\"name\":\"Mali : La 5\u00e8me \u00e9dition des journ\u00e9es d\u2019\u00e9changes Justice-Presse pour plus de synergie dans les rapports sur la corruption - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/14\\\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/14\\\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/20221111_093103-800x445-1.jpg\",\"datePublished\":\"2022-11-14T03:15:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/14\\\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/14\\\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/14\\\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/20221111_093103-800x445-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/20221111_093103-800x445-1.jpg\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/14\\\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali : La 5\u00e8me \u00e9dition des journ\u00e9es d\u2019\u00e9changes Justice-Presse pour plus de synergie dans les rapports sur la corruption\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali : La 5\u00e8me \u00e9dition des journ\u00e9es d\u2019\u00e9changes Justice-Presse pour plus de synergie dans les rapports sur la corruption - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali : La 5\u00e8me \u00e9dition des journ\u00e9es d\u2019\u00e9changes Justice-Presse pour plus de synergie dans les rapports sur la corruption - REUSSITE INFO","og_description":"Le minist\u00e8re de la Justice, des Droits de l\u2019Homme, garde des Sceaux en collaboration avec la maison de la Presse","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/","og_site_name":"REUSSITE INFO","article_published_time":"2022-11-14T03:15:43+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/11\/20221111_093103-800x445-1.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali : La 5\u00e8me \u00e9dition des journ\u00e9es d\u2019\u00e9changes Justice-Presse pour plus de synergie dans les rapports sur la corruption","datePublished":"2022-11-14T03:15:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/"},"wordCount":836,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/11\/20221111_093103-800x445-1.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/","name":"Mali : La 5\u00e8me \u00e9dition des journ\u00e9es d\u2019\u00e9changes Justice-Presse pour plus de synergie dans les rapports sur la corruption - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/11\/20221111_093103-800x445-1.jpg","datePublished":"2022-11-14T03:15:43+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/11\/20221111_093103-800x445-1.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/11\/20221111_093103-800x445-1.jpg","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/14\/mali-la-5eme-edition-des-journees-dechanges-justice-presse-pour-plus-de-synergie-dans-les-rapports-sur-la-corruption\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali : La 5\u00e8me \u00e9dition des journ\u00e9es d\u2019\u00e9changes Justice-Presse pour plus de synergie dans les rapports sur la corruption"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/4237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=4237"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/4237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/4238"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=4237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=4237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=4237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}