{"id":4206,"date":"2022-11-06T15:58:28","date_gmt":"2022-11-06T15:58:28","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=4206"},"modified":"2022-11-06T15:58:28","modified_gmt":"2022-11-06T15:58:28","slug":"mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/","title":{"rendered":"Mali : Lancement officiel du mouvement she leads pour soutenir le leadership f\u00e9minin"},"content":{"rendered":"\n<p>L&rsquo;h\u00f4tel de l&rsquo;Amiti\u00e9 a abrit\u00e9 le jeudi 03 novembre 2022, la c\u00e9r\u00e9monie officielle de lancement du projet \u00ab She Leads \u00bb. Cette rencontre pr\u00e9sid\u00e9e par le ministre de Sport, de la Jeunesse et de la Construction citoyenne, Moussa Ag ATTAHER vise \u00e0 promouvoir l\u2019autonomisation des femmes.<\/p>\n\n\n\n<p>Le projet \u00ab She Leads \u00bb qui signifie en fran\u00e7ais est financ\u00e9 par le minist\u00e8re des Affaires \u00e9trang\u00e8res du Pays-Bas. Il a comme objectif l\u2019implication des jeunes filles et les femmes dans les prises de d\u00e9cision et soutenir le leadership f\u00e9minin. Le ministre de la Jeunesse s&rsquo;est f\u00e9licit\u00e9 de la mise en place de ce programme important dont la finalit\u00e9 est d\u2019accro\u00eetre significativement l\u2019influence durable des filles et des jeunes femmes sur la prise de d\u00e9cision. Le Programme She Leads Mali sera mis en \u0153uvre par le Consortium Terre des hommes Lausanne, Plan International Mali et le ROAJELF.<\/p>\n\n\n\n<p>Selon le ministre ATTAHER, cette initiative constitue une avanc\u00e9e dans la protection et la promotion de la jeune fille et le d\u00e9veloppement du leadership f\u00e9minin. \u00ab <em>Elle contribuera, \u00e0 c\u00f4t\u00e9 des nombreuses initiatives du gouvernement, aux efforts de sensibilisation et de plaidoyer pour l\u2019am\u00e9lioration accrue des conditions de vie de la jeune femme au Mali. Les droits de la jeune fille sont des droits humains inali\u00e9nables et, pour un Mali juste et prosp\u00e8re, le gouvernement est r\u00e9solument engag\u00e9 \u00e0 les respecter et faire respecter<\/em> \u00bb souligne le ministre des Sports, de la Jeunesse et de la Construction citoyenne. Pour lui, la construction d\u2019un monde meilleur passe n\u00e9cessairement par une participation enti\u00e8re et effective des femmes dans tous les domaines de la vie. Et ajouter qu&rsquo;il ne saurait y avoir de d\u00e9veloppement sans le respect des droits de toutes les composantes de la soci\u00e9t\u00e9. C\u2019est fort de cette vision, et dans une approche globale et plus holistique, que le d\u00e9partement de la Jeunesse a \u00e9labor\u00e9 une Politique nationale de la jeunesse, unique cadre de r\u00e9f\u00e9rence pour toutes les interventions en mati\u00e8re de jeunesse et qui prend en compte, amplement, la dimension genre.<\/p>\n\n\n\n<p><strong>Falaye SISSOKO<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;h\u00f4tel de l&rsquo;Amiti\u00e9 a abrit\u00e9 le jeudi 03 novembre 2022, la c\u00e9r\u00e9monie officielle de lancement du projet \u00ab She Leads<\/p>\n","protected":false},"author":1,"featured_media":4207,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali : Lancement officiel du mouvement she leads pour soutenir le leadership f\u00e9minin - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali : Lancement officiel du mouvement she leads pour soutenir le leadership f\u00e9minin - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;h\u00f4tel de l&rsquo;Amiti\u00e9 a abrit\u00e9 le jeudi 03 novembre 2022, la c\u00e9r\u00e9monie officielle de lancement du projet \u00ab She Leads\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-06T15:58:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/11\/1-She-leads.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/06\\\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/06\\\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali : Lancement officiel du mouvement she leads pour soutenir le leadership f\u00e9minin\",\"datePublished\":\"2022-11-06T15:58:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/06\\\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\\\/\"},\"wordCount\":379,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/06\\\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/1-She-leads.jpg\",\"articleSection\":[\"EDITORIAL\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/06\\\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/06\\\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\\\/\",\"name\":\"Mali : Lancement officiel du mouvement she leads pour soutenir le leadership f\u00e9minin - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/06\\\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/06\\\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/1-She-leads.jpg\",\"datePublished\":\"2022-11-06T15:58:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/06\\\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/06\\\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/06\\\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/1-She-leads.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/1-She-leads.jpg\",\"width\":1000,\"height\":629},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/11\\\/06\\\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali : Lancement officiel du mouvement she leads pour soutenir le leadership f\u00e9minin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali : Lancement officiel du mouvement she leads pour soutenir le leadership f\u00e9minin - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali : Lancement officiel du mouvement she leads pour soutenir le leadership f\u00e9minin - REUSSITE INFO","og_description":"L&rsquo;h\u00f4tel de l&rsquo;Amiti\u00e9 a abrit\u00e9 le jeudi 03 novembre 2022, la c\u00e9r\u00e9monie officielle de lancement du projet \u00ab She Leads","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/","og_site_name":"REUSSITE INFO","article_published_time":"2022-11-06T15:58:28+00:00","og_image":[{"width":1000,"height":629,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/11\/1-She-leads.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali : Lancement officiel du mouvement she leads pour soutenir le leadership f\u00e9minin","datePublished":"2022-11-06T15:58:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/"},"wordCount":379,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/11\/1-She-leads.jpg","articleSection":["EDITORIAL"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/","name":"Mali : Lancement officiel du mouvement she leads pour soutenir le leadership f\u00e9minin - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/11\/1-She-leads.jpg","datePublished":"2022-11-06T15:58:28+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/11\/1-She-leads.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/11\/1-She-leads.jpg","width":1000,"height":629},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/11\/06\/mali-lancement-officiel-du-mouvement-she-leads-pour-soutenir-le-leadership-feminin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali : Lancement officiel du mouvement she leads pour soutenir le leadership f\u00e9minin"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/4206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=4206"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/4206\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/4207"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=4206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=4206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=4206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}