{"id":4044,"date":"2022-09-21T02:22:03","date_gmt":"2022-09-21T02:22:03","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=4044"},"modified":"2022-09-21T02:22:03","modified_gmt":"2022-09-21T02:22:03","slug":"mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/","title":{"rendered":"Mali : Revue du dispositif national de lutte contre le Blanchiment des Capitaux et le Financement du Terrorisme"},"content":{"rendered":"\n<p>Une r\u00e9union d\u2019\u00e9valuation du plan d\u2019action consensuel du dispositif national de lutte contre la Blanchiment des Capitaux et le Financement du Terrorisme (LBC\/FT) du Mali a eu lieu le lundi 12 septembre 2022, en mode hybride. C\u2019\u00e9tait entre les autorit\u00e9s maliennes en charge de la lutte contre le Blanchiment des Capitaux et le Financement du Terrorisme (LBC\/FT), le Groupe Conjoint d\u2019\u00e9valuateurs constitu\u00e9 de pays membres du Groupe d\u2019Action Financi\u00e8re (GAFI), le Secr\u00e9tariat du GAFI et celui du Groupe Intergouvernemental d\u2019Action contre le Blanchiment d\u2019Argent en Afrique de l\u2019Ouest (GIABA).<\/p>\n\n\n\n<p>Le ministre de l\u2019Economie et des Finances, Alouss\u00e9ni SANOU, accompagn\u00e9 par le ministre de la Justice et des Droits de l&rsquo;Homme, Garde des Sceaux, Mahamadou KASSOGUE et le ministre de la S\u00e9curit\u00e9 et de la Protection Civile le G\u00e9n\u00e9ral de Brigade Daoud Aly MOHAMMEDINE ont pris part aux discussions, par visio-conf\u00e9rence avec les membres du Groupe conjoint Afrique\/Moyen-Orient du GAFI (r\u00e9unis \u00e0 Livingston en Zambie pour la circonstance) en pr\u00e9sence d\u2019une d\u00e9l\u00e9gation malienne conduite par le charg\u00e9 de mission au cabinet du ministre de l\u2019Economie et des Finances, S\u00e9kou Amadou N\u2019DOURE. Cette d\u00e9l\u00e9gation comprenant \u00e9galement le Pr\u00e9sident de la Cellule Nationale de Traitement des Informations Financi\u00e8res du Mali (CENTIF-Mali), Idrissa Mahamar HAIDARA, des cadres des d\u00e9partements en charge de la Justice et de la S\u00e9curit\u00e9 ainsi que le repr\u00e9sentant de la Banque Centrale des Etats de l\u2019Afrique de l\u2019Ouest (BCEAO).<\/p>\n\n\n\n<p>D\u2019autres repr\u00e9sentants de la CENTIF-Mali, de la Commission bancaire de l\u2019UEMOA et des structures membres de la Commission Nationale de Coordination des Activit\u00e9s de lutte contre le Blanchiment des Capitaux et le Financement du Terrorisme (CONACA-LBC\/FT) ont particip\u00e9 par visioconf\u00e9rence aux discussions.<\/p>\n\n\n\n<p>Le ministre de l\u2019\u00c9conomie et des Finances a fait remarquer les efforts importants consentis par l\u2019Etat du Mali dans le cadre de la mise en \u0153uvre du plan d\u2019actions de l\u2019ICRG malgr\u00e9 les contraintes majeures caus\u00e9es par l\u2019embargo inflig\u00e9 par le CEDEAO et le contexte s\u00e9curitaire. Le plan d\u2019action, qui vise l\u2019att\u00e9nuation des insuffisances du dispositif national LBC\/FT, compte vingt-sept (27) mesures parmi lesquelles trois ont \u00e9t\u00e9 totalement mises en \u0153uvre et le reste est en cours de r\u00e9alisation conform\u00e9ment au calendrier d\u2019ex\u00e9cution.<\/p>\n\n\n\n<p>Les plus hautes autorit\u00e9s ont pris l\u2019engagement de tout mettre en \u0153uvre dans la lutte contre la Blanchiment des Capitaux et le Financement du Terrorisme \u00e0 travers la mobilisation des trois ministres, le d\u00e9placement de la d\u00e9l\u00e9gation malienne pour la r\u00e9union de \u00ab face \u00e0 face \u00bb en Zambie ainsi que les progr\u00e8s r\u00e9alis\u00e9s dans la mise en \u0153uvre du plan d\u2019action ont \u00e9t\u00e9 salu\u00e9s par les experts du Comit\u00e9 mixte Afrique\/Moyen-Orient du GAFI. Les r\u00e9sultats appr\u00e9ciables obtenus par le Mali augurent de bonnes perspectives en vue d\u2019une sortie du Mali de la \u00ab surveillance accrue \u00bb \u00e0 travers un dispositif national de LBC\/FT r\u00e9pondant aux normes de conformit\u00e9 technique et d\u2019efficacit\u00e9.<\/p>\n\n\n\n<p>A noter que le Groupe d\u2019action financi\u00e8re (GAFI) est un organisme intergouvernemental cr\u00e9\u00e9 en 1989 par les Ministres de ses \u00c9tats membres.&nbsp; Les objectifs du GAFI sont l\u2019\u00e9laboration des normes et la promotion de l\u2019efficace application de mesures l\u00e9gislatives, r\u00e9glementaires et op\u00e9rationnelles en mati\u00e8re de lutte contre le blanchiment de capitaux, le financement du terrorisme et les autres menaces li\u00e9es pour l\u2019int\u00e9grit\u00e9 du syst\u00e8me financier international.&nbsp; Le Groupe d\u2019action financi\u00e8re est donc un organisme d\u2019\u00e9laboration des politiques qui s\u2019efforce de susciter la volont\u00e9 politique n\u00e9cessaire pour effectuer les r\u00e9formes l\u00e9gislatives et r\u00e9glementaires dans ces domaines.<\/p>\n\n\n\n<p><strong>Charles MESSE<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-gabi-1-1024x683.jpg\" alt=\"\" class=\"wp-image-4046\" srcset=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-gabi-1-1024x683.jpg 1024w, https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-gabi-1-300x200.jpg 300w, https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-gabi-1-768x512.jpg 768w, https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-gabi-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Une r\u00e9union d\u2019\u00e9valuation du plan d\u2019action consensuel du dispositif national de lutte contre la Blanchiment des Capitaux et le Financement<\/p>\n","protected":false},"author":1,"featured_media":4045,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali : Revue du dispositif national de lutte contre le Blanchiment des Capitaux et le Financement du Terrorisme - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali : Revue du dispositif national de lutte contre le Blanchiment des Capitaux et le Financement du Terrorisme - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"Une r\u00e9union d\u2019\u00e9valuation du plan d\u2019action consensuel du dispositif national de lutte contre la Blanchiment des Capitaux et le Financement\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-21T02:22:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Gabi-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali : Revue du dispositif national de lutte contre le Blanchiment des Capitaux et le Financement du Terrorisme\",\"datePublished\":\"2022-09-21T02:22:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\\\/\"},\"wordCount\":668,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/1-Gabi-2.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\\\/\",\"name\":\"Mali : Revue du dispositif national de lutte contre le Blanchiment des Capitaux et le Financement du Terrorisme - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/1-Gabi-2.jpg\",\"datePublished\":\"2022-09-21T02:22:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/1-Gabi-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/1-Gabi-2.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali : Revue du dispositif national de lutte contre le Blanchiment des Capitaux et le Financement du Terrorisme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali : Revue du dispositif national de lutte contre le Blanchiment des Capitaux et le Financement du Terrorisme - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali : Revue du dispositif national de lutte contre le Blanchiment des Capitaux et le Financement du Terrorisme - REUSSITE INFO","og_description":"Une r\u00e9union d\u2019\u00e9valuation du plan d\u2019action consensuel du dispositif national de lutte contre la Blanchiment des Capitaux et le Financement","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/","og_site_name":"REUSSITE INFO","article_published_time":"2022-09-21T02:22:03+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Gabi-2.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali : Revue du dispositif national de lutte contre le Blanchiment des Capitaux et le Financement du Terrorisme","datePublished":"2022-09-21T02:22:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/"},"wordCount":668,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Gabi-2.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/","name":"Mali : Revue du dispositif national de lutte contre le Blanchiment des Capitaux et le Financement du Terrorisme - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Gabi-2.jpg","datePublished":"2022-09-21T02:22:03+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Gabi-2.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Gabi-2.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-revue-du-dispositif-national-de-lutte-contre-le-blanchiment-des-capitaux-et-le-financement-du-terrorisme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali : Revue du dispositif national de lutte contre le Blanchiment des Capitaux et le Financement du Terrorisme"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/4044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=4044"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/4044\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/4045"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=4044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=4044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=4044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}