{"id":4040,"date":"2022-09-21T02:17:01","date_gmt":"2022-09-21T02:17:01","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=4040"},"modified":"2022-09-21T02:17:01","modified_gmt":"2022-09-21T02:17:01","slug":"mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/","title":{"rendered":"Mali : Inauguration du nouveau si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes"},"content":{"rendered":"\n<p>L\u2019inauguration du nouveau si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes a \u00e9t\u00e9 fait lundi 19 septembre 2022 \u00e0 Samako II (commune du Mand\u00e9) par le Colonel Assimi GOITA, Pr\u00e9sident de la Transition, Chef de l\u2019Etat. C\u2019\u00e9tait en pr\u00e9sence des Pr\u00e9sidents des Institutions de la R\u00e9publique, des membres du Gouvernement, des repr\u00e9sentants des repr\u00e9sentations diplomatiques et consulaires accr\u00e9dit\u00e9es au Mali , des Autorit\u00e9s Traditionnelles, Religieuses et Coutumi\u00e8res, de plusieurs responsables de la haute administration et du secteur priv\u00e9.<\/p>\n\n\n\n<p>Le Pr\u00e9sident de la Transition, Chef de l\u2019Etat, le Colonel Assimi GOITA a d\u2019abord d\u00e9cor\u00e9 des agents des douanes en reconnaissance de leur m\u00e9rite, avant de proc\u00e9der \u00e0 la coupure symbolique du ruban. Il a \u00e9galement visit\u00e9 l\u2019int\u00e9rieur du nouveau b\u00e2timent qui abrite d\u00e9sormais la Direction G\u00e9n\u00e9rale des Douanes.<\/p>\n\n\n\n<p>La construction d\u2019une nouvelle direction g\u00e9n\u00e9rale des douanes t\u00e9moigne de la volont\u00e9 des plus Hautes Autorit\u00e9s d\u2019accompagner ce service dans l\u2019exercice de ses missions strat\u00e9giques notamment la mobilisation des ressources, la lutte contre la fraude et la criminalit\u00e9 transfrontali\u00e8re, la protection des populations, des animaux et des v\u00e9g\u00e9taux contre la circulation illicite des substances nocives. Elle met les services des douanes dans les conditions optimales de travail en vue d\u2019am\u00e9liorer ses performances et d\u2019assurer l\u2019atteinte des objectifs fix\u00e9s.<\/p>\n\n\n\n<p>\u00ab C<em>\u2019est la premi\u00e8re fois, depuis 1960, que l\u2019Administration des Douanes du Mali disposera d\u2019une infrastructure construite sp\u00e9cialement pour abriter les services centraux de la Direction G\u00e9n\u00e9rale des Douanes. C\u2019est aussi la premi\u00e8re fois dans l\u2019Histoire de notre pays qu\u2019un service central de l\u2019Etat se trouvera log\u00e9 en dehors des limites territoriales du District de Bamako<\/em> \u00bb a d\u00e9clar\u00e9 le Ministre de l\u2019Economie et des Finances Alouss\u00e9ni SANOU dans son allocution lors de ladite c\u00e9r\u00e9monie.<\/p>\n\n\n\n<p>L\u2019ach\u00e8vement des travaux a connu un coup d\u2019acc\u00e9l\u00e9rateur \u00e0 la suite de la visite du ministre de l\u2019\u00c9conomie et des Finances sur le chantier, le jeudi 17 mars dernier. Ce joyau est b\u00e2ti sur une superficie de trente (30) hectares. Il abrite le si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes, le centre de formation des Douanes ainsi que les futures infrastructures du centre d\u2019expertise technique, du centre de formation militaire des agents des Douanes, des logements d\u2019astreinte pour le personnel en service et un parking de trois cents (300) places. \u00ab&nbsp;<em>L\u2019infrastructure a co\u00fbt\u00e9 4.531.198.197 F CFA enti\u00e8rement financ\u00e9s par le Budget National.&nbsp; Sa r\u00e9alisation a \u00e9t\u00e9 confi\u00e9e aux entreprises COMATEXIBAT SA et EDAK au Cabinet Architecture Style et Technique (ASTEC), au bureau ALPAGES-Mali pour le contr\u00f4le des travaux et \u00e0 AGETIER-Mali pour la Ma\u00eetrise d\u2019ouvrage d\u00e9l\u00e9gu\u00e9 <\/em>\u00bb a expliqu\u00e9 le ministre SANOU.<\/p>\n\n\n\n<p>Lors de la c\u00e9r\u00e9monie, le ministre de l\u2019\u00c9conomie et des Finances, avec la permission du Chef de l\u2019Etat, a rendu hommage aux dix-huit (18) agents des douanes, tout grade confondu, ayant perdu la vie dans l\u2019exercice de leur fonction sous les balles du terrorisme, de 2011 \u00e0 2022, ainsi qu\u2019aux vingt-cinq (25) autres bless\u00e9s sur la m\u00eame p\u00e9riode. \u00ab <em>La coupure du ruban symbolique restera un moment fort d\u2019\u00e9motion pour tout le personnel de mon d\u00e9partement, mais aussi, un moment de souvenir et de compassion envers nos coll\u00e8gues tomb\u00e9s sur le champ d\u2019honneur dans l\u2019exercice de leur fonction<\/em> \u00bb dira le Ministre.<\/p>\n\n\n\n<p>Le ministre de l\u2019\u00c9conomie et des Finances a remerci\u00e9 le Pr\u00e9sident de la Transition, Chef de l\u2019Etat, aux noms de l\u2019ensemble des Agents du minist\u00e8re de l&rsquo;\u00c9conomie et des Finances, \u00e0 son nom propre et plus particuli\u00e8rement aux noms des Agents de la Douanes pour toutes les marques de reconnaissance faites \u00e0 leurs endroits en si peu de temps.<\/p>\n\n\n\n<p>La poursuite de la mise en \u0153uvre des r\u00e9formes organisationnelles, la modernisation des proc\u00e9dures et la construction prochaine des locaux du Centre d\u2019Expertise Technique, qui contribueront fortement \u00e0 l\u2019atteinte et au d\u00e9passement des objectifs assign\u00e9s, sont les perspectives imm\u00e9diates auxquelles le ministre de l&rsquo;\u00c9conomie et des Finances engage la Direction g\u00e9n\u00e9rale des douanes et l\u2019ensemble du personnel \u00e0 redoubler d\u2019efforts, \u00e0 plus de rigueur et d\u2019engagement dans le travail malgr\u00e9 le contexte international et sous r\u00e9gional difficile. Il les invite \u00e9galement \u00e0 prendre grand soin des nouveaux locaux.&nbsp;<\/p>\n\n\n\n<p>Enfin, le Ministre Alouss\u00e9ni SANOU a assur\u00e9 les agents des Douanes de l\u2019appui et de l\u2019accompagnement constant du d\u00e9partement et des plus Hautes Autorit\u00e9s.<\/p>\n\n\n\n<p><strong>Charles MESSE<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Douane-3oui.jpg\" alt=\"\" class=\"wp-image-4042\" srcset=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Douane-3oui.jpg 1024w, https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Douane-3oui-300x200.jpg 300w, https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Douane-3oui-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019inauguration du nouveau si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes a \u00e9t\u00e9 fait lundi 19 septembre 2022 \u00e0 Samako II<\/p>\n","protected":false},"author":1,"featured_media":4041,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali : Inauguration du nouveau si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali : Inauguration du nouveau si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"L\u2019inauguration du nouveau si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes a \u00e9t\u00e9 fait lundi 19 septembre 2022 \u00e0 Samako II\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-21T02:17:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Douane1oui.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"688\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali : Inauguration du nouveau si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes\",\"datePublished\":\"2022-09-21T02:17:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\\\/\"},\"wordCount\":810,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/1-Douane1oui.jpg\",\"articleSection\":[\"EDITORIAL\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\\\/\",\"name\":\"Mali : Inauguration du nouveau si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/1-Douane1oui.jpg\",\"datePublished\":\"2022-09-21T02:17:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/1-Douane1oui.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/1-Douane1oui.jpg\",\"width\":1000,\"height\":688},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/09\\\/21\\\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali : Inauguration du nouveau si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali : Inauguration du nouveau si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali : Inauguration du nouveau si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes - REUSSITE INFO","og_description":"L\u2019inauguration du nouveau si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes a \u00e9t\u00e9 fait lundi 19 septembre 2022 \u00e0 Samako II","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/","og_site_name":"REUSSITE INFO","article_published_time":"2022-09-21T02:17:01+00:00","og_image":[{"width":1000,"height":688,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Douane1oui.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali : Inauguration du nouveau si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes","datePublished":"2022-09-21T02:17:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/"},"wordCount":810,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Douane1oui.jpg","articleSection":["EDITORIAL"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/","name":"Mali : Inauguration du nouveau si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Douane1oui.jpg","datePublished":"2022-09-21T02:17:01+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Douane1oui.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/09\/1-Douane1oui.jpg","width":1000,"height":688},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/09\/21\/mali-inauguration-du-nouveau-siege-de-la-direction-generale-des-douanes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali : Inauguration du nouveau si\u00e8ge de la direction g\u00e9n\u00e9rale des Douanes"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/4040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=4040"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/4040\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/4041"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=4040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=4040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=4040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}