{"id":3846,"date":"2022-08-15T04:35:04","date_gmt":"2022-08-15T04:35:04","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=3846"},"modified":"2022-08-15T04:35:04","modified_gmt":"2022-08-15T04:35:04","slug":"mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/","title":{"rendered":"Mali : Conf\u00e9rence de presse conjointe du ministre du commerce et celui de l`Economie sur la vie ch\u00e8re"},"content":{"rendered":"\n<p>Le ministre en charge de l\u2019Industrie et du Commerce, Mahmoud Ould MOHAMED et son homologue de l\u2019Economie et des Finances, Alousseni SANOU \u00e9taient le jeudi 11 ao\u00fbt 2022, face aux journalistes de la presse nationale pour aborder des sujets concernant l\u2019inflation et l\u2019impact budg\u00e9taire des mesures d\u2019att\u00e9nuation mises en place par le gouvernement de Transition.<\/p>\n\n\n\n<p>Cette conf\u00e9rence de presse s\u2019inscrit en droite ligne du conseil des ministres extraordinaire du dimanche 7 ao\u00fbt dernier, et se veut un cadre d\u2019apaisement de la tension des consommateurs confront\u00e9s \u00e0 la hausse anormale et injustifi\u00e9e des prix des produits de premi\u00e8re n\u00e9cessit\u00e9.<\/p>\n\n\n\n<p>A l\u2019entame de ses propos, le ministre en charge de l\u2019Industrie et du Commerce, Mahmoud Ould MOHAMED a indiqu\u00e9 que les augmentations de prix constat\u00e9es ne sont ni sp\u00e9cifiques ni particuli\u00e8res au Mali, mais imputables \u00e0 la crise ukrainienne et aux sanctions ill\u00e9gales et injustes prises par la Communaut\u00e9 Economique des \u00c9tats de l\u2019Afrique de l\u2019Ouest (CEDEAO) et l\u2019Union Economique et Mon\u00e9taire ouest-africaine (UEMOA) contre notre pays, d\u00e9j\u00e0 confront\u00e9 par la double crise s\u00e9curitaire et sanitaire li\u00e9e \u00e0 la Covid-19.<\/p>\n\n\n\n<p>Pour le ministre de l&rsquo;\u00c9conomie et des Finances, Alousseni SANOU, cette crise institutionnelle a fortement perturb\u00e9 les relations avec les partenaires techniques et financiers. Raison pour laquelle les appuis budg\u00e9taires g\u00e9n\u00e9raux se font rares. \u00ab&nbsp;<em>Face \u00e0 cette situation, le gouvernement a adopt\u00e9 une s\u00e9rie de mesures tendant \u00e0 assurer l\u2019approvisionnement correct du pays en produits de premi\u00e8re n\u00e9cessit\u00e9 \u00e0 un prix maitris\u00e9 et \u00e0 maintenir le pouvoir d\u2019achat des m\u00e9nages<\/em>&nbsp;\u00bb a indiqu\u00e9 le ministre Alousseni SANOU.<\/p>\n\n\n\n<p>Malgr\u00e9 toutes ces mesures pour \u00e9viter l&rsquo;augmentation des prix, force est de constater que la flamb\u00e9e des prix demeure. C\u2019est pourquoi le ministre en charge du commerce hausse le ton&nbsp;: \u00ab&nbsp;<em>Le gouvernement condamne fermement cette hausse anormale et injustifi\u00e9e des prix des produits de premi\u00e8re n\u00e9cessit\u00e9. Pour faire face \u00e0 cette situation, le gouvernement a d\u00e9cid\u00e9 de r\u00e9affecter les quantit\u00e9s subventionn\u00e9es non ex\u00e9cut\u00e9es au cordon douanier repr\u00e9sentant au moins un mois et demi de consommation \u00e0 d&rsquo;autres op\u00e9rateurs \u00e9conomiques<\/em> \u00bb a martel\u00e9 M. Mahmoud Ould MOHAMED, avant d\u2019expliquer que cette r\u00e9affectation, en ce qui concerne le sucre, pourra \u00eatre accompagn\u00e9e \u00e9ventuellement par l&rsquo;allocation d&rsquo;une quantit\u00e9 suppl\u00e9mentaire correspondant \u00e0 environ un mois de consommation ; de proc\u00e9der \u00e0 la v\u00e9rification de l&rsquo;affichage obligatoire des prix des diff\u00e9rents produits dans les lieux de commerce ; de contr\u00f4ler le respect des conventions et r\u00e8glements en vigueur.<\/p>\n\n\n\n<p>Plusieurs journalistes ont pos\u00e9 la question de savoir ce qui peut justifier le non-respect des prix plafond convenus, et quelles sanctions seront r\u00e9serv\u00e9es aux r\u00e9cidivistes&nbsp;? Les deux ministres ont \u00e9t\u00e9 fermes sur leur position, celle d\u2019inviter les consommateurs \u00e0 d\u00e9noncer syst\u00e9matiquement les cas de violation des prix des produits subventionn\u00e9s. \u00c0 cet effet, le minist\u00e8re du Commerce a mis en place des num\u00e9ros verts notamment les 36020 et 36080, pour la d\u00e9nonciation des abus des commer\u00e7ants v\u00e9reux. \u00ab&nbsp;<em>Nous n&rsquo;accepterons pas d\u00e9sordres sur le march\u00e9. Nous allons agir en renfor\u00e7ant la fr\u00e9quence des contr\u00f4les et en augmentant la taille des brigades de contr\u00f4le des prix en y adjoignant des \u00e9l\u00e9ments des Forces de S\u00e9curit\u00e9 afin d&rsquo;intensifier le contr\u00f4le \u00e0 tous les niveaux de la chaine de distribution<\/em>&nbsp;\u00bb a promis le ministre du commerce.<\/p>\n\n\n\n<p>A noter que le gouvernement de la Transition a mis en place un comit\u00e9 interminist\u00e9riel de suivi de la mise en \u0153uvre des mesures prises, et a appel\u00e9 la population \u00e0 rester sereine dans l\u2019optique que toutes les dispositions seront prises pour contenir cette hausse des prix des produits de premi\u00e8re n\u00e9cessit\u00e9.<\/p>\n\n\n\n<p><strong>Charles MESSE<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre en charge de l\u2019Industrie et du Commerce, Mahmoud Ould MOHAMED et son homologue de l\u2019Economie et des Finances,<\/p>\n","protected":false},"author":1,"featured_media":3847,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali : Conf\u00e9rence de presse conjointe du ministre du commerce et celui de l`Economie sur la vie ch\u00e8re - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali : Conf\u00e9rence de presse conjointe du ministre du commerce et celui de l`Economie sur la vie ch\u00e8re - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"Le ministre en charge de l\u2019Industrie et du Commerce, Mahmoud Ould MOHAMED et son homologue de l\u2019Economie et des Finances,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-15T04:35:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/08\/Ministre-MEF-et-MCCoui-vf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/08\\\/15\\\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/08\\\/15\\\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali : Conf\u00e9rence de presse conjointe du ministre du commerce et celui de l`Economie sur la vie ch\u00e8re\",\"datePublished\":\"2022-08-15T04:35:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/08\\\/15\\\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\\\/\"},\"wordCount\":679,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/08\\\/15\\\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Ministre-MEF-et-MCCoui-vf.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/08\\\/15\\\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/08\\\/15\\\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\\\/\",\"name\":\"Mali : Conf\u00e9rence de presse conjointe du ministre du commerce et celui de l`Economie sur la vie ch\u00e8re - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/08\\\/15\\\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/08\\\/15\\\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Ministre-MEF-et-MCCoui-vf.jpg\",\"datePublished\":\"2022-08-15T04:35:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/08\\\/15\\\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/08\\\/15\\\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/08\\\/15\\\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Ministre-MEF-et-MCCoui-vf.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Ministre-MEF-et-MCCoui-vf.jpg\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/08\\\/15\\\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali : Conf\u00e9rence de presse conjointe du ministre du commerce et celui de l`Economie sur la vie ch\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali : Conf\u00e9rence de presse conjointe du ministre du commerce et celui de l`Economie sur la vie ch\u00e8re - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali : Conf\u00e9rence de presse conjointe du ministre du commerce et celui de l`Economie sur la vie ch\u00e8re - REUSSITE INFO","og_description":"Le ministre en charge de l\u2019Industrie et du Commerce, Mahmoud Ould MOHAMED et son homologue de l\u2019Economie et des Finances,","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/","og_site_name":"REUSSITE INFO","article_published_time":"2022-08-15T04:35:04+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/08\/Ministre-MEF-et-MCCoui-vf.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali : Conf\u00e9rence de presse conjointe du ministre du commerce et celui de l`Economie sur la vie ch\u00e8re","datePublished":"2022-08-15T04:35:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/"},"wordCount":679,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/08\/Ministre-MEF-et-MCCoui-vf.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/","name":"Mali : Conf\u00e9rence de presse conjointe du ministre du commerce et celui de l`Economie sur la vie ch\u00e8re - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/08\/Ministre-MEF-et-MCCoui-vf.jpg","datePublished":"2022-08-15T04:35:04+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/08\/Ministre-MEF-et-MCCoui-vf.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/08\/Ministre-MEF-et-MCCoui-vf.jpg","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/08\/15\/mali-conference-de-presse-conjointe-du-ministre-du-commerce-et-celui-de-leconomie-sur-la-vie-chere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali : Conf\u00e9rence de presse conjointe du ministre du commerce et celui de l`Economie sur la vie ch\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/3846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=3846"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/3846\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/3847"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=3846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=3846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=3846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}