{"id":3708,"date":"2022-07-18T20:19:15","date_gmt":"2022-07-18T20:19:15","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=3708"},"modified":"2022-07-18T20:19:15","modified_gmt":"2022-07-18T20:19:15","slug":"mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/","title":{"rendered":"Mali : L&rsquo;\u00e9tau se resserre autour de ALASSANE DRAMANE OUATTARA dans l\u2019affaire des 49 militaires ivoiriens arr\u00eat\u00e9s"},"content":{"rendered":"\n<p>Les enqu\u00eates dans l&rsquo;affaire des 49 militaires arr\u00eat\u00e9s au Mali mettent \u00e0 nu les manigances du pr\u00e9sident ivoirien, Alassane Dramane Ouattara. Les enqu\u00eates concernant les soldats ivoiriens arr\u00eat\u00e9s au Mali se pr\u00e9cisent. Selon le gouvernement du Mali, gr\u00e2ce au professionnalisme des Forces de D\u00e9fense et de S\u00e9curit\u00e9 maliennes, il a \u00e9t\u00e9 \u00e9tabli que les 49 militaires ivoiriens se trouvaient ill\u00e9galement sur le territoire national du Mali.<\/p>\n\n\n\n<p>Selon le ministre de l&rsquo;Administration territoriale et de la D\u00e9centralisation, Porte-parole du gouvernement, <a>le col Abdoulaye MAIGA<\/a>, ces militaires dont une trentaine des forces sp\u00e9ciales, \u00e9taient en possession d&rsquo;armes et de munitions de guerre, sans ordre de mission ni autorisation. \u00ab&nbsp;<em>La profession r\u00e9elle des militaires \u00e9tait pour la plupart dissimul\u00e9e. Sur la majorit\u00e9 des passeports des militaires interpell\u00e9s, les professions inscrites \u00e9taient les suivantes \u00e9tudiants, chauffeurs, ma\u00e7ons, m\u00e9caniciens, vendeuses, \u00e9lectriciens, vigiles, peintres<\/em> \u00bb a pr\u00e9cis\u00e9 le col Abdoulaye MAIGA. Pour en savoir davantage, des responsables des Forces de D\u00e9fense et de S\u00e9curit\u00e9 maliennes ont contact\u00e9 imm\u00e9diatement leurs homologues ivoiriens. Ces derniers ont affirm\u00e9 qu&rsquo;ils ignoraient la pr\u00e9sence des militaires ivoiriens interpell\u00e9s au Mali. En outre, interrog\u00e9e par les autorit\u00e9s maliennes, la MINUSMA a indiqu\u00e9 qu&rsquo;elle n&rsquo;avait pas de rotation pr\u00e9vue, le 10 Juillet 2022. Apr\u00e8s toutes ces analyses, le Mali consid\u00e8re ces militaires comme des \u00ab mercenaires \u00bb.<\/p>\n\n\n\n<p>La C\u00f4te d&rsquo;Ivoire a affirm\u00e9 que ces militaires font partie des contingents de la MINUSMA. Les d\u00e9clarations du porte-parole adjoint de l&rsquo;ONU, Farhan HAQ a d\u00e9menti cette affirmation. Selon ses explications, les militaires interpell\u00e9s ne faisaient pas formellement partie de la MINUSMA, mais qu&rsquo;ils \u00e9taient des \u00c9l\u00e9ments nationaux de Soutien (NSE), c&rsquo;est-\u00e0-dire des effectifs d\u00e9ploy\u00e9s par les pays contributeurs de troupes en soutien \u00e0 leurs contingents. Ensuite, il a inform\u00e9 que c&rsquo;est une pratique commune dans les missions de maintien de la paix. En plus de ceux-ci, s&rsquo;ajoute la d\u00e9claration du secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;ONU, Antonio Guterres. \u00ab Les militaires ivoiriens arr\u00eat\u00e9s ne font pas partie du contingent de l&rsquo;ONU et de la NSE et la C\u00f4te d&rsquo;Ivoire n&rsquo;a pas dit la v\u00e9rit\u00e9. L&rsquo;ONU ne comprend pas leur pr\u00e9sence au Mali \u00bb d\u00e9nonce le secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;ONU.<\/p>\n\n\n\n<p><strong>Joseph SISSOKO<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les enqu\u00eates dans l&rsquo;affaire des 49 militaires arr\u00eat\u00e9s au Mali mettent \u00e0 nu les manigances du pr\u00e9sident ivoirien, Alassane Dramane<\/p>\n","protected":false},"author":1,"featured_media":3709,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali : L&#039;\u00e9tau se resserre autour de ALASSANE DRAMANE OUATTARA dans l\u2019affaire des 49 militaires ivoiriens arr\u00eat\u00e9s - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali : L&#039;\u00e9tau se resserre autour de ALASSANE DRAMANE OUATTARA dans l\u2019affaire des 49 militaires ivoiriens arr\u00eat\u00e9s - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"Les enqu\u00eates dans l&rsquo;affaire des 49 militaires arr\u00eat\u00e9s au Mali mettent \u00e0 nu les manigances du pr\u00e9sident ivoirien, Alassane Dramane\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-18T20:19:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/07\/alassane-dramane-ouattara-president-ivoirien.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/07\\\/18\\\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/07\\\/18\\\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali : L&rsquo;\u00e9tau se resserre autour de ALASSANE DRAMANE OUATTARA dans l\u2019affaire des 49 militaires ivoiriens arr\u00eat\u00e9s\",\"datePublished\":\"2022-07-18T20:19:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/07\\\/18\\\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\\\/\"},\"wordCount\":432,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/07\\\/18\\\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/alassane-dramane-ouattara-president-ivoirien.webp\",\"articleSection\":[\"EDITORIAL\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/07\\\/18\\\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/07\\\/18\\\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\\\/\",\"name\":\"Mali : L'\u00e9tau se resserre autour de ALASSANE DRAMANE OUATTARA dans l\u2019affaire des 49 militaires ivoiriens arr\u00eat\u00e9s - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/07\\\/18\\\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/07\\\/18\\\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/alassane-dramane-ouattara-president-ivoirien.webp\",\"datePublished\":\"2022-07-18T20:19:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/07\\\/18\\\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/07\\\/18\\\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/07\\\/18\\\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/alassane-dramane-ouattara-president-ivoirien.webp\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/alassane-dramane-ouattara-president-ivoirien.webp\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/07\\\/18\\\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali : L&rsquo;\u00e9tau se resserre autour de ALASSANE DRAMANE OUATTARA dans l\u2019affaire des 49 militaires ivoiriens arr\u00eat\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali : L'\u00e9tau se resserre autour de ALASSANE DRAMANE OUATTARA dans l\u2019affaire des 49 militaires ivoiriens arr\u00eat\u00e9s - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali : L'\u00e9tau se resserre autour de ALASSANE DRAMANE OUATTARA dans l\u2019affaire des 49 militaires ivoiriens arr\u00eat\u00e9s - REUSSITE INFO","og_description":"Les enqu\u00eates dans l&rsquo;affaire des 49 militaires arr\u00eat\u00e9s au Mali mettent \u00e0 nu les manigances du pr\u00e9sident ivoirien, Alassane Dramane","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/","og_site_name":"REUSSITE INFO","article_published_time":"2022-07-18T20:19:15+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/07\/alassane-dramane-ouattara-president-ivoirien.webp","type":"image\/webp"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali : L&rsquo;\u00e9tau se resserre autour de ALASSANE DRAMANE OUATTARA dans l\u2019affaire des 49 militaires ivoiriens arr\u00eat\u00e9s","datePublished":"2022-07-18T20:19:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/"},"wordCount":432,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/07\/alassane-dramane-ouattara-president-ivoirien.webp","articleSection":["EDITORIAL"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/","name":"Mali : L'\u00e9tau se resserre autour de ALASSANE DRAMANE OUATTARA dans l\u2019affaire des 49 militaires ivoiriens arr\u00eat\u00e9s - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/07\/alassane-dramane-ouattara-president-ivoirien.webp","datePublished":"2022-07-18T20:19:15+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/07\/alassane-dramane-ouattara-president-ivoirien.webp","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/07\/alassane-dramane-ouattara-president-ivoirien.webp","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/07\/18\/mali-letau-se-resserre-autour-de-alassane-dramane-ouattara-dans-laffaire-des-49-militaires-ivoiriens-arretes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali : L&rsquo;\u00e9tau se resserre autour de ALASSANE DRAMANE OUATTARA dans l\u2019affaire des 49 militaires ivoiriens arr\u00eat\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/3708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=3708"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/3708\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/3709"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=3708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=3708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=3708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}