{"id":3550,"date":"2022-05-21T20:38:01","date_gmt":"2022-05-21T20:38:01","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=3550"},"modified":"2022-05-21T20:38:01","modified_gmt":"2022-05-21T20:38:01","slug":"mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/","title":{"rendered":"Mali : Le manque de salles dans les universit\u00e9s, pousse les \u00e9tudiants \u00e0 interpeller le gouvernement"},"content":{"rendered":"\n<p>Les \u00e9tudiants de la Facult\u00e9 des Lettres, des Langues et des Sciences du Langage ( FLSL ) ont manifest\u00e9 dans l&rsquo;enceinte de la cit\u00e9 universitaire de kabala pour d\u00e9noncer l&rsquo;insuffisance des salles. C&rsquo;\u00e9tait ce lundi 16 mai 2022.&nbsp;<\/p>\n\n\n\n<p>Les universit\u00e9s publiques du Mali sont confront\u00e9es \u00e0 plusieurs probl\u00e8mes, notamment l&rsquo;insuffisance des salles, les gr\u00e8ves intempestives. Face \u00e0 cette situation, les \u00e9tudiants de la Facult\u00e9 des Lettres, des Langues et des Sciences du Langage ( FLSL ) ont montr\u00e9 leur indignation \u00e0 travers une manifestation grandiose. A la suite de cette mobilisation, ils ont d\u00e9cr\u00e9t\u00e9 une gr\u00e8ve de 48h pour informer les plus hautes autorit\u00e9s du pays y compris l&rsquo;opinion nationale et internationale sur la probl\u00e9matique des salles de classe dans les universit\u00e9s. En effet, le comit\u00e9 de l&rsquo;Association des \u00c9l\u00e8ves et \u00c9tudiants de la FLSL a indiqu\u00e9 que le nombre des nouveaux bacheliers inscrits cette ann\u00e9e s&rsquo;\u00e9l\u00e8ve \u00e0 plus de 5000 personnes sans compter les anciens avec une disponibilit\u00e9 des salles de classes pour mille personnes. Cette statistique prouve que les \u00e9tudiants sont confront\u00e9s \u00e0 des \u00e9normes difficult\u00e9s en cette ann\u00e9e scolaire 2021-2022.&nbsp;Selon le t\u00e9moignage d\u2019un \u00e9tudiant de ladite facult\u00e9, les \u00e9tudiants des d\u00e9partements Linguistique et Arabe n&rsquo;ont pas des salles de classe. En plus, les bacheliers de 2020 inscrits dans certaines universit\u00e9s publiques ont commenc\u00e9 les cours en 2022 et ceux de 2021 sont encore dans l&rsquo;attente.&nbsp;Selon l&rsquo;AEEM, l&rsquo;augmentation de l&rsquo;effectif des \u00e9tudiants par rapport aux salles de classes n&rsquo;a pas commenc\u00e9 aujourd&rsquo;hui, mais depuis l&rsquo;ouverture de la Cit\u00e9 universitaire de Kabala. Il est important de rappeler que le manque des salles de classe et le fait de faire pendant 2 ans la m\u00eame classe sans redoubler, poussent la plupart des \u00e9tudiants \u00e0 abandonner les \u00e9tudes. \u00ab Quant aux professeurs, il tr\u00e8s difficile pour eux de dispenser les cours comme il le faut \u00bb, mart\u00e8le le comit\u00e9 de l&rsquo;AEEM.<\/p>\n\n\n\n<p><strong>Falaye SISSOKO<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00e9tudiants de la Facult\u00e9 des Lettres, des Langues et des Sciences du Langage ( FLSL ) ont manifest\u00e9 dans<\/p>\n","protected":false},"author":1,"featured_media":3551,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,2],"tags":[],"class_list":["post-3550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecole","category-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali : Le manque de salles dans les universit\u00e9s, pousse les \u00e9tudiants \u00e0 interpeller le gouvernement - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali : Le manque de salles dans les universit\u00e9s, pousse les \u00e9tudiants \u00e0 interpeller le gouvernement - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"Les \u00e9tudiants de la Facult\u00e9 des Lettres, des Langues et des Sciences du Langage ( FLSL ) ont manifest\u00e9 dans\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-21T20:38:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/05\/1-Universiteoui.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"808\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/05\\\/21\\\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/05\\\/21\\\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali : Le manque de salles dans les universit\u00e9s, pousse les \u00e9tudiants \u00e0 interpeller le gouvernement\",\"datePublished\":\"2022-05-21T20:38:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/05\\\/21\\\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\\\/\"},\"wordCount\":353,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/05\\\/21\\\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/1-Universiteoui.jpg\",\"articleSection\":[\"ACTIVITES\",\"EDITORIAL\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/05\\\/21\\\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/05\\\/21\\\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\\\/\",\"name\":\"Mali : Le manque de salles dans les universit\u00e9s, pousse les \u00e9tudiants \u00e0 interpeller le gouvernement - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/05\\\/21\\\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/05\\\/21\\\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/1-Universiteoui.jpg\",\"datePublished\":\"2022-05-21T20:38:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/05\\\/21\\\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/05\\\/21\\\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/05\\\/21\\\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/1-Universiteoui.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/1-Universiteoui.jpg\",\"width\":1080,\"height\":808},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/05\\\/21\\\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali : Le manque de salles dans les universit\u00e9s, pousse les \u00e9tudiants \u00e0 interpeller le gouvernement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali : Le manque de salles dans les universit\u00e9s, pousse les \u00e9tudiants \u00e0 interpeller le gouvernement - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali : Le manque de salles dans les universit\u00e9s, pousse les \u00e9tudiants \u00e0 interpeller le gouvernement - REUSSITE INFO","og_description":"Les \u00e9tudiants de la Facult\u00e9 des Lettres, des Langues et des Sciences du Langage ( FLSL ) ont manifest\u00e9 dans","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/","og_site_name":"REUSSITE INFO","article_published_time":"2022-05-21T20:38:01+00:00","og_image":[{"width":1080,"height":808,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/05\/1-Universiteoui.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali : Le manque de salles dans les universit\u00e9s, pousse les \u00e9tudiants \u00e0 interpeller le gouvernement","datePublished":"2022-05-21T20:38:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/"},"wordCount":353,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/05\/1-Universiteoui.jpg","articleSection":["ACTIVITES","EDITORIAL"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/","name":"Mali : Le manque de salles dans les universit\u00e9s, pousse les \u00e9tudiants \u00e0 interpeller le gouvernement - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/05\/1-Universiteoui.jpg","datePublished":"2022-05-21T20:38:01+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/05\/1-Universiteoui.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/05\/1-Universiteoui.jpg","width":1080,"height":808},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/05\/21\/mali-le-manque-de-salles-dans-les-universites-pousse-les-etudiants-a-interpeller-le-gouvernement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali : Le manque de salles dans les universit\u00e9s, pousse les \u00e9tudiants \u00e0 interpeller le gouvernement"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/3550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=3550"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/3550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/3551"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=3550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=3550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=3550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}