{"id":3445,"date":"2022-04-03T14:41:37","date_gmt":"2022-04-03T14:41:37","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=3445"},"modified":"2022-04-03T14:41:37","modified_gmt":"2022-04-03T14:41:37","slug":"mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/","title":{"rendered":"Mali : Assembl\u00e9e g\u00e9n\u00e9rale extraordinaire pour la sortie de la crise au CNPM"},"content":{"rendered":"\n<p>Le conseil national du Patronat du Mali a tenu une assembl\u00e9e g\u00e9n\u00e9rale extraordinaire pour mettre fin au bic\u00e9phalisme au sein de cette organisation. La c\u00e9r\u00e9monie d&rsquo;ouverture a \u00e9t\u00e9 pr\u00e9sid\u00e9e par le chef de cabinet du minist\u00e8re de l&rsquo;Economie et des Finances, Bourama TOURE. Il avait \u00e0 ses c\u00f4t\u00e9s le pr\u00e9sident de l&rsquo;administration provisoire, Soya GOLFA, de son vice-pr\u00e9sident, Boubacar Hassimi DIALLO et du pr\u00e9sident de la Chambre de Commerce et d&rsquo;Industrie du Mali, Youssouf BATHILY.<\/p>\n\n\n\n<p>Depuis plus de18 mois, le conseil national du Patronat du Mali (CNPM) est secou\u00e9 par une crise de leadership. Le 04 novembre 2022, une administration provisoire compos\u00e9e de 16 membres avec \u00e0 t\u00eate Soya GOLFA, a \u00e9t\u00e9 mise en place. Apr\u00e8s avoir fait des b\u00e9n\u00e9dictions pour le Mali, le pr\u00e9sident de l&rsquo;administration provisoire, Soya GOLFA a remerci\u00e9 Amadou SANKARE et Mamadou Sinsy COULIBALY non seulement pour leur pr\u00e9sence, mais aussi d&rsquo;avoir facilit\u00e9 la tenue de cette session extraordinaire pour la sortie de crise. Il a aussi appel\u00e9 les membres du CNPM \u00e0 l&rsquo;union pour le bonheur du Mali et de l&rsquo;organisation.&nbsp;Cette administration provisoire aura pour mission de rassembler davantage, d&rsquo;assurer la coh\u00e9sion entre les membres du CNPM, d&rsquo;assurer la continuit\u00e9 de l&rsquo;existence m\u00eame du patronat et d&rsquo;organiser une nouvelle \u00e9lection dans un d\u00e9lai de 3 \u00e0 6 mois dans un climat apais\u00e9. \u00ab&nbsp;<em>Pour l&rsquo;organisation d&rsquo;une \u00e9lection cr\u00e9dible et transparente, l&rsquo;administration provisoire se propose de faire la relecture de certains articles de nos textes et de faire organiser les \u00e9lections par une structure ind\u00e9pendante d&rsquo;elle-m\u00eame pour \u00e9viter qu&rsquo;elle ne soit \u00e0 l&rsquo;origine d&rsquo;une nouvelle crise. <\/em>\u00bb a indiqu\u00e9 le vice-pr\u00e9sident, Boubacar Hassimi DIALLO. Pour lui, c&rsquo;est une obligation pour les membres de l&rsquo;administration provisoire reconstitu\u00e9e de r\u00e9unir aujourd&rsquo;hui tous les patrons, pour qu\u2019ils soient les acteurs de la r\u00e9conciliation. Il a profit\u00e9 de cette occasion pour demander \u00e0 Amadou SANKARE et \u00e0 Mamadou Sinsy COULIBALY de retirer toutes les plaintes et les proc\u00e9dures judiciaires. \u00ab&nbsp;<em>Le CNPM pourra ainsi se joindre tr\u00e8s bient\u00f4t, aux autres acteurs \u00e9conomiques nationaux et internationaux, pour aider les autorit\u00e9s de la Transition \u00e0 trouver des r\u00e9ponses appropri\u00e9es dans la r\u00e9solution de cette crise complexe \u00e0 un moment o\u00f9 des sanctions inhumaines, ill\u00e9gitimes et injustifi\u00e9es sont inflig\u00e9es \u00e0 notre pays et \u00e0 notre \u00e9conomie<\/em> \u00bb a conclu le vice-pr\u00e9sident.&nbsp;<\/p>\n\n\n\n<p><strong>Charles MESSE<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le conseil national du Patronat du Mali a tenu une assembl\u00e9e g\u00e9n\u00e9rale extraordinaire pour mettre fin au bic\u00e9phalisme au sein<\/p>\n","protected":false},"author":1,"featured_media":3446,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali : Assembl\u00e9e g\u00e9n\u00e9rale extraordinaire pour la sortie de la crise au CNPM - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali : Assembl\u00e9e g\u00e9n\u00e9rale extraordinaire pour la sortie de la crise au CNPM - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"Le conseil national du Patronat du Mali a tenu une assembl\u00e9e g\u00e9n\u00e9rale extraordinaire pour mettre fin au bic\u00e9phalisme au sein\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-03T14:41:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/04\/CNPMoui.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/04\\\/03\\\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/04\\\/03\\\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali : Assembl\u00e9e g\u00e9n\u00e9rale extraordinaire pour la sortie de la crise au CNPM\",\"datePublished\":\"2022-04-03T14:41:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/04\\\/03\\\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\\\/\"},\"wordCount\":445,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/04\\\/03\\\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/CNPMoui.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/04\\\/03\\\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/04\\\/03\\\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\\\/\",\"name\":\"Mali : Assembl\u00e9e g\u00e9n\u00e9rale extraordinaire pour la sortie de la crise au CNPM - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/04\\\/03\\\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/04\\\/03\\\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/CNPMoui.jpg\",\"datePublished\":\"2022-04-03T14:41:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/04\\\/03\\\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/04\\\/03\\\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/04\\\/03\\\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/CNPMoui.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/CNPMoui.jpg\",\"width\":1000,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/04\\\/03\\\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali : Assembl\u00e9e g\u00e9n\u00e9rale extraordinaire pour la sortie de la crise au CNPM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali : Assembl\u00e9e g\u00e9n\u00e9rale extraordinaire pour la sortie de la crise au CNPM - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali : Assembl\u00e9e g\u00e9n\u00e9rale extraordinaire pour la sortie de la crise au CNPM - REUSSITE INFO","og_description":"Le conseil national du Patronat du Mali a tenu une assembl\u00e9e g\u00e9n\u00e9rale extraordinaire pour mettre fin au bic\u00e9phalisme au sein","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/","og_site_name":"REUSSITE INFO","article_published_time":"2022-04-03T14:41:37+00:00","og_image":[{"width":1000,"height":450,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/04\/CNPMoui.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali : Assembl\u00e9e g\u00e9n\u00e9rale extraordinaire pour la sortie de la crise au CNPM","datePublished":"2022-04-03T14:41:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/"},"wordCount":445,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/04\/CNPMoui.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/","name":"Mali : Assembl\u00e9e g\u00e9n\u00e9rale extraordinaire pour la sortie de la crise au CNPM - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/04\/CNPMoui.jpg","datePublished":"2022-04-03T14:41:37+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/04\/CNPMoui.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/04\/CNPMoui.jpg","width":1000,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/04\/03\/mali-assemblee-generale-extraordinaire-pour-la-sortie-de-la-crise-au-cnpm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali : Assembl\u00e9e g\u00e9n\u00e9rale extraordinaire pour la sortie de la crise au CNPM"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/3445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=3445"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/3445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/3446"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=3445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=3445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=3445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}