{"id":3434,"date":"2022-03-26T19:56:57","date_gmt":"2022-03-26T19:56:57","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=3434"},"modified":"2022-03-26T19:56:57","modified_gmt":"2022-03-26T19:56:57","slug":"mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/","title":{"rendered":"Mali : Le gouvernement rassure la population sur l\u2019approvisionnement des produits de premi\u00e8re n\u00e9cessit\u00e9"},"content":{"rendered":"\n<p>En pr\u00e9lude au mois de ramadan, le directeur g\u00e9n\u00e9ral de Commerce et de Concurrence, Boucadary DOUMBIA a organis\u00e9 un caf\u00e9 presse le vendredi 25 mars 2022, au Grand h\u00f4tel de Bamako. Cet espace d\u2019\u00e9change et de partage avec les journalistes de la presse nationale sur la situation d&rsquo;approvisionnement des produits de premi\u00e8re n\u00e9cessit\u00e9 au Mali a vu la participation d\u2019une centaine d\u2019hommes de media.<\/p>\n\n\n\n<p>Cette rencontre de la direction g\u00e9n\u00e9rale de Commerce et de Concurrence (DGCC) avec la presse a permis aux hommes de media, de comprendre les efforts que l\u2019Etat du Mali est en train de fournir, pour soulager la souffrance des populations. <a>Le directeur DOUMBIA <\/a>a profit\u00e9 de l\u2019occasion pour informer que dans le cadre du plan d&rsquo;urgence de s\u00e9curit\u00e9 alimentaire mis en place par le gouvernement de la transition, les op\u00e9rateurs agro businessmen se sont engag\u00e9s \u00e0 approvisionner le march\u00e9 de plus 5000 t\u00eates des b\u0153ufs et de plus de 200 000 tonnes de riz.<\/p>\n\n\n\n<p>Le chef de la DGCC n\u2019a pas oubli\u00e9 de rappeler le r\u00f4le de l&rsquo;\u00c9tat malien dans le commerce. Selon lui, l\u2019Etat ayant lib\u00e9ralis\u00e9 le secteur du commerce, son r\u00f4le est de cr\u00e9er les conditions d\u2019une bonne transaction en enlevant les barri\u00e8res inutiles afin de faciliter les \u00e9changes commerciaux en faveur des op\u00e9rateurs \u00e9conomiques. Il a \u00e9galement pour r\u00f4le de faire en sorte que les op\u00e9rateurs respectent les textes l\u00e9gislatifs et r\u00e9glementaires r\u00e9gissant le domaine du commerce luttant contre les pratiques frauduleuses. Le directeur DOUMBIA a aussi expliqu\u00e9 les diff\u00e9rentes causes de la flamb\u00e9e des prix sur le march\u00e9. \u00ab <em>Les difficult\u00e9s constat\u00e9es montrent \u00e0 suffisance que la situation est plut\u00f4t exacerb\u00e9e par des facteurs li\u00e9s \u00e0 la crise s\u00e9curitaire et sanitaire. Le gouvernement a voulu cette r\u00e9flexion pour partager les informations sur la chert\u00e9 des denr\u00e9es, avec les hommes de m\u00e9dias pour faire cesser les mauvaises interpr\u00e9tations qui ont tendance \u00e0 diluer les efforts du gouvernement<\/em>&nbsp;\u00bb a soulign\u00e9 Boucadary DOUMBIA.<\/p>\n\n\n\n<p>R\u00e9pondant aux questions des journalistes, le directeur g\u00e9n\u00e9ral de Commerce et de Concurrence a rassur\u00e9 que la rupture de stock des denr\u00e9es alimentaires de premier n\u00e9cessit\u00e9 ne sera pas \u00e0 l\u2019ordre du jour. &nbsp;\u00ab <em>\u00c0 travers le dispositif de surveillance qu&rsquo;on a mis en place, les stocks disponibles aupr\u00e8s des op\u00e9rateurs principaux, le flux des \u00e9vacuations des produits enregistr\u00e9es chaque semaine et le flux des importations de ces denr\u00e9es, on est en mesure de rassurer la population qu&rsquo;il n&rsquo;y aura pas de rupture de stocks. Le mois de ramadan se passera dans les bonnes conditions<\/em> \u00bb a confirm\u00e9 le directeur g\u00e9n\u00e9ral de Commerce et de Concurrence. <strong>Charles MESSE<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En pr\u00e9lude au mois de ramadan, le directeur g\u00e9n\u00e9ral de Commerce et de Concurrence, Boucadary DOUMBIA a organis\u00e9 un caf\u00e9<\/p>\n","protected":false},"author":1,"featured_media":3435,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali : Le gouvernement rassure la population sur l\u2019approvisionnement des produits de premi\u00e8re n\u00e9cessit\u00e9 - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali : Le gouvernement rassure la population sur l\u2019approvisionnement des produits de premi\u00e8re n\u00e9cessit\u00e9 - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"En pr\u00e9lude au mois de ramadan, le directeur g\u00e9n\u00e9ral de Commerce et de Concurrence, Boucadary DOUMBIA a organis\u00e9 un caf\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-26T19:56:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/03\/1-DGCCouivf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/03\\\/26\\\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/03\\\/26\\\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali : Le gouvernement rassure la population sur l\u2019approvisionnement des produits de premi\u00e8re n\u00e9cessit\u00e9\",\"datePublished\":\"2022-03-26T19:56:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/03\\\/26\\\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\\\/\"},\"wordCount\":492,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/03\\\/26\\\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/1-DGCCouivf.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/03\\\/26\\\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/03\\\/26\\\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\\\/\",\"name\":\"Mali : Le gouvernement rassure la population sur l\u2019approvisionnement des produits de premi\u00e8re n\u00e9cessit\u00e9 - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/03\\\/26\\\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/03\\\/26\\\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/1-DGCCouivf.jpg\",\"datePublished\":\"2022-03-26T19:56:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/03\\\/26\\\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/03\\\/26\\\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/03\\\/26\\\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/1-DGCCouivf.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/1-DGCCouivf.jpg\",\"width\":1000,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2022\\\/03\\\/26\\\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali : Le gouvernement rassure la population sur l\u2019approvisionnement des produits de premi\u00e8re n\u00e9cessit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali : Le gouvernement rassure la population sur l\u2019approvisionnement des produits de premi\u00e8re n\u00e9cessit\u00e9 - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali : Le gouvernement rassure la population sur l\u2019approvisionnement des produits de premi\u00e8re n\u00e9cessit\u00e9 - REUSSITE INFO","og_description":"En pr\u00e9lude au mois de ramadan, le directeur g\u00e9n\u00e9ral de Commerce et de Concurrence, Boucadary DOUMBIA a organis\u00e9 un caf\u00e9","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/","og_site_name":"REUSSITE INFO","article_published_time":"2022-03-26T19:56:57+00:00","og_image":[{"width":1000,"height":625,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/03\/1-DGCCouivf.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali : Le gouvernement rassure la population sur l\u2019approvisionnement des produits de premi\u00e8re n\u00e9cessit\u00e9","datePublished":"2022-03-26T19:56:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/"},"wordCount":492,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/03\/1-DGCCouivf.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/","name":"Mali : Le gouvernement rassure la population sur l\u2019approvisionnement des produits de premi\u00e8re n\u00e9cessit\u00e9 - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/03\/1-DGCCouivf.jpg","datePublished":"2022-03-26T19:56:57+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/03\/1-DGCCouivf.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2022\/03\/1-DGCCouivf.jpg","width":1000,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2022\/03\/26\/mali-le-gouvernement-rassure-la-population-sur-lapprovisionnement-des-produits-de-premiere-necessite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali : Le gouvernement rassure la population sur l\u2019approvisionnement des produits de premi\u00e8re n\u00e9cessit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/3434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=3434"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/3434\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/3435"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=3434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=3434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=3434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}