{"id":3179,"date":"2021-12-18T21:30:20","date_gmt":"2021-12-18T21:30:20","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=3179"},"modified":"2021-12-18T21:30:20","modified_gmt":"2021-12-18T21:30:20","slug":"mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/","title":{"rendered":"Mali : Le CNPM et ses partenaires ont c\u00e9l\u00e9br\u00e9 les journ\u00e9es de l\u2019Entreprise Priv\u00e9e"},"content":{"rendered":"\n<p>Le Conseil National du Patronat du Mali (CNPM), en partenariat avec le Secr\u00e9tariat Technique Permanent du Conseil Sup\u00e9rieur du Secteur priv\u00e9 (STP CSP), a organis\u00e9, les 12 et 13 d\u00e9cembre 2021, \u00e0 son si\u00e8ge, la quatri\u00e8me 4\u00e8me \u00e9dition des Journ\u00e9es de l\u2019Entreprise priv\u00e9e (JEP). La c\u00e9r\u00e9monie d\u2019ouverture \u00e9tait pr\u00e9sid\u00e9e sous la pr\u00e9sidence du secr\u00e9taire g\u00e9n\u00e9ral du minist\u00e8re de l\u2019Industrie et du Commerce, Adama Yoro SIDIBE, repr\u00e9sentant le ministre.<\/p>\n\n\n\n<p>Cette 4\u00e8me \u00e9dition des \u2018\u2018Journ\u00e9es de l\u2019Entreprise Priv\u00e9e \u00bb se tient selon le pr\u00e9sident du CNPM, Amadou dit Diadi\u00e9 SANKARE, dans un contexte particulier, plongeant les entreprises priv\u00e9es dans une p\u00e9riode d\u2019impasse. Parmi les secteurs les plus atteints, on peut citer entre autres : l\u2019h\u00f4tellerie, la restauration, le tourisme, la culture, etc. D\u2019o\u00f9 le th\u00e8me de cette 4eme \u00e9dition : \u00ab la r\u00e9silience des entreprises face aux effets de la Covid-19 et \u00e0 la crise sociopolitique au Mali\u00bb.<\/p>\n\n\n\n<p>L\u2019objectif de ces journ\u00e9es, selon le pr\u00e9sident du CNPM, \u00e9tait de r\u00e9unir tous les acteurs pour d\u00e9gager des pistes de relance de l\u2019activit\u00e9 \u00e9conomique affect\u00e9es par les diff\u00e9rentes crises. De mani\u00e8re sp\u00e9cifique, il s\u2019agissait, lors de cette r\u00e9union qui a vu la participation des membres du Bureau du CNPM, des Pr\u00e9sidents des Groupements professionnels, des chefs d\u2019entreprises, des partenaires techniques et financiers, ainsi que des repr\u00e9sentants des structures gouvernementales , d\u2019\u00e9changer sur les cons\u00e9quences de la COVID-19 et la crise sociopolitique sur l\u2019activit\u00e9 \u00e9conomique; identifier des actions concr\u00e8tes \u00e0 mettre en place pour relancer l\u2019\u00e9conomie nationale, renforcer la comp\u00e9titivit\u00e9 et la r\u00e9silience des entreprises, en particulier les PME, face \u00e0 ces d\u00e9sastres ; proposer des m\u00e9canismes de financements innovants, diversifi\u00e9s et adapt\u00e9s \u00e0 la situation; proposer des pistes de solutions pour un environnement stable et favorable \u00e0 l\u2019investissement. Pour atteindre les objectifs fix\u00e9s, trois panels de discussions ont \u00e9t\u00e9 organis\u00e9s sur les th\u00e8mes sp\u00e9cifiques suivants : les effets des multiples crises sur le secteur priv\u00e9, et les mesures pour y faire face, quels m\u00e9canismes de financement pour assurer la r\u00e9silience des entreprises maliennes dans ce contexte multicrise? Comment am\u00e9liorer la comp\u00e9titivit\u00e9 des entreprises dans une logique de transformation structurelle de l\u2019\u00e9conomie ?<\/p>\n\n\n\n<p>Pour le repr\u00e9sentant du ministre, Adama Yoro SIDIBE, la loi d\u2019orientation sur le secteur priv\u00e9, ambitionne de se munir d\u2019un outil d\u2019\u00e9mergence d\u2019un secteur indispensable d\u2019orientation du Secteur priv\u00e9 fort.<\/p>\n\n\n\n<p>&nbsp;\u00ab&nbsp;A cette crise multidimensionnelle, les solutions doivent \u00eatre vari\u00e9es. Il urge de prendre en compte toutes les dimensions \u00e9conomico-sociales, sanitaires. C\u2019est pourquoi, nous appr\u00e9cions fortement le fait que les r\u00e9flexions soient orient\u00e9es sur la r\u00e9silience des entreprises au Mali face aux diff\u00e9rentes crises \u00bb, a soulign\u00e9 Adama Yoro SIDIBE.<\/p>\n\n\n\n<p><strong>Maria RAMAROSA<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Conseil National du Patronat du Mali (CNPM), en partenariat avec le Secr\u00e9tariat Technique Permanent du Conseil Sup\u00e9rieur du Secteur<\/p>\n","protected":false},"author":1,"featured_media":2342,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali : Le CNPM et ses partenaires ont c\u00e9l\u00e9br\u00e9 les journ\u00e9es de l\u2019Entreprise Priv\u00e9e - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali : Le CNPM et ses partenaires ont c\u00e9l\u00e9br\u00e9 les journ\u00e9es de l\u2019Entreprise Priv\u00e9e - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"Le Conseil National du Patronat du Mali (CNPM), en partenariat avec le Secr\u00e9tariat Technique Permanent du Conseil Sup\u00e9rieur du Secteur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-18T21:30:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/02\/fondation.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/12\\\/18\\\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/12\\\/18\\\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali : Le CNPM et ses partenaires ont c\u00e9l\u00e9br\u00e9 les journ\u00e9es de l\u2019Entreprise Priv\u00e9e\",\"datePublished\":\"2021-12-18T21:30:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/12\\\/18\\\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\\\/\"},\"wordCount\":512,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/12\\\/18\\\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/fondation.jpg\",\"articleSection\":[\"EDITORIAL\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/12\\\/18\\\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/12\\\/18\\\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\\\/\",\"name\":\"Mali : Le CNPM et ses partenaires ont c\u00e9l\u00e9br\u00e9 les journ\u00e9es de l\u2019Entreprise Priv\u00e9e - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/12\\\/18\\\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/12\\\/18\\\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/fondation.jpg\",\"datePublished\":\"2021-12-18T21:30:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/12\\\/18\\\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/12\\\/18\\\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/12\\\/18\\\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/fondation.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/fondation.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/12\\\/18\\\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali : Le CNPM et ses partenaires ont c\u00e9l\u00e9br\u00e9 les journ\u00e9es de l\u2019Entreprise Priv\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali : Le CNPM et ses partenaires ont c\u00e9l\u00e9br\u00e9 les journ\u00e9es de l\u2019Entreprise Priv\u00e9e - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali : Le CNPM et ses partenaires ont c\u00e9l\u00e9br\u00e9 les journ\u00e9es de l\u2019Entreprise Priv\u00e9e - REUSSITE INFO","og_description":"Le Conseil National du Patronat du Mali (CNPM), en partenariat avec le Secr\u00e9tariat Technique Permanent du Conseil Sup\u00e9rieur du Secteur","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/","og_site_name":"REUSSITE INFO","article_published_time":"2021-12-18T21:30:20+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/02\/fondation.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali : Le CNPM et ses partenaires ont c\u00e9l\u00e9br\u00e9 les journ\u00e9es de l\u2019Entreprise Priv\u00e9e","datePublished":"2021-12-18T21:30:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/"},"wordCount":512,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/02\/fondation.jpg","articleSection":["EDITORIAL"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/","name":"Mali : Le CNPM et ses partenaires ont c\u00e9l\u00e9br\u00e9 les journ\u00e9es de l\u2019Entreprise Priv\u00e9e - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/02\/fondation.jpg","datePublished":"2021-12-18T21:30:20+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/02\/fondation.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/02\/fondation.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/12\/18\/mali-le-cnpm-et-ses-partenaires-ont-celebre-les-journees-de-lentreprise-privee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali : Le CNPM et ses partenaires ont c\u00e9l\u00e9br\u00e9 les journ\u00e9es de l\u2019Entreprise Priv\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/3179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=3179"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/3179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/2342"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=3179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=3179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=3179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}