{"id":2754,"date":"2021-07-17T19:18:43","date_gmt":"2021-07-17T19:18:43","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=2754"},"modified":"2021-07-17T19:18:43","modified_gmt":"2021-07-17T19:18:43","slug":"mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/","title":{"rendered":"Mali : c\u00e9l\u00e9bration de la journ\u00e9e Internationale de la Croix-Rouge et du Croissant-Rouge"},"content":{"rendered":"\n<p>L\u2019\u00e9v\u00e9nement est plac\u00e9 sous la pr\u00e9sidence du repr\u00e9sentant du gouverneur Yaya WAIGALO, en pr\u00e9sence du repr\u00e9sentant de la direction r\u00e9gionale de la Sant\u00e9, parrain de l\u2019\u00e9v\u00e9nement Dr Yaya TRAORE, de la pr\u00e9sidente par int\u00e9rim, Assitan COULIBALY&nbsp; et&nbsp; du pr\u00e9sident de la croix rouge du district de Bamako, Aliou KONATE. C\u2019\u00e9tait dans la salle de conf\u00e9rence du gouvernorat du district de Bamako.<\/p>\n\n\n\n<p>Plac\u00e9e cette ann\u00e9e sous le th\u00e8me \u00ab&nbsp;Ensemble nous sommes inalt\u00e9rables&nbsp;\u00bb, la journ\u00e9e internationale de la Croix-Rouge et du Croissant-Rouge vise \u00e0 s&rsquo;assurer que chacun r\u00e9pond toujours \u00e0 l&rsquo;appel \u00e0 l&rsquo;aide de l\u2019autre avec d\u00e9termination.&nbsp;<\/p>\n\n\n\n<p>Pour la pr\u00e9sidente par int\u00e9rim, Assitan COULIBALY, servir avec humanit\u00e9 en tout lieu et en toute circonstance est une valeur qui conditionne la nature de notre action.&nbsp;\u00ab&nbsp; <em>Cette journ\u00e9e c\u00e9l\u00e9br\u00e9e &nbsp;de part le monde entier, donne l&rsquo;occasion de sensibiliser l&rsquo;opinion nationale et internationale sur le principe des valeurs humaines<\/em>&nbsp;\u00bb &nbsp;a soulign\u00e9 Assitan COULIBALY.<\/p>\n\n\n\n<p>Pour le pr\u00e9sident de la croix rouge du district de Bamako, Aliou KONATE, la mission fondamentale de la Croix-Rouge est d&rsquo;assister les populations vuln\u00e9rables et cette mission est toujours accompagn\u00e9e par les autorit\u00e9s administratives, traditionnelles et religieuses. \u00ab&nbsp;<em>Cette activit\u00e9 est organis\u00e9e par le comit\u00e9 de la Croix-Rouge malienne du district de Bamako pour vous informer, afin de renforcer vos connaissances sur le mouvement au niveau national de la Croix-Rouge et surtout ce que nous faisons au niveau de Bamako comme action humanitaire, dans le cadre des missions de la Croix-Rouge<\/em>&nbsp;\u00bb a soulign\u00e9 Aliou KONATE, selon lui, les d\u00e9fis \u00e0 travers le monde devraient interpeller tous les pays sans exclusion. \u00ab <em>Depuis un certains temps des \u00e9v\u00e8nements malheureux comme les forces de l&rsquo;opposition, les terroristes et les malentendus entre les communaut\u00e9s ont occasionn\u00e9s des mouvements des populations vers les r\u00e9gions du centre et de Bamako. La Croix-Rouge contribue au r\u00e9tablissement des liens familiaux et des assistances de soutien aux familles d\u00e9plac\u00e9es<\/em>&nbsp;\u00bb a d\u00e9plor\u00e9 Aliou KONATE.&nbsp;<\/p>\n\n\n\n<p>Quant au parrain et repr\u00e9sentant de la direction r\u00e9gionale de la sant\u00e9, &nbsp; Yaya TRAORE, il a indiqu\u00e9 qu\u2019en acceptant ce parrainage, il vient aussi s&rsquo;inspirer des exp\u00e9riences de la Croix-Rouge malienne, en mati\u00e8re d&rsquo;am\u00e9lioration des conditions de vie des personnes vuln\u00e9rables.<\/p>\n\n\n\n<p><strong>Lorie Saint-Charbel<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9v\u00e9nement est plac\u00e9 sous la pr\u00e9sidence du repr\u00e9sentant du gouverneur Yaya WAIGALO, en pr\u00e9sence du repr\u00e9sentant de la direction r\u00e9gionale<\/p>\n","protected":false},"author":1,"featured_media":2755,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali : c\u00e9l\u00e9bration de la journ\u00e9e Internationale de la Croix-Rouge et du Croissant-Rouge - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali : c\u00e9l\u00e9bration de la journ\u00e9e Internationale de la Croix-Rouge et du Croissant-Rouge - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"L\u2019\u00e9v\u00e9nement est plac\u00e9 sous la pr\u00e9sidence du repr\u00e9sentant du gouverneur Yaya WAIGALO, en pr\u00e9sence du repr\u00e9sentant de la direction r\u00e9gionale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-17T19:18:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/07\/IMG-20210717-WA0037.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/07\\\/17\\\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/07\\\/17\\\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali : c\u00e9l\u00e9bration de la journ\u00e9e Internationale de la Croix-Rouge et du Croissant-Rouge\",\"datePublished\":\"2021-07-17T19:18:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/07\\\/17\\\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\\\/\"},\"wordCount\":438,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/07\\\/17\\\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/IMG-20210717-WA0037.jpg\",\"articleSection\":[\"EDITORIAL\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/07\\\/17\\\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/07\\\/17\\\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\\\/\",\"name\":\"Mali : c\u00e9l\u00e9bration de la journ\u00e9e Internationale de la Croix-Rouge et du Croissant-Rouge - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/07\\\/17\\\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/07\\\/17\\\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/IMG-20210717-WA0037.jpg\",\"datePublished\":\"2021-07-17T19:18:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/07\\\/17\\\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/07\\\/17\\\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/07\\\/17\\\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/IMG-20210717-WA0037.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/IMG-20210717-WA0037.jpg\",\"width\":1080,\"height\":810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/07\\\/17\\\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali : c\u00e9l\u00e9bration de la journ\u00e9e Internationale de la Croix-Rouge et du Croissant-Rouge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali : c\u00e9l\u00e9bration de la journ\u00e9e Internationale de la Croix-Rouge et du Croissant-Rouge - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali : c\u00e9l\u00e9bration de la journ\u00e9e Internationale de la Croix-Rouge et du Croissant-Rouge - REUSSITE INFO","og_description":"L\u2019\u00e9v\u00e9nement est plac\u00e9 sous la pr\u00e9sidence du repr\u00e9sentant du gouverneur Yaya WAIGALO, en pr\u00e9sence du repr\u00e9sentant de la direction r\u00e9gionale","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/","og_site_name":"REUSSITE INFO","article_published_time":"2021-07-17T19:18:43+00:00","og_image":[{"width":1080,"height":810,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/07\/IMG-20210717-WA0037.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali : c\u00e9l\u00e9bration de la journ\u00e9e Internationale de la Croix-Rouge et du Croissant-Rouge","datePublished":"2021-07-17T19:18:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/"},"wordCount":438,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/07\/IMG-20210717-WA0037.jpg","articleSection":["EDITORIAL"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/","name":"Mali : c\u00e9l\u00e9bration de la journ\u00e9e Internationale de la Croix-Rouge et du Croissant-Rouge - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/07\/IMG-20210717-WA0037.jpg","datePublished":"2021-07-17T19:18:43+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/07\/IMG-20210717-WA0037.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/07\/IMG-20210717-WA0037.jpg","width":1080,"height":810},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/07\/17\/mali-celebration-de-la-journee-internationale-de-la-croix-rouge-et-du-croissant-rouge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali : c\u00e9l\u00e9bration de la journ\u00e9e Internationale de la Croix-Rouge et du Croissant-Rouge"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=2754"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/2755"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=2754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=2754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=2754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}