{"id":2726,"date":"2021-06-27T12:55:29","date_gmt":"2021-06-27T12:55:29","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=2726"},"modified":"2021-06-27T12:55:29","modified_gmt":"2021-06-27T12:55:29","slug":"mali-celebration-de-la-journee-mondiale-des-pme-pmi","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/","title":{"rendered":"Mali: c\u00e9l\u00e9bration de la journ\u00e9e mondiale des PME\/PMI"},"content":{"rendered":"\n<p>L\u2019esplanade du palais des sports de Bamako, a servi de cadre le samedi 26 juin 2021, aux festivit\u00e9s de la c\u00e9l\u00e9bration de la journ\u00e9e mondiale des micros, petites et moyennes entreprises (PME\/PMI). La c\u00e9r\u00e9monie d\u2019ouverture de ces festivit\u00e9s est plac\u00e9e sous la pr\u00e9sidence du ministre de l\u2019Industrie, du&nbsp;Commerce et de la&nbsp;Promotion des investissements, repr\u00e9sent\u00e9 par le directeur national des PME, Boubacary CISSE. C\u2019\u00e9tait en pr\u00e9sence de la directrice du centre malien de la Propri\u00e9t\u00e9 Intellectuelle Sira ghatta TRAORE, de l\u2019administrateur g\u00e9n\u00e9ral du r\u00e9seau malien des PME, Koro COULIBALY.<\/p>\n\n\n\n<p>En pr\u00e9lude \u00e0 la journ\u00e9e mondiale des micros, petites et moyennes entreprises c\u00e9l\u00e9br\u00e9e par la communaut\u00e9 internationale le dimanche 27 juin 2021, le r\u00e9seau malien des micros, petites et moyennes entreprises en collaboration avec le minist\u00e8re de l\u2019Industrie, du\u00a0Commerce et de la\u00a0Promotion des investissements, a organis\u00e9 des festivit\u00e9s pour pr\u00e9senter la situation de ces entreprises et les efforts entrepris pour leur promotion et leur d\u00e9veloppement. Le repr\u00e9sentant du ministre, Boubacary CISSE, non moins\u00a0 directeur national des PME, a indiqu\u00e9 que cette journ\u00e9e mondiale des PME, permettra de donner une visibilit\u00e9 \u00e0 nos PME. \u00ab\u00a0<em>Ce sont les PME qui cr\u00e9ent les richesses, qui cr\u00e9ent de l&#8217;emploi, donc pour activer une croissance \u00e9conomique, il faut obligatoirement passer par les PME\u00a0<\/em>\u00bba comment\u00e9 Boubacary CISSE. Selon lui, cette journ\u00e9e donne une occasion de mettre l&rsquo;accent sur la contribution des PME \u00e0 l&rsquo;\u00e9conomie malienne. En mati\u00e8re de pourcentage, le tissu de l&rsquo;entrepreneuriat du Mali est domin\u00e9 par les PME. \u00ab\u00a0<em>Plus de 90% des entreprises au Mali, sont des PME, mais ces PME ont des difficult\u00e9s d&rsquo;acc\u00e8s au financement. Elles ont aussi des difficult\u00e9s de renforcement des capacit\u00e9s techniques et manag\u00e9riales. Donc vous voyez les difficult\u00e9s de financement des PME, c\u2019est seulement 10% de portefeuille des banques qui vont aux PME. Pourtant, en mati\u00e8re de cr\u00e9ation d&#8217;emploi, ces PME ne cr\u00e9ent pas moins de 100 milles emplois dans notre pays. Voyez les recettes fiscales, elles contribuent \u00e0 moins de 07% \u00e0 l&rsquo;\u00e9conomie malienne. Il faut donc un passage \u00e0 l&rsquo;\u00e9chelle pour que ces PME puissent jouer pleinement leur r\u00f4le dans la croissance \u00e9conomique<\/em>\u00a0\u00bb a plaid\u00e9 le directeur national des PME.\u00a0<\/p>\n\n\n\n<p>On se rappelle, dans son message \u00e0 la nation le vendredi 23 juin 2021, le ministre de l\u2019Industrie, du&nbsp;Commerce et de la&nbsp;Promotion des investissements, Mahmoud Ould MOHAMED a indiqu\u00e9 que l\u2019essentiel de notre tissu \u00e9conomique est constitu\u00e9 de micros petites et moyennes entreprises, soit plus de 90%, dont 80% \u00e9voluent dans le secteur informel.&nbsp; Les micros petites et moyennes entreprises sont confront\u00e9es \u00e0 un certain nombre de difficult\u00e9s, parmi lesquelles figurent, l\u2019acc\u00e8s au financement ; l\u2019acc\u00e8s \u00e0 la commande publique et aux march\u00e9s ; l\u2019acc\u00e8s \u00e0 la recherche et \u00e0 l\u2019innovation. \u00ab&nbsp;<em>Pour pallier ces difficult\u00e9s, le Gouvernement a consenti beaucoup d\u2019efforts pour promouvoir les micros petites et moyennes entreprises. C\u2019est dans cette optique que l\u2019Etat a mis en place la direction nationale des micros petites et moyennes entreprises avec son Programme d\u2019appui au d\u00e9veloppement du secteur, comprenant quatre composantes \u00e0 savoir l\u2019am\u00e9lioration du climat des affaires ; le renforcement des capacit\u00e9s techniques et manag\u00e9riales des micros petites et moyennes entreprises ;&nbsp;l\u2019am\u00e9lioration de l\u2019acc\u00e8s au financement &nbsp;et la d\u00e9fense des int\u00e9r\u00eats des micros petites et moyennes entreprises<\/em>&nbsp;\u00bb a soulign\u00e9 le ministre.<\/p>\n\n\n\n<p>A noter que les PME sont les vecteurs de dynamisme \u00e9conomique qui doivent impacter les conditions de vie des populations, r\u00e9duire le ch\u00f4mage et remplir les caisses de l&rsquo;\u00c9tat \u00e0 travers le payement des imp\u00f4ts. Dans ce cas, il devient urgent de les assister et de les accompagner.<\/p>\n\n\n\n<p><strong>Charles MESSE<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019esplanade du palais des sports de Bamako, a servi de cadre le samedi 26 juin 2021, aux festivit\u00e9s de la<\/p>\n","protected":false},"author":1,"featured_media":2713,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali: c\u00e9l\u00e9bration de la journ\u00e9e mondiale des PME\/PMI - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali: c\u00e9l\u00e9bration de la journ\u00e9e mondiale des PME\/PMI - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"L\u2019esplanade du palais des sports de Bamako, a servi de cadre le samedi 26 juin 2021, aux festivit\u00e9s de la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-27T12:55:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/06\/PME1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali: c\u00e9l\u00e9bration de la journ\u00e9e mondiale des PME\\\/PMI\",\"datePublished\":\"2021-06-27T12:55:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\\\/\"},\"wordCount\":672,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/PME1.jpg\",\"articleSection\":[\"EDITORIAL\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\\\/\",\"name\":\"Mali: c\u00e9l\u00e9bration de la journ\u00e9e mondiale des PME\\\/PMI - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/PME1.jpg\",\"datePublished\":\"2021-06-27T12:55:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/PME1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/PME1.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali: c\u00e9l\u00e9bration de la journ\u00e9e mondiale des PME\\\/PMI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali: c\u00e9l\u00e9bration de la journ\u00e9e mondiale des PME\/PMI - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali: c\u00e9l\u00e9bration de la journ\u00e9e mondiale des PME\/PMI - REUSSITE INFO","og_description":"L\u2019esplanade du palais des sports de Bamako, a servi de cadre le samedi 26 juin 2021, aux festivit\u00e9s de la","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/","og_site_name":"REUSSITE INFO","article_published_time":"2021-06-27T12:55:29+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/06\/PME1.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali: c\u00e9l\u00e9bration de la journ\u00e9e mondiale des PME\/PMI","datePublished":"2021-06-27T12:55:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/"},"wordCount":672,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/06\/PME1.jpg","articleSection":["EDITORIAL"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/","name":"Mali: c\u00e9l\u00e9bration de la journ\u00e9e mondiale des PME\/PMI - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/06\/PME1.jpg","datePublished":"2021-06-27T12:55:29+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/06\/PME1.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/06\/PME1.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-celebration-de-la-journee-mondiale-des-pme-pmi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali: c\u00e9l\u00e9bration de la journ\u00e9e mondiale des PME\/PMI"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=2726"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/2713"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=2726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=2726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=2726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}