{"id":2708,"date":"2021-06-27T10:44:29","date_gmt":"2021-06-27T10:44:29","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=2708"},"modified":"2021-06-27T10:44:29","modified_gmt":"2021-06-27T10:44:29","slug":"mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/","title":{"rendered":"Mali: Assembl\u00e9e consulaire de l\u2019APCMM, pour r\u00e9fl\u00e9chir sur les probl\u00e8mes de l\u2019artisanat malien"},"content":{"rendered":"\n<p>La 20\u00e8 session ordinaire de l\u2019Assembl\u00e9e consulaire de l\u2019Assembl\u00e9e Permanente des Chambres de M\u00e9tiers du Mali (APCMM) s\u2019est tenue, le jeudi 24 juin 2021 dans les locaux de la chambre des m\u00e9tiers, sous la houlette ministre de la&nbsp;Culture, de l\u2019Artisanat, de l\u2019industrie h\u00f4teli\u00e8re et du&nbsp;Tourisme, Andogoly GUINDO en pr\u00e9sence de son homologue de l\u2019Entrepreneuriat national, de l\u2019Emploi et de la&nbsp;Formation professionnelle, Bakary DOUMBIA, du pr\u00e9sident du patronat Diadi\u00e9 dit Amadou SANKARE, du pr\u00e9sident de l\u2019APCMM, Mamadou Minkoro TRAORE et des pr\u00e9sidents des chambres des m\u00e9tiers et des \u00e9lus consulaires des r\u00e9gions et du district de Bamako.<\/p>\n\n\n\n<p>Le pr\u00e9sident de l\u2019Assembl\u00e9e permanente des chambres de m\u00e9tiers du Mali (APCMM), Mamadou Minkoro TRAORE, a entam\u00e9 ses propos en \u00e9talant la s\u00e9rie des r\u00e9alisations des artisans, tout en louant l\u2019accompagnement de l\u2019Etat. Il a \u00e9voqu\u00e9 plusieurs innovations en faveur du progr\u00e8s du secteur. Cependant, l&rsquo;arbre ne doit pas cacher la for\u00eat a t-il averti. <em>\u00ab&nbsp;Malgr\u00e9 les r\u00e9alisations ci-dessous \u00e9voqu\u00e9es, notre secteur reste confront\u00e9 \u00e0 des d\u00e9fis multiformes relatifs notamment \u00e0 l&rsquo;insuffisance de ressources humaines qualit\u00e9s ;&nbsp;l&rsquo;insuffisance de ressources financi\u00e8res et mat\u00e9rielles, notamment les mat\u00e9riels roulants ;&nbsp;la construction des si\u00e8ges des chambres de m\u00e9tiers ;&nbsp;la comp\u00e9titivit\u00e9 des produits artisanaux ;&nbsp;la promotion des produits artisanaux et l&rsquo;institutionnalisation du Salon internationale de l&rsquo;Artisanat du Mali ( SIAMA );&nbsp;la protection sociale des artisans ;&nbsp;l&rsquo;acc\u00e8s des artisans aux march\u00e9s publics;&nbsp;la poursuite de la formation professionnelle et l&rsquo;apprentissage des artisans ;&nbsp;la s\u00e9curisation du foncier d\u00e9di\u00e9 \u00e0 l&rsquo;exercice des activit\u00e9s artisanales;&nbsp;&nbsp;le financement adapt\u00e9 au secteur de l&rsquo;artisanat ( acc\u00e8s aux cr\u00e9dits );&nbsp;la fiscalit\u00e9 adapt\u00e9e au secteur de l&rsquo;artisanat ( contribution sp\u00e9cifique pour l&rsquo;artisanat CSA);&nbsp;l&rsquo;insuffisance d&rsquo;informations strat\u00e9giques ;&nbsp;la restructuration des chambres des m\u00e9tiers et des organisations professionnelles d&rsquo;artisans (OPA), conform\u00e9ment au code communautaire de l&rsquo;artisanat de l&rsquo;UEMOA&nbsp;<\/em>\u00bb a \u00e9num\u00e9r\u00e9 Mamadou Minkoro TRAORE<\/p>\n\n\n\n<p>Pour le ministre<strong><em> <\/em><\/strong>de la&nbsp;Culture, de l\u2019Artisanat, de l\u2019industrie h\u00f4teli\u00e8re et du&nbsp;Tourisme, Andogoly GUINDO, la disponibilit\u00e9 du gouvernement \u00e0 vous accompagner dans la mise en \u0153uvre de vos projets et programmes ne fera pas d\u00e9faut.&nbsp;\u00ab&nbsp; <em>Aussi, je voudrais vous assurer que les dispositions sont en cours pour la mise en \u0153uvre des mesures prises par l&rsquo;\u00c9tat, en vue d&rsquo;endiguer les effets de la crise du secteur de l&rsquo;artisanat. Mes services sont \u00e0 pieds d&rsquo;\u0153uvre, en rapport avec l&rsquo;APCMM, pour le traitement diligent du dossier de l&rsquo;appui sp\u00e9cial aux acteurs du secteur<\/em>&nbsp;\u00bb a rassur\u00e9 Andogoly GUINDO.<\/p>\n\n\n\n<p>A noter que&nbsp; le pr\u00e9sident de l\u2019APCMM TRAORE a fait savoir que durant les deux jours de travaux, les artisans passeront en revue les diff\u00e9rents probl\u00e8mes entravant l\u2019essor de l\u2019activit\u00e9 tout en apportant des solutions idoines aux probl\u00e8mes qui entravent le d\u00e9veloppement de l\u2019artisanat malien. Les textes communautaires de l&rsquo;artisanat seront pass\u00e9s aux peignes fins pour donner effet, de solution relative notamment \u00e0 la nomenclature de m\u00e9tier pour le cursus, pour le r\u00e9pertoire des entreprises artisanales, \u00e0 la d\u00e9livrance des cartes professionnelles, \u00e0 la commission qui adopte des certifications des comp\u00e9tences des artisans et la restructuration des organisations professionnelles des artisans.&nbsp;<\/p>\n\n\n\n<p><strong>Joseph SISSOKO<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 20\u00e8 session ordinaire de l\u2019Assembl\u00e9e consulaire de l\u2019Assembl\u00e9e Permanente des Chambres de M\u00e9tiers du Mali (APCMM) s\u2019est tenue, le<\/p>\n","protected":false},"author":1,"featured_media":2710,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali: Assembl\u00e9e consulaire de l\u2019APCMM, pour r\u00e9fl\u00e9chir sur les probl\u00e8mes de l\u2019artisanat malien - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali: Assembl\u00e9e consulaire de l\u2019APCMM, pour r\u00e9fl\u00e9chir sur les probl\u00e8mes de l\u2019artisanat malien - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"La 20\u00e8 session ordinaire de l\u2019Assembl\u00e9e consulaire de l\u2019Assembl\u00e9e Permanente des Chambres de M\u00e9tiers du Mali (APCMM) s\u2019est tenue, le\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-27T10:44:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/06\/APCMM2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali: Assembl\u00e9e consulaire de l\u2019APCMM, pour r\u00e9fl\u00e9chir sur les probl\u00e8mes de l\u2019artisanat malien\",\"datePublished\":\"2021-06-27T10:44:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\\\/\"},\"wordCount\":623,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/APCMM2.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\\\/\",\"name\":\"Mali: Assembl\u00e9e consulaire de l\u2019APCMM, pour r\u00e9fl\u00e9chir sur les probl\u00e8mes de l\u2019artisanat malien - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/APCMM2.jpg\",\"datePublished\":\"2021-06-27T10:44:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/APCMM2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/APCMM2.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/06\\\/27\\\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali: Assembl\u00e9e consulaire de l\u2019APCMM, pour r\u00e9fl\u00e9chir sur les probl\u00e8mes de l\u2019artisanat malien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali: Assembl\u00e9e consulaire de l\u2019APCMM, pour r\u00e9fl\u00e9chir sur les probl\u00e8mes de l\u2019artisanat malien - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali: Assembl\u00e9e consulaire de l\u2019APCMM, pour r\u00e9fl\u00e9chir sur les probl\u00e8mes de l\u2019artisanat malien - REUSSITE INFO","og_description":"La 20\u00e8 session ordinaire de l\u2019Assembl\u00e9e consulaire de l\u2019Assembl\u00e9e Permanente des Chambres de M\u00e9tiers du Mali (APCMM) s\u2019est tenue, le","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/","og_site_name":"REUSSITE INFO","article_published_time":"2021-06-27T10:44:29+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/06\/APCMM2.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali: Assembl\u00e9e consulaire de l\u2019APCMM, pour r\u00e9fl\u00e9chir sur les probl\u00e8mes de l\u2019artisanat malien","datePublished":"2021-06-27T10:44:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/"},"wordCount":623,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/06\/APCMM2.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/","name":"Mali: Assembl\u00e9e consulaire de l\u2019APCMM, pour r\u00e9fl\u00e9chir sur les probl\u00e8mes de l\u2019artisanat malien - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/06\/APCMM2.jpg","datePublished":"2021-06-27T10:44:29+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/06\/APCMM2.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/06\/APCMM2.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/06\/27\/mali-assemblee-consulaire-de-lapcmm-pour-reflechir-sur-les-problemes-de-lartisanat-malien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali: Assembl\u00e9e consulaire de l\u2019APCMM, pour r\u00e9fl\u00e9chir sur les probl\u00e8mes de l\u2019artisanat malien"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=2708"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2708\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/2710"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=2708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=2708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=2708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}