{"id":2581,"date":"2021-04-25T15:40:49","date_gmt":"2021-04-25T15:40:49","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=2581"},"modified":"2021-04-25T15:40:49","modified_gmt":"2021-04-25T15:40:49","slug":"mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/","title":{"rendered":"Mali: Signature de convention de financement de 60 millions de dollars US  pour financer le projet PAFEEM"},"content":{"rendered":"\n<p>Le Mali et la Banque mondiale ont sign\u00e9 le mardi 20 avril 2021 \u00e0 Bamako, une convention de financement du projet de promotion de l\u2019Acc\u00e8s au Financement, \u00e0 l\u2019Entreprenariat et \u00e0 l\u2019Emploi au Mali (PAFEEM) d\u2019un montant de 33, 08 milliards FCFA soit 60 millions de dollars US (30 millions de dollars en pr\u00eat IDA et 30 millions de dollars en don). La c\u00e9r\u00e9monie de signature s\u2019est d\u00e9roul\u00e9e entre le ministre de l\u2019\u00c9conomie et des Finances, Alouss\u00e9ni SANOU et la directrice des Op\u00e9rations de la Banque mondiale au Mali, Mme Soukeina KANE.<\/p>\n\n\n\n<p>Approuv\u00e9 le 17 mars 2021 par le Conseil des administrateurs de la Banque mondiale, le PAFEEM permettra de soutenir les efforts du gouvernement face aux d\u00e9fis de l\u2019inclusion financi\u00e8re, du financement des micros, petites et moyennes entreprises (MPME) et de la cr\u00e9ation d\u2019activit\u00e9s g\u00e9n\u00e9ratrices de revenus, particuli\u00e8rement au b\u00e9n\u00e9fice des jeunes et des femmes.<\/p>\n\n\n\n<p>Le ministre de MEF a rappel\u00e9 avec satisfaction que la signature de cet Accord de financement est la 5<sup>\u00e8me<\/sup> sign\u00e9 avec la Banque mondiale, depuis le d\u00e9but de l\u2019ann\u00e9e 2021, et totalisant un montant de plus de 397,81 millions de dollars am\u00e9ricains, soit environ 219,35 milliards de F.CFA en pr\u00eats et dons. Selon lui, l\u2019Accord de financement qui vient d\u2019\u00eatre sign\u00e9, d\u2019un montant de 60 millions de dollars US, soit environ 33, 08 milliards FCFA (30 millions de dollars en pr\u00eat IDA et 30 millions en don), permettra au Gouvernement du Mali de soutenir l\u2019entreprenariat et l\u2019emploi au Mali en appuyant l\u2019acc\u00e8s au financement des activit\u00e9s g\u00e9n\u00e9ratrices de revenus et en promouvant l\u2019entreprenariat et l\u2019emploi au profit des segments vuln\u00e9rables au Mali.&nbsp;\u00ab&nbsp;<em>Aussi voudrais-je vous rassurer que nous ne m\u00e9nagerons&nbsp; aucun effort pour honorer les engagements pris afin d\u2019assurer la bonne r\u00e9alisation de ce projet qui contribue ind\u00e9niablement \u00e0 la mise en \u0153uvre r\u00e9ussie de notre nouveau Cadre Strat\u00e9gique pour la Relance Economique et le D\u00e9veloppement Durable (CREDD) et de son plan d\u2019actions pour la p\u00e9riode 2019-2023, particuli\u00e8rement l\u2019axe strat\u00e9gique n\u00b03&nbsp;: Croissance inclusive et transformation structurelle de l\u2019\u00e9conomie<\/em>&nbsp;\u00bb.<\/p>\n\n\n\n<p>Pour la directrice des Op\u00e9rations de la Banque mondiale, cette initiative a pour objectif de soutenir les efforts du gouvernement face aux d\u00e9fis de l\u2019inclusion financi\u00e8re, du financement des micro, petites et moyennes entreprises (MPME) et de la cr\u00e9ation d\u2019activit\u00e9s g\u00e9n\u00e9ratrices de revenus, particuli\u00e8rement au b\u00e9n\u00e9fice des jeunes et des femmes. \u00ab&nbsp;<em>Le PAFEEM adh\u00e8re \u00e0 la strat\u00e9gie de d\u00e9veloppement \u00e9conomique durable qui inclut la promotion du d\u00e9veloppement inclusif et de la transformation \u00e9conomique et appuie les efforts nationaux pour l\u2019emploi&nbsp;<\/em>\u00bb a pr\u00e9cis\u00e9 Mme KANE avant d\u2019ajouter que le projet s\u2019inscrit dans le cadre de la politique de la r\u00e9gion Afrique de l\u2019Ouest et du Centre de la Banque mondiale visant \u00e0 renforcer le capital humain, l\u2019autonomisation des femmes, l\u2019acc\u00e9l\u00e9ration de la transformation num\u00e9rique et l\u2019int\u00e9gration r\u00e9gionale.<\/p>\n\n\n\n<p>Le projet sera mis en \u0153uvre \u00e0 travers cinq composantes qui sont les suivantes: La composante 1: promotion d\u2019une inclusion financi\u00e8re durable et le D\u00e9veloppement de la Fintech; la composante 2: partage des risques et renforcement des capacit\u00e9s des Micros, Petites et Moyennes Entreprises (MPME) ; la composante 3: appui aux Activit\u00e9s G\u00e9n\u00e9ratrices de Revenus, Aide au revenu et \u00e0 l\u2019emploi; la composante 4: \u00ab Intervention d\u2019urgence et de contingence \u00bb ; et enfin la composante 5: soutien \u00e0 la gestion et \u00e0 la mise en \u0153uvre du projet.<\/p>\n\n\n\n<p>Les composantes 1 et 2 couvriront tout le Mali, alors que la composante 3 (Activit\u00e9s G\u00e9n\u00e9ratrices de Revenus-AGR et Travaux de Haute Intensit\u00e9 de Main d\u2019\u0153uvre-HIMO) se concentreront sur les populations vuln\u00e9rables, en particulier les femmes et les jeunes dans le Centre et le Nord du pays (Mopti, Gao, Tombouctou et Kidal).<\/p>\n\n\n\n<p>Selon la Directrice des Op\u00e9rations de la Banque mondiale au Mali, \u00ab\u00a0le PAFEEM adh\u00e8re \u00e0 la strat\u00e9gie de d\u00e9veloppement \u00e9conomique durable qui inclut la promotion du d\u00e9veloppement inclusif et de la transformation \u00e9conomique et appuie les efforts nationaux pour l\u2019emploi. En outre, le projet s\u2019inscrit dans le cadre de la politique de la r\u00e9gion Afrique de l\u2019Ouest et du Centre de la Banque mondiale visant \u00e0 renforcer le capital humain, l\u2019autonomisation des femmes, l\u2019acc\u00e9l\u00e9ration de la transformation num\u00e9rique et l\u2019int\u00e9gration r\u00e9gionale \u00ab\u00a0.<\/p>\n\n\n\n<p>L\u2019Unit\u00e9 d\u2019Appui et de Suivi du Secteur Financier (services rattach\u00e9s du Minist\u00e8re de l\u2019Economie et des Finances), le Fonds de Garantie du Secteur Priv\u00e9 (FGSP-SA), l\u2019Association des Banques et Etablissements Financiers (APBEF) ainsi que les institutions de microfinance au Mali sont les structures qui participeront \u00e0 la mise en \u0153uvre r\u00e9ussie du projet qui garantira un pr\u00eat ou une ligne de cr\u00e9dit \u00e0 1 000 micros, petites et moyennes entreprises et 15 000 personnes pourront b\u00e9n\u00e9ficier d\u2019opportunit\u00e9s g\u00e9n\u00e9ratrices de revenus, notamment les femmes.<\/p>\n\n\n\n<p>De plus, il soutiendra la num\u00e9risation de certains services de paiement du gouvernement afin d\u2019augmenter le nombre de personnes d\u00e9tenant un compte de transaction \u00e9lectronique.<\/p>\n\n\n\n<p>Avant de cl\u00f4turer la c\u00e9r\u00e9monie, le Ministre de l\u2019Economie et des Finances a adress\u00e9 au Groupe de la Banque mondiale les chaleureux remerciements du Pr\u00e9sident de la Transition et du Gouvernement du Mali pour tous ses efforts inlassables en faveur du d\u00e9veloppement socio-\u00e9conomique du Mali.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><\/td><td><\/td><\/tr><tr><td>&nbsp;<\/td><td><\/td><td><\/td><\/tr><tr><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Charles MESSE<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Mali et la Banque mondiale ont sign\u00e9 le mardi 20 avril 2021 \u00e0 Bamako, une convention de financement du<\/p>\n","protected":false},"author":1,"featured_media":2582,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali: Signature de convention de financement de 60 millions de dollars US pour financer le projet PAFEEM - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali: Signature de convention de financement de 60 millions de dollars US pour financer le projet PAFEEM - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"Le Mali et la Banque mondiale ont sign\u00e9 le mardi 20 avril 2021 \u00e0 Bamako, une convention de financement du\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-25T15:40:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/mef-et-bm2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1011\" \/>\n\t<meta property=\"og:image:height\" content=\"712\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/25\\\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/25\\\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali: Signature de convention de financement de 60 millions de dollars US pour financer le projet PAFEEM\",\"datePublished\":\"2021-04-25T15:40:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/25\\\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\\\/\"},\"wordCount\":958,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/25\\\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/mef-et-bm2.jpg\",\"articleSection\":[\"EDITORIAL\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/25\\\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/25\\\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\\\/\",\"name\":\"Mali: Signature de convention de financement de 60 millions de dollars US pour financer le projet PAFEEM - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/25\\\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/25\\\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/mef-et-bm2.jpg\",\"datePublished\":\"2021-04-25T15:40:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/25\\\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/25\\\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/25\\\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/mef-et-bm2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/mef-et-bm2.jpg\",\"width\":1011,\"height\":712},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/25\\\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali: Signature de convention de financement de 60 millions de dollars US pour financer le projet PAFEEM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali: Signature de convention de financement de 60 millions de dollars US pour financer le projet PAFEEM - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali: Signature de convention de financement de 60 millions de dollars US pour financer le projet PAFEEM - REUSSITE INFO","og_description":"Le Mali et la Banque mondiale ont sign\u00e9 le mardi 20 avril 2021 \u00e0 Bamako, une convention de financement du","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/","og_site_name":"REUSSITE INFO","article_published_time":"2021-04-25T15:40:49+00:00","og_image":[{"width":1011,"height":712,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/mef-et-bm2.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali: Signature de convention de financement de 60 millions de dollars US pour financer le projet PAFEEM","datePublished":"2021-04-25T15:40:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/"},"wordCount":958,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/mef-et-bm2.jpg","articleSection":["EDITORIAL"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/","name":"Mali: Signature de convention de financement de 60 millions de dollars US pour financer le projet PAFEEM - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/mef-et-bm2.jpg","datePublished":"2021-04-25T15:40:49+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/mef-et-bm2.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/mef-et-bm2.jpg","width":1011,"height":712},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/25\/mali-signature-de-convention-de-financement-de-60-millions-de-dollars-us-pour-financer-le-projet-pafeem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali: Signature de convention de financement de 60 millions de dollars US pour financer le projet PAFEEM"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=2581"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/2582"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=2581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=2581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=2581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}