{"id":2563,"date":"2021-04-14T15:07:45","date_gmt":"2021-04-14T15:07:45","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=2563"},"modified":"2021-04-14T15:07:45","modified_gmt":"2021-04-14T15:07:45","slug":"business-plan-les-erreurs-a-ne-pas-commettre","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/","title":{"rendered":"Business plan : les erreurs \u00e0 ne pas commettre"},"content":{"rendered":"\n<p>Trop souvent, le business plan est vu par le cr\u00e9ateur d\u2019entreprise comme une obligation administrative, sous la forme de tableaux complexes, qu\u2019il d\u00e9volue au comptable parce qu\u2019il pense qu\u2019il est plus \u00e0 m\u00eame de cerner les chiffres. Au contraire, le business plan doit \u00eatre con\u00e7u par le cr\u00e9ateur pour lui-m\u00eame, comme un sc\u00e9nario \u00e9conomique et financier destin\u00e9 \u00e0 v\u00e9rifier la rentabilit\u00e9 de son projet d\u2019entreprise et d\u00e9celer les opportunit\u00e9s du moment pr\u00e9sent ou futur, d\u00e9celer les faiblesses pour y rester attentif tout au long du d\u00e9veloppement de l\u2019entreprise.<\/p>\n\n\n\n<p><strong>Abordez le projet dans son ensemble, de fa\u00e7on structur\u00e9e<\/strong><\/p>\n\n\n\n<p>Partez de constats d\u00e9finis dans l\u2019\u00e9tude de march\u00e9, qui permettent de cerner le produit\/ service vis\u00e9, la taille du march\u00e9, la concurrence et les fournisseurs. D\u00e9roulez la strat\u00e9gie et le positionnement choisis et explicitez le business model retenu. Pour vous aider, utilisez des trames existantes, telles que celles qu\u2019on trouve sur le site de bpifrance.<\/p>\n\n\n\n<p>Attention, cette partie ne doit pas rester th\u00e9orique : si vous montez un restaurant \u00e0 salades, les g\u00e9n\u00e9ralit\u00e9s sur le secteur ne vous int\u00e9ressent gu\u00e8re (type \u00ab Les Fran\u00e7ais consacrent de moins en moins de temps au d\u00e9jeuner \u00bb ou \u00ab Ils sont soucieux de la qualit\u00e9 des produits, du manger sain \u00bb).<\/p>\n\n\n\n<p>En revanche, vous vous pencherez sur l\u2019environnement local : bureaux et entreprises situ\u00e9s \u00e0 proximit\u00e9, passage devant votre local, \u00e9tude d\u00e9taill\u00e9e des concurrents, leurs performances, votre positionnement produit et prix, votre <a href=\"https:\/\/www.dynamique-mag.com\/article\/le-plan-d-action-commerciale-pac.2651\">plan d\u2019actions commercial<\/a>\u2026 Vous pouvez ensuite fonder des hypoth\u00e8ses de chiffre d\u2019affaires tangibles : un panier moyen, un nombre de clients par jour que vous modulez en tenant compte de 2 variables fondamentales : la saisonnalit\u00e9 et surtout le temps de la mont\u00e9e en charge. Vous pouvez gr\u00e2ce au contexte actuel mesurer la prise de risques et envisager les circonstances impr\u00e9vues et rechercher des solutions qui vous permettront de changer de strat\u00e9gie en cas d\u2019obligation gouvernementale (terrasse chauff\u00e9e ou non, click and collect.<\/p>\n\n\n\n<p><strong>Mettez les \u00e9l\u00e9ments r\u00e9colt\u00e9s en chiffres \u00e0 travers le pr\u00e9visionnel financier<\/strong><\/p>\n\n\n\n<p>Il se compose de 3 tableaux essentiels, li\u00e9s entre eux et qui illustrent votre sc\u00e9nario. Mobilisez coh\u00e9rence et bon sens !<\/p>\n\n\n\n<p>\u2013 \u00e0 travers le plan de financement, vous chiffrez les besoins pour d\u00e9marrer (investissements, stocks et tr\u00e9sorerie) et obtenez les ressources \u00e0 mobiliser pour d\u00e9marrer (apports, pr\u00eat d\u2019honneur, investisseurs et pr\u00eat bancaire) ;<\/p>\n\n\n\n<p>\u2013 Par le compte d\u2019exploitation, vous mesurez les conditions de rentabilit\u00e9 du projet : le chiffre d\u2019affaires de l\u2019ann\u00e9e<\/p>\n\n\n\n<p>\u2013 les charges d\u2019exploitation ;<\/p>\n\n\n\n<p>\u2013 Le tableau de tr\u00e9sorerie indique chaque mois l\u2019\u00e9tat de votre compte en banque (les encaissements<\/p>\n\n\n\n<p>\u2013 les d\u00e9caissements).<\/p>\n\n\n\n<p>Attention, ne minimisez pas le facteur temps, vorace en tr\u00e9sorerie. Lorsque vous cr\u00e9ez une entreprise, vous partez de z\u00e9ro ou presque. En d\u00e9finitive, vous validez, sur le papier, la faisabilit\u00e9 et la p\u00e9rennit\u00e9 de votre projet. Cet argumentaire vous permet de <a href=\"https:\/\/www.dynamique-mag.com\/article\/quels-sont-les-leviers-pour-seduire-les-investisseurs.5977\">convaincre investisseurs<\/a> et banquiers ; et il devient, une fois la soci\u00e9t\u00e9 cr\u00e9\u00e9e, votre plan de route que vous ne cesserez d\u2019amender. Quoiqu\u2019il en soit, le dossier doit \u00eatre synth\u00e9tique, complet et reli\u00e9 par une coh\u00e9rence d\u2019ensemble. Il ne faut jamais oublier que les investisseurs savent appr\u00e9hender rapidement les failles d\u2019un projet ou bien s\u00fbr les opportunit\u00e9s. Il faudra que ce business plan vous permette de r\u00e9pondre \u00e0 toutes les questions.<\/p>\n\n\n\n<p><strong>Dynamique entrepreneuriale<\/strong><\/p>\n\n\n\n<h1 class=\"wp-block-heading\">&nbsp;<\/h1>\n\n\n\n<h1 class=\"wp-block-heading\">&nbsp;<\/h1>\n","protected":false},"excerpt":{"rendered":"<p>Trop souvent, le business plan est vu par le cr\u00e9ateur d\u2019entreprise comme une obligation administrative, sous la forme de tableaux<\/p>\n","protected":false},"author":1,"featured_media":2564,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,4,6],"tags":[],"class_list":["post-2563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avis-dexpert","category-business","category-contribution"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Business plan : les erreurs \u00e0 ne pas commettre - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Business plan : les erreurs \u00e0 ne pas commettre - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"Trop souvent, le business plan est vu par le cr\u00e9ateur d\u2019entreprise comme une obligation administrative, sous la forme de tableaux\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-14T15:07:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/images.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"290\" \/>\n\t<meta property=\"og:image:height\" content=\"174\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/14\\\/business-plan-les-erreurs-a-ne-pas-commettre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/14\\\/business-plan-les-erreurs-a-ne-pas-commettre\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Business plan : les erreurs \u00e0 ne pas commettre\",\"datePublished\":\"2021-04-14T15:07:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/14\\\/business-plan-les-erreurs-a-ne-pas-commettre\\\/\"},\"wordCount\":607,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/14\\\/business-plan-les-erreurs-a-ne-pas-commettre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/images.jpg\",\"articleSection\":[\"AVIS D'EXPERT\",\"BUSINESS\",\"CONTACT\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/14\\\/business-plan-les-erreurs-a-ne-pas-commettre\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/14\\\/business-plan-les-erreurs-a-ne-pas-commettre\\\/\",\"name\":\"Business plan : les erreurs \u00e0 ne pas commettre - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/14\\\/business-plan-les-erreurs-a-ne-pas-commettre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/14\\\/business-plan-les-erreurs-a-ne-pas-commettre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/images.jpg\",\"datePublished\":\"2021-04-14T15:07:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/14\\\/business-plan-les-erreurs-a-ne-pas-commettre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/14\\\/business-plan-les-erreurs-a-ne-pas-commettre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/14\\\/business-plan-les-erreurs-a-ne-pas-commettre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/images.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/images.jpg\",\"width\":290,\"height\":174},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/14\\\/business-plan-les-erreurs-a-ne-pas-commettre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Business plan : les erreurs \u00e0 ne pas commettre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Business plan : les erreurs \u00e0 ne pas commettre - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/","og_locale":"fr_FR","og_type":"article","og_title":"Business plan : les erreurs \u00e0 ne pas commettre - REUSSITE INFO","og_description":"Trop souvent, le business plan est vu par le cr\u00e9ateur d\u2019entreprise comme une obligation administrative, sous la forme de tableaux","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/","og_site_name":"REUSSITE INFO","article_published_time":"2021-04-14T15:07:45+00:00","og_image":[{"width":290,"height":174,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/images.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Business plan : les erreurs \u00e0 ne pas commettre","datePublished":"2021-04-14T15:07:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/"},"wordCount":607,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/images.jpg","articleSection":["AVIS D'EXPERT","BUSINESS","CONTACT"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/","name":"Business plan : les erreurs \u00e0 ne pas commettre - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/images.jpg","datePublished":"2021-04-14T15:07:45+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/images.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/images.jpg","width":290,"height":174},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/14\/business-plan-les-erreurs-a-ne-pas-commettre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Business plan : les erreurs \u00e0 ne pas commettre"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=2563"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2563\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/2564"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=2563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=2563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=2563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}