{"id":2498,"date":"2021-04-02T12:34:49","date_gmt":"2021-04-02T12:34:49","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=2498"},"modified":"2021-04-02T12:34:49","modified_gmt":"2021-04-02T12:34:49","slug":"mali-partage-dexperiences-en-communication-et-leadership","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/","title":{"rendered":"Mali: Partage d&rsquo;exp\u00e9riences en communication et leadership"},"content":{"rendered":"\n<p>L\u2019amphith\u00e9\u00e2tre de 500 places de l\u2019Universit\u00e9 de S\u00e9gou a abrit\u00e9 le week-end dernier, le 7\u00e8 num\u00e9ro de l\u2019espace leadership. Ce cadre hebdomadaire d\u2019activit\u00e9s p\u00e9dagogiques et d\u2019\u00e9panouissement regroupant les \u00e9tudiants, les enseignants et les administrateurs a \u00e9t\u00e9 instaur\u00e9 par la Facult\u00e9 des sciences sociales (FASSO). Il vise \u00e0 favoriser le partage d\u2019exp\u00e9riences et de connaissances \u00e0 travers une conf\u00e9rence anim\u00e9e par un th\u00e9oricien ou praticien qui accepte volontiers de partager son savoir et savoir-\u00eatre avec la jeunesse estudiantine.<br><br>Le directeur g\u00e9n\u00e9ral sortant de l\u2019Office de radio et t\u00e9l\u00e9vision du Mali (Ortm), Salif Sanogo \u00e9tait l\u2019invit\u00e9 d\u2019honneur de cette conf\u00e9rence. Les \u00e9changes avec les \u00e9tudiants de l\u2019Universit\u00e9 de S\u00e9gou se sont articul\u00e9s autour de la th\u00e9matique : \u00abCommunication et leadership\u00bb. Avant d\u2019entrer dans le vif du sujet, une minute de silence a \u00e9t\u00e9 observ\u00e9e en la m\u00e9moire de nos soldats tomb\u00e9s sur le champ de bataille. Dans son intervention, Salif Sanogo a indiqu\u00e9 qu\u2019\u00e0 l\u2019heure de la dictature des r\u00e9seaux sociaux, de l\u2019explosion des fake news et dans un contexte de pr\u00e9dominance du pr\u00eat \u00e0 consommer o\u00f9 chacun cherche \u00e0 diss\u00e9miner sa pens\u00e9e, la question qui se pose est de savoir comment on peut construire un monde meilleur par la communication et le leadership.<br><br>\u00c0 en croire le conf\u00e9rencier, l\u2019aspect communication sous-tend fortement le leadership. Salif Sanogo a d\u00e9fini la communication comme l\u2019action d\u2019\u00e9changer et d\u2019informer. Selon lui, un leader sans communication n\u2019est absolument rien, ajoutant qu\u2019il doit avoir un message adapt\u00e9, clair et net qui atteint sa cible. Salif Sanogo a, en substance, soulign\u00e9 qu\u2019un leader doit \u00eatre un bon orateur. Un leader est suivi par les autres non pas pour sa personne, mais pour les valeurs qu\u2019il incarne et son exemplarit\u00e9. \u00c0 ce propos, Salif Sanogo a \u00e9voqu\u00e9 quelques champions de la nouvelle \u00e9conomie \u00e0 savoir Elon Musk et Steve Jobs qui ne sont pas suivis pour leurs traits de personnalit\u00e9, mais pour les valeurs de cr\u00e9ativit\u00e9 et d\u2019innovation qu\u2019ils partagent. Le conf\u00e9rencier a aussi cit\u00e9 trois exemples de leaders historiques qui, par leur r\u00f4le moteur dans le d\u00e9veloppement de la soci\u00e9t\u00e9, ont fait preuve de courage, de comp\u00e9tence et de patriotisme durant leurs parcours. Il s\u2019agit de Winston Churchill, Nelson Mandela et Abraham Lincoln. Pour le conf\u00e9rencier, la vision, l\u2019ouverture d\u2019esprit, l\u2019exemplarit\u00e9, la coh\u00e9rence avec les valeurs et les convictions, l\u2019intelligence pluridisciplinaire sont les principaux \u00e9l\u00e9ments qui caract\u00e9risent un leader.<br><br>\u00abLa confiance en soi est essentielle pour pouvoir ensuite donner confiance \u00e0 autrui\u00bb, a-t-il ajout\u00e9. Au terme de cet expos\u00e9 enrichissant, Salif Sanogo a apport\u00e9 des \u00e9l\u00e9ments de r\u00e9ponse aux questions des \u00e9tudiants ayant trait \u00e0 la communication et la gestion de crise ainsi que le r\u00f4le de l\u2019informatique dans la communication.<br>Le recteur de l\u2019Universit\u00e9 de S\u00e9gou a chaleureusement remerci\u00e9 le conf\u00e9rencier pour les efforts patriotiques combien importants qu\u2019il a consentis \u00e0 l\u2019occasion de ce cadre universitaire et p\u00e9dagogique. Esaii Daou a rappel\u00e9 que l\u2019Universit\u00e9 est avant tout un haut lieu de construction et de d\u00e9veloppement de la personnalit\u00e9 des apprenants.<br><br>Il a estim\u00e9 que les \u00e9tudiants ont d\u00e9sormais la possibilit\u00e9 de renforcer et d\u2019accro\u00eetre leurs capacit\u00e9s en permanence aupr\u00e8s des experts de tous les horizons, avant d\u2019ajouter que la pr\u00e9sence de personnalit\u00e9s de haut niveau telles que le directeur g\u00e9n\u00e9ral sortant de l\u2019Ortm est une marque d\u2019estime pour les \u00e9tudiants qui sont form\u00e9s \u00e0 affronter les r\u00e9alit\u00e9s du march\u00e9 de l\u2019emploi.<\/p>\n\n\n\n<p><strong>Mamadou S<\/strong>Y<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019amphith\u00e9\u00e2tre de 500 places de l\u2019Universit\u00e9 de S\u00e9gou a abrit\u00e9 le week-end dernier, le 7\u00e8 num\u00e9ro de l\u2019espace leadership. Ce<\/p>\n","protected":false},"author":1,"featured_media":2499,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,6],"tags":[],"class_list":["post-2498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecole","category-contribution"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali: Partage d&#039;exp\u00e9riences en communication et leadership - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali: Partage d&#039;exp\u00e9riences en communication et leadership - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"L\u2019amphith\u00e9\u00e2tre de 500 places de l\u2019Universit\u00e9 de S\u00e9gou a abrit\u00e9 le week-end dernier, le 7\u00e8 num\u00e9ro de l\u2019espace leadership. Ce\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-02T12:34:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/segou.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"504\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/02\\\/mali-partage-dexperiences-en-communication-et-leadership\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/02\\\/mali-partage-dexperiences-en-communication-et-leadership\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali: Partage d&rsquo;exp\u00e9riences en communication et leadership\",\"datePublished\":\"2021-04-02T12:34:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/02\\\/mali-partage-dexperiences-en-communication-et-leadership\\\/\"},\"wordCount\":645,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/02\\\/mali-partage-dexperiences-en-communication-et-leadership\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/segou.jpg\",\"articleSection\":[\"ACTIVITES\",\"CONTACT\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/02\\\/mali-partage-dexperiences-en-communication-et-leadership\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/02\\\/mali-partage-dexperiences-en-communication-et-leadership\\\/\",\"name\":\"Mali: Partage d'exp\u00e9riences en communication et leadership - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/02\\\/mali-partage-dexperiences-en-communication-et-leadership\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/02\\\/mali-partage-dexperiences-en-communication-et-leadership\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/segou.jpg\",\"datePublished\":\"2021-04-02T12:34:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/02\\\/mali-partage-dexperiences-en-communication-et-leadership\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/02\\\/mali-partage-dexperiences-en-communication-et-leadership\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/02\\\/mali-partage-dexperiences-en-communication-et-leadership\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/segou.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/segou.jpg\",\"width\":750,\"height\":504},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/04\\\/02\\\/mali-partage-dexperiences-en-communication-et-leadership\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali: Partage d&rsquo;exp\u00e9riences en communication et leadership\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali: Partage d'exp\u00e9riences en communication et leadership - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali: Partage d'exp\u00e9riences en communication et leadership - REUSSITE INFO","og_description":"L\u2019amphith\u00e9\u00e2tre de 500 places de l\u2019Universit\u00e9 de S\u00e9gou a abrit\u00e9 le week-end dernier, le 7\u00e8 num\u00e9ro de l\u2019espace leadership. Ce","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/","og_site_name":"REUSSITE INFO","article_published_time":"2021-04-02T12:34:49+00:00","og_image":[{"width":750,"height":504,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/segou.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali: Partage d&rsquo;exp\u00e9riences en communication et leadership","datePublished":"2021-04-02T12:34:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/"},"wordCount":645,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/segou.jpg","articleSection":["ACTIVITES","CONTACT"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/","name":"Mali: Partage d'exp\u00e9riences en communication et leadership - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/segou.jpg","datePublished":"2021-04-02T12:34:49+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/segou.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/04\/segou.jpg","width":750,"height":504},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/04\/02\/mali-partage-dexperiences-en-communication-et-leadership\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali: Partage d&rsquo;exp\u00e9riences en communication et leadership"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=2498"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/2499"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=2498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=2498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=2498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}