{"id":2490,"date":"2021-03-29T04:13:18","date_gmt":"2021-03-29T04:13:18","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=2490"},"modified":"2021-03-29T04:13:18","modified_gmt":"2021-03-29T04:13:18","slug":"mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/","title":{"rendered":"Mali: INTEC SUP a organis\u00e9 la soutenance de m\u00e9moire des \u00e9tudiants"},"content":{"rendered":"\n<p><em>L\u2019Institut Sup\u00e9rieur des Techniques Economiques, Comptables et Commerciales (INTEC SUP) a proc\u00e9d\u00e9 ce samedi 27 mars 2021, \u00e0 son si\u00e8ge sis \u00e0 l\u2019ACI 2000, \u00e0 l\u2019organisation de la c\u00e9r\u00e9monie de soutenance de m\u00e9moire des \u00e9tudiants en fin de cycle.<\/em> Ce sont 14 \u00e9tudiants qui ont pass\u00e9 2 ans de formation en Master, et qui se retrouvent dans une situation o\u00f9 ils doivent d\u00e9fendre des projets de fin de cycle de formation en master 2.<em><\/em><\/p>\n\n\n\n<p>Ces soutenances s&rsquo;inscrivent dans une dynamique de cons\u00e9cration pour L\u2019INTEC SUP. C\u2019est donc une opportunit\u00e9 pour ces 14 \u00e9tudiants de s&rsquo;illustrer, non dans l&rsquo;optique de vouloir faire une force de d\u00e9monstration, mais de justifier leurs acquis devant un comit\u00e9 de jury, compos\u00e9 d&rsquo;\u00e9minents professeurs et professionnels, qui ont pour mission de juger de la pertinence des diff\u00e9rents travaux d&rsquo;\u00e9tudes.<\/p>\n\n\n\n<p>Les diff\u00e9rents th\u00e8mes de m\u00e9moires sont issus des fili\u00e8res de comptabilit\u00e9-contr\u00f4le &#8211; audit, de management \u2013communication- marketing, du GRH-EGP, ainsi que des sciences politiques et relations internationales.<\/p>\n\n\n\n<p>&nbsp;Le secr\u00e9taire g\u00e9n\u00e9ral de L\u2019INTEC SUP, Khalid DEMBELE nous \u00e9num\u00e8re les 3 objectifs majeurs qui sous tendent la mise en organisation de cette soutenance. \u00ab&nbsp;<em>Le premier objectif permet aux \u00e9tudiants de s&rsquo;auto \u00e9valuer sur la formation re\u00e7ue pendant les 2 ann\u00e9es en classe de Master 1 et 2. Le 2eme objectif est une opportunit\u00e9 de communiquer, sur la qualit\u00e9 de service que nous offrons ici \u00e0 INTEC SUP. En effet, Depuis 2 ans, INTEC SUP a fait le choix d\u2019aller vers le processus de qualit\u00e9 via les normes internationales \u00e0 savoir le Conseil Africain et Malgache pour l\u2019Enseignement Secondaire (CAMES). Ce que fait aujourd&rsquo;hui qu\u2019on se retrouve dans une situation, o\u00f9 il faut communiquer sur cette qualit\u00e9. Le 3eme objectif est que ces soutenances organis\u00e9es, communiquent sur le processus de qualit\u00e9 auquel nous sommes en train d&rsquo;instaurer au sein de notre Institut. Il faudra reconna\u00eetre que L&rsquo;INTEC SUP est en phase de croissance, pour cela, il faut d\u00e9montrer, en quoi nous formons des bons produits chez nous&nbsp;<\/em>\u00bb a expliqu\u00e9 Khalid DEMBELE.<\/p>\n\n\n\n<p>Pour l\u2019\u00e9tudiant en master 2, Issouf&nbsp; Issa MAIGA, qui a soutenu en Droit Public G\u00e9n\u00e9ral, option Relation Internationale, il a choisi de traiter sur l&rsquo;implication des leaders religieux dans la politique: cas du Mali.&nbsp;\u00ab&nbsp;Vu la situation que le Mali traverse en ce moment, je me dis&nbsp; qu\u2019il faut un th\u00e8me d&rsquo;actualit\u00e9 pour minimiser l&rsquo;impact des leaders religieux dans les prises de d\u00e9cision des nos autorit\u00e9s politiques \u00bb a justifi\u00e9 Issouf&nbsp; Issa MAIGA.<\/p>\n\n\n\n<p>A noter que le&nbsp; m\u00e9moire est un travail \u00e0 caract\u00e8re intellectuel et scientifique r\u00e9alis\u00e9 par un \u00e9tudiant au terme de sa carri\u00e8re estudiantine. Pour cela, l\u2019\u00e9tudiant doit \u00eatre totalement suivi dans son travail par son directeur de m\u00e9moire qui l\u2019aide \u00e0 choisir ou \u00e0 bien choisir le sujet.<\/p>\n\n\n\n<p><strong>Maria RAMAROSON<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/reussiteinfo.com\/wp-content\/uploads\/2021\/03\/intec-Khalid-Dembele.jpg\" alt=\"\" class=\"wp-image-2492\" srcset=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/intec-Khalid-Dembele.jpg 1024w, https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/intec-Khalid-Dembele-300x225.jpg 300w, https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/intec-Khalid-Dembele-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/reussiteinfo.com\/wp-content\/uploads\/2021\/03\/IMG_20210327_104935.jpg\" alt=\"\" class=\"wp-image-2493\" srcset=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/IMG_20210327_104935.jpg 1024w, https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/IMG_20210327_104935-300x225.jpg 300w, https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/IMG_20210327_104935-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Institut Sup\u00e9rieur des Techniques Economiques, Comptables et Commerciales (INTEC SUP) a proc\u00e9d\u00e9 ce samedi 27 mars 2021, \u00e0 son si\u00e8ge<\/p>\n","protected":false},"author":1,"featured_media":2491,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2490","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecole"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali: INTEC SUP a organis\u00e9 la soutenance de m\u00e9moire des \u00e9tudiants - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali: INTEC SUP a organis\u00e9 la soutenance de m\u00e9moire des \u00e9tudiants - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"L\u2019Institut Sup\u00e9rieur des Techniques Economiques, Comptables et Commerciales (INTEC SUP) a proc\u00e9d\u00e9 ce samedi 27 mars 2021, \u00e0 son si\u00e8ge\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-29T04:13:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/INTEc-SUP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/29\\\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/29\\\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali: INTEC SUP a organis\u00e9 la soutenance de m\u00e9moire des \u00e9tudiants\",\"datePublished\":\"2021-03-29T04:13:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/29\\\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\\\/\"},\"wordCount\":513,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/29\\\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/INTEc-SUP.jpg\",\"articleSection\":[\"ACTIVITES\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/29\\\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/29\\\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\\\/\",\"name\":\"Mali: INTEC SUP a organis\u00e9 la soutenance de m\u00e9moire des \u00e9tudiants - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/29\\\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/29\\\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/INTEc-SUP.jpg\",\"datePublished\":\"2021-03-29T04:13:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/29\\\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/29\\\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/29\\\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/INTEc-SUP.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/INTEc-SUP.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/29\\\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali: INTEC SUP a organis\u00e9 la soutenance de m\u00e9moire des \u00e9tudiants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali: INTEC SUP a organis\u00e9 la soutenance de m\u00e9moire des \u00e9tudiants - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali: INTEC SUP a organis\u00e9 la soutenance de m\u00e9moire des \u00e9tudiants - REUSSITE INFO","og_description":"L\u2019Institut Sup\u00e9rieur des Techniques Economiques, Comptables et Commerciales (INTEC SUP) a proc\u00e9d\u00e9 ce samedi 27 mars 2021, \u00e0 son si\u00e8ge","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/","og_site_name":"REUSSITE INFO","article_published_time":"2021-03-29T04:13:18+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/INTEc-SUP.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali: INTEC SUP a organis\u00e9 la soutenance de m\u00e9moire des \u00e9tudiants","datePublished":"2021-03-29T04:13:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/"},"wordCount":513,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/INTEc-SUP.jpg","articleSection":["ACTIVITES"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/","name":"Mali: INTEC SUP a organis\u00e9 la soutenance de m\u00e9moire des \u00e9tudiants - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/INTEc-SUP.jpg","datePublished":"2021-03-29T04:13:18+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/INTEc-SUP.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/INTEc-SUP.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/29\/mali-intec-sup-a-organise-la-soutenance-de-memoire-des-etudiants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali: INTEC SUP a organis\u00e9 la soutenance de m\u00e9moire des \u00e9tudiants"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=2490"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2490\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/2491"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=2490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=2490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=2490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}