{"id":2437,"date":"2021-03-09T13:14:07","date_gmt":"2021-03-09T13:14:07","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=2437"},"modified":"2021-03-09T13:14:07","modified_gmt":"2021-03-09T13:14:07","slug":"mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/","title":{"rendered":"Mali: interview de SISSOKO Coumba SIDIBE, sur sa passion de femme chauffeur"},"content":{"rendered":"\n<p>\u00c0 l&rsquo;occasion de la c\u00e9l\u00e9bration de la f\u00eate de 08 mars 2021, sur le \u00ab\u2009Leadership f\u00e9minin pour un futur \u00e9galitaire dans le monde de la Covid-19 \u00bb, le Mali, \u00e0 l\u2019instar de la communaut\u00e9 internationale, a c\u00e9l\u00e8br\u00e9 les efforts consid\u00e9rables d\u00e9ploy\u00e9s par les femmes et les filles partout dans le monde, pour fa\u00e7onner un futur et une relance plus \u00e9galitaire, suite \u00e0 la pand\u00e9mie de Covid-19. Votre journal \u00ab&nbsp;La R\u00e9ussite Mali&nbsp;\u00bb &nbsp;a rencontr\u00e9 Mme SISSOKO Coumba SIDIBE. Elle fait du volontariat dans le domaine de la conduite de v\u00e9hicule professionnel. C\u2019\u00e9tait au Centre National pour la Promotion du Volontariat ( CNPV )<\/p>\n\n\n\n<p>&nbsp;<strong>Le journal \u00ab&nbsp;La R\u00e9ussite Mali&nbsp;\u00bb<\/strong> <strong>: Veuillez-vous pr\u00e9senter s\u2019il vous plait&nbsp;?<\/strong><\/p>\n\n\n\n<p><strong>Mme SISSOKO Coumba SIDIBE :&nbsp;<\/strong>Je suis mari\u00e9e, m\u00e8re de deux enfants. J&rsquo;ai un dipl\u00f4me en droit des affaires et une licence en communication des entreprises. Je suis aussi formatrice en entrepreneuriat.<\/p>\n\n\n\n<p><strong>Le journal \u00ab&nbsp;La R\u00e9ussite Mali&nbsp;\u00bb<\/strong><strong>: Quelles sont vos motivations en ce moment&nbsp;?<\/strong><\/p>\n\n\n\n<p><strong>Mme SISSOKO Coumba SIDIBE:&nbsp;<\/strong>Ma premi\u00e8re motivation est de servir mon pays. Je vais apporter ma pierre \u00e0 l&rsquo;\u00e9difice national pour la construction de ce pays.&nbsp; Ma deuxi\u00e8me motivation est le sentiment d&rsquo;accomplissement de mes ambitions qui date depuis des ann\u00e9es.&nbsp;<\/p>\n\n\n\n<p><strong>Le journal \u00ab&nbsp;La R\u00e9ussite Mali&nbsp;\u00bb<\/strong><strong>: Comment avez-vous connu le CNPV&nbsp;?<\/strong>&nbsp;<\/p>\n\n\n\n<p><strong>Mme SISSOKO Coumba SIDIBE:&nbsp;<\/strong>Mon mari est venu me parler que le centre national pour la promotion du volontariat est \u00e0 la recherche d\u2019un chauffeur. Du coup, je me suis dite, pourquoi ne pas postuler, parce que conduire a toujours \u00e9t\u00e9 ma passion. Donc, c\u2019est dans cette perspective que je suis venue d\u00e9poser ma candidature.&nbsp;<\/p>\n\n\n\n<p><strong>Le journal \u00ab&nbsp;La R\u00e9ussite Mali&nbsp;\u00bb<\/strong><strong>: &nbsp;Quel est votre dernier mot&nbsp;?<\/strong><\/p>\n\n\n\n<p><strong>Mme SISSOKO Coumba SIDIBE:&nbsp;<\/strong>Je suis heureuse et fi\u00e8re, parce que j&rsquo;ai accompli une de mes ambitions, qui est d&rsquo;\u00eatre conductrice professionnelle. Je suis heureuse, je suis fi\u00e8re de moi. Les gens s&rsquo;\u00e9tonnent de voir une femme d&rsquo;\u00eatre chauffeur avec tous les dipl\u00f4mes et formation en plus volontaire. Mais moi, je les dis ce que les hommes peuvent faire et les femmes peuvent le faire. Donc il n&rsquo;y a pas de diff\u00e9rence chez moi, c&rsquo;est la parit\u00e9, l&rsquo;\u00e9galit\u00e9 du genre.&nbsp;<\/p>\n\n\n\n<p>Le message que je lance aux autres femmes, est de se battre pour ce qu&rsquo;elles veulent r\u00e9ellement, se fixer des objectifs et se donner les moyens de les atteindre, \u00eatre toujours ambitieuses. Dans la vie, quand on n&rsquo;a pas d&rsquo;ambition, c&rsquo;est z\u00e9ro.&nbsp;<\/p>\n\n\n\n<p><strong>REACTION DES TEMOINS<\/strong><\/p>\n\n\n\n<p><strong>Ibrahim BAH : Charg\u00e9 de communication du Centre national pour la Promotion du Volontariat&nbsp;<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/reussiteinfo.com\/wp-content\/uploads\/2021\/03\/cnpg-1.jpg\" alt=\"\" class=\"wp-image-2444\" srcset=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/cnpg-1.jpg 1024w, https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/cnpg-1-300x225.jpg 300w, https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/cnpg-1-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"blob:https:\/\/www.lareussiteinfo.com\/735e20d6-3e4e-4adf-90da-0dd43ac1f02c\" alt=\"\"\/><\/figure>\n\n\n\n<p>Mes impressions par rapport \u00e0 Coumba SIDIBE, sont des sentiments de joie, de voir une dame si brave, s&rsquo;engager comme une femme chauffeur. Ce n&rsquo;est pas tout le temps, qu&rsquo;on voit \u00e7a. On a lanc\u00e9 l&rsquo;appel \u00e0 candidature pour le compte d&rsquo;un chauffeur. Et elle a d\u00e9pos\u00e9 ses dossiers. Au moment de s\u00e9lection, on a vu les dossiers d\u2019une dame, on n&rsquo;en croyait pas, mais quand on l&rsquo;a appel\u00e9e pour l&rsquo;interview, elle est venue. Vraiment, on sentait qu&rsquo;elle est motiv\u00e9e et c&rsquo;est une passion pour elle. Je ne peux que l&rsquo;encourager dans cette voie et plein succ\u00e8s \u00e0 Coumba. Ce n&rsquo;est pas un emploi, c&rsquo;est du volontariat. Le volontariat, c&rsquo;est 2 ans non renouvelable, mais pendant ces 2 ans, elle aura la possibilit\u00e9 de faire ce qu&rsquo;elle voulait, il y a tr\u00e8s longtemps. Il s&rsquo;agit aussi de son mari qui a vraiment accept\u00e9 que sa femme puisse faire ce boulot de chauffeur. Conduire les hommes, n&rsquo;est pas facile surtout dans notre soci\u00e9t\u00e9.&nbsp;<\/p>\n\n\n\n<p><strong>Mme TRAORE Assitan DIAWARA, assistante comptable au centre national pour la promotion du volontariat<\/strong><\/p>\n\n\n\n<p>\u00c7a me va droit au c\u0153ur, je suis fi\u00e8re. Il n&rsquo;y a pas de diff\u00e9rence entre une femme et un homme. Tous ceux que les hommes peuvent faire, les femmes peuvent les faire aussi. Donc je ne peux que la f\u00e9liciter de la d\u00e9cision qu&rsquo;elle a prise. Je l&rsquo;encourage dans son ambition. Je sais que dans notre soci\u00e9t\u00e9, ce n&rsquo;est facile de voir une femme chauffeur. Avec tout \u00e7a, elle a eu le courage de le faire. Donc je la f\u00e9licite, bon vent, bon courage dans son nouveau travail. Dans notre soci\u00e9t\u00e9, \u00e7a peut porter beaucoup de pr\u00e9judices. Le fait d\u2019\u00eatre toujours avec les hommes, conduire les hommes, cela am\u00e8ne les gens \u00e0 penser \u00e0 beaucoup de choses, surtout une femme mari\u00e9e. Il faut avoir un homme compr\u00e9hensible pour comprendre \u00e7a. Donc, ce n&rsquo;est pas facile.<\/p>\n\n\n\n<p><strong>Propos recueilli Joseph SISSOKO<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><\/td><td><\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 l&rsquo;occasion de la c\u00e9l\u00e9bration de la f\u00eate de 08 mars 2021, sur le \u00ab\u2009Leadership f\u00e9minin pour un futur \u00e9galitaire<\/p>\n","protected":false},"author":1,"featured_media":2442,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali: interview de SISSOKO Coumba SIDIBE, sur sa passion de femme chauffeur - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali: interview de SISSOKO Coumba SIDIBE, sur sa passion de femme chauffeur - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"\u00c0 l&rsquo;occasion de la c\u00e9l\u00e9bration de la f\u00eate de 08 mars 2021, sur le \u00ab\u2009Leadership f\u00e9minin pour un futur \u00e9galitaire\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-09T13:14:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/cnpn-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"499\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/09\\\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/09\\\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali: interview de SISSOKO Coumba SIDIBE, sur sa passion de femme chauffeur\",\"datePublished\":\"2021-03-09T13:14:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/09\\\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\\\/\"},\"wordCount\":843,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/09\\\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cnpn-1.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/09\\\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/09\\\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\\\/\",\"name\":\"Mali: interview de SISSOKO Coumba SIDIBE, sur sa passion de femme chauffeur - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/09\\\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/09\\\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cnpn-1.jpg\",\"datePublished\":\"2021-03-09T13:14:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/09\\\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/09\\\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/09\\\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cnpn-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cnpn-1.jpg\",\"width\":768,\"height\":499},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/03\\\/09\\\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali: interview de SISSOKO Coumba SIDIBE, sur sa passion de femme chauffeur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali: interview de SISSOKO Coumba SIDIBE, sur sa passion de femme chauffeur - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali: interview de SISSOKO Coumba SIDIBE, sur sa passion de femme chauffeur - REUSSITE INFO","og_description":"\u00c0 l&rsquo;occasion de la c\u00e9l\u00e9bration de la f\u00eate de 08 mars 2021, sur le \u00ab\u2009Leadership f\u00e9minin pour un futur \u00e9galitaire","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/","og_site_name":"REUSSITE INFO","article_published_time":"2021-03-09T13:14:07+00:00","og_image":[{"width":768,"height":499,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/cnpn-1.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali: interview de SISSOKO Coumba SIDIBE, sur sa passion de femme chauffeur","datePublished":"2021-03-09T13:14:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/"},"wordCount":843,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/cnpn-1.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/","name":"Mali: interview de SISSOKO Coumba SIDIBE, sur sa passion de femme chauffeur - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/cnpn-1.jpg","datePublished":"2021-03-09T13:14:07+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/cnpn-1.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/03\/cnpn-1.jpg","width":768,"height":499},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/03\/09\/mali-interview-de-sissoko-coumba-sidibe-sur-sa-passion-de-femme-chauffeur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali: interview de SISSOKO Coumba SIDIBE, sur sa passion de femme chauffeur"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=2437"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2437\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/2442"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=2437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=2437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=2437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}