{"id":2309,"date":"2021-02-15T15:12:20","date_gmt":"2021-02-15T15:12:20","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=2309"},"modified":"2021-02-15T15:12:20","modified_gmt":"2021-02-15T15:12:20","slug":"malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/","title":{"rendered":"Mali:Le gouvernement d\u00e9termin\u00e9 \u00e0 trouver des solutions aux probl\u00e8mes des commer\u00e7ants d\u00e9taillants"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">La chambre du commerce et d&rsquo;industrie du Mali (CCIM) a servi de cadre \u00e0 une rencontre d\u2019\u00e9change, entre le ministre de l\u2019Industrie, du&nbsp;Commerce et de la&nbsp;Promotion des investissements, Arouna NIANG, les commer\u00e7ants d\u00e9taillants et les directeurs des Centres de Gestion Agr\u00e9\u00e9s (CGA), le jeudi 11 f\u00e9vrier 2021. C\u2019\u00e9tait en pr\u00e9sence du pr\u00e9sident de la CCIM, Youssouf BATHILY et la pr\u00e9sidente de l\u2019Ordre des Experts Comptables et Comptables Agr\u00e9\u00e9s du Mali (ONECCA), Mme SIDIBE Fatoumata CISSE.<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">&nbsp;<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Cette rencontre a pour objectif&nbsp; de trouver des solutions aux pr\u00e9occupations des commer\u00e7ants d\u00e9taillants et partant, celles d\u2019autres corps de m\u00e9tiers, qui sont confront\u00e9s \u00e0 de s\u00e9rieuses difficult\u00e9s.<\/h3>\n\n\n\n<p>A cette occasion, le pr\u00e9sident de la CCIM, Youssouf BATHILY a remerci\u00e9 les plus hautes autorit\u00e9s de la Transition pour avoir mis en place depuis 2018 et ce jusqu\u2019en 2022, le Projet de Formalisation des Acteurs du Commerce de D\u00e9tail (PROFAC). \u00ab<em>A cet effet, nous esp\u00e9rons que le PROFAC va rapidement, sous l\u2019autorit\u00e9 de notre ministre de tutelle, atteindre sa vitesse de croisi\u00e8re pour le plus grand b\u00e9n\u00e9fice des commer\u00e7ants d\u00e9taillants sur l\u2019ensemble du territoire national&nbsp;<strong>\u00bb,<\/strong><\/em>s\u2019est r\u00e9joui le pr\u00e9sident &nbsp;BATHILY.<\/p>\n\n\n\n<p>Selon la pr\u00e9sidente de l\u2019Ordre des Experts Comptables et Comptables Agr\u00e9\u00e9s du Mali (ONECCA), Mme SIDIBE Fatoumata CISSE, les premiers Centres de Gestion Agr\u00e9\u00e9s(CGA), 18 au total, ont \u00e9t\u00e9 cr\u00e9\u00e9s \u00e0 la faveur du Projet d\u2019Appui aux Commer\u00e7ants D\u00e9taillants (PACD). Le bilan mitig\u00e9 du PACD a conduit le Mali \u00e0 la mise en place du Projet de Formalisation des Acteurs du Commerce de D\u00e9tail (PROFAC).<\/p>\n\n\n\n<p>Le commerce de d\u00e9tail est une composante majeure de l&rsquo;\u00e9conomie malienne, mais la majorit\u00e9 des commer\u00e7ants \u00e9voluent dans l\u2019informel. Toute chose qui les expose aux dangers multiples parfois, les emp\u00eache d&rsquo;\u00e9voluer. L\u2019\u00c9tat qui pr\u00e9tend \u00eatre un grand assistant des commer\u00e7ants d\u00e9taillants ne tire pas grand profit de leurs activit\u00e9s, en raison de non payement d&rsquo;imp\u00f4t. D&rsquo;autre part, les conditions d&rsquo;hygi\u00e8ne et de s\u00e9curit\u00e9 ne sont pas r\u00e9unies. ce qui constituent un frein au commerce de d\u00e9tail. Selon le ministre de l&rsquo;Industrie du Commerce et de la Promotion des Investissements, Harouna NIANG, l&rsquo;\u00c9tat malien veut aider les commer\u00e7ants d\u00e9taillants, mais demande qu&rsquo;ils sortent de l&rsquo;informel, qu\u2019ils s&rsquo;organisent et qu\u2019ils se forment. \u00ab&nbsp;<em>L&rsquo;ambition du gouvernement, c&rsquo;est d&rsquo;am\u00e9nager des infrastructures, pour transformer les secteurs informels en formels pour qu&rsquo;ils puissent contribuer d&rsquo;avantage \u00e0 l&rsquo;\u00e9panouissement de l&rsquo;\u00e9conomie nationale. Le commerce de d\u00e9tail \u00e9tant une \u00e9conomie de proximit\u00e9, est un maillon de l&rsquo;\u00e9conomie familiale au Mali et rend un grand service \u00e0 la nation. Aidez-nous \u00e0 vous aider en sortant de l&rsquo;informel et en vous unissant<\/em>&nbsp;\u00bb, a lanc\u00e9 le Ministre Harouna NIANG, avant d\u2019ajouter que l\u2019union des commer\u00e7ants d\u00e9taillants dans un central d&rsquo;achat est importante pour assainir le milieu des d\u00e9taillants.&nbsp;<\/p>\n\n\n\n<p><strong>Joseph SISSOKO<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La chambre du commerce et d&rsquo;industrie du Mali (CCIM) a servi de cadre \u00e0 une rencontre d\u2019\u00e9change, entre le ministre<\/p>\n","protected":false},"author":1,"featured_media":2310,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mali:Le gouvernement d\u00e9termin\u00e9 \u00e0 trouver des solutions aux probl\u00e8mes des commer\u00e7ants d\u00e9taillants - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali:Le gouvernement d\u00e9termin\u00e9 \u00e0 trouver des solutions aux probl\u00e8mes des commer\u00e7ants d\u00e9taillants - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"La chambre du commerce et d&rsquo;industrie du Mali (CCIM) a servi de cadre \u00e0 une rencontre d\u2019\u00e9change, entre le ministre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-15T15:12:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/02\/ccim.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/02\\\/15\\\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/02\\\/15\\\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Mali:Le gouvernement d\u00e9termin\u00e9 \u00e0 trouver des solutions aux probl\u00e8mes des commer\u00e7ants d\u00e9taillants\",\"datePublished\":\"2021-02-15T15:12:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/02\\\/15\\\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\\\/\"},\"wordCount\":553,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/02\\\/15\\\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/ccim.jpg\",\"articleSection\":[\"BUSINESS\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/02\\\/15\\\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/02\\\/15\\\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\\\/\",\"name\":\"Mali:Le gouvernement d\u00e9termin\u00e9 \u00e0 trouver des solutions aux probl\u00e8mes des commer\u00e7ants d\u00e9taillants - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/02\\\/15\\\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/02\\\/15\\\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/ccim.jpg\",\"datePublished\":\"2021-02-15T15:12:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/02\\\/15\\\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/02\\\/15\\\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/02\\\/15\\\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/ccim.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/ccim.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2021\\\/02\\\/15\\\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali:Le gouvernement d\u00e9termin\u00e9 \u00e0 trouver des solutions aux probl\u00e8mes des commer\u00e7ants d\u00e9taillants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali:Le gouvernement d\u00e9termin\u00e9 \u00e0 trouver des solutions aux probl\u00e8mes des commer\u00e7ants d\u00e9taillants - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali:Le gouvernement d\u00e9termin\u00e9 \u00e0 trouver des solutions aux probl\u00e8mes des commer\u00e7ants d\u00e9taillants - REUSSITE INFO","og_description":"La chambre du commerce et d&rsquo;industrie du Mali (CCIM) a servi de cadre \u00e0 une rencontre d\u2019\u00e9change, entre le ministre","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/","og_site_name":"REUSSITE INFO","article_published_time":"2021-02-15T15:12:20+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/02\/ccim.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Mali:Le gouvernement d\u00e9termin\u00e9 \u00e0 trouver des solutions aux probl\u00e8mes des commer\u00e7ants d\u00e9taillants","datePublished":"2021-02-15T15:12:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/"},"wordCount":553,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/02\/ccim.jpg","articleSection":["BUSINESS"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/","name":"Mali:Le gouvernement d\u00e9termin\u00e9 \u00e0 trouver des solutions aux probl\u00e8mes des commer\u00e7ants d\u00e9taillants - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/02\/ccim.jpg","datePublished":"2021-02-15T15:12:20+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/02\/ccim.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2021\/02\/ccim.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2021\/02\/15\/malile-gouvernement-determine-a-trouver-des-solutions-aux-problemes-des-commercants-detaillants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Mali:Le gouvernement d\u00e9termin\u00e9 \u00e0 trouver des solutions aux probl\u00e8mes des commer\u00e7ants d\u00e9taillants"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=2309"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/2309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/2310"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=2309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=2309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=2309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}