{"id":1954,"date":"2020-10-22T15:49:36","date_gmt":"2020-10-22T15:49:36","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=1954"},"modified":"2020-10-22T15:49:36","modified_gmt":"2020-10-22T15:49:36","slug":"ecole-tous-en-classe","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/","title":{"rendered":"Ecole: Tous en classe !"},"content":{"rendered":"\n<p>En prenant l\u2019Ordonnance n\u00b02020-002\/P-CNSP du 11 septembre 2020, le Comit\u00e9 National pour le Salut du Peuple (CNSP) met un terme au feuilleton de l\u2019application imm\u00e9diate de l\u2019article 39 de la loi n\u00b02018-007 du 16 janvier 2018 portant \u00abstatut du personnel enseignant de l\u2019enseignement secondaire, de l\u2019enseignement fondamental et l\u2019\u00e9ducation pr\u00e9scolaire et sp\u00e9ciale\u00bb, le gouvernement s\u2019engage \u00e0 \u00e9lever la grille indiciaire du statut du personnel de l\u2019enseignement secondaire, de l\u2019enseignement fondamental et de l\u2019\u00e9ducation pr\u00e9scolaire et sp\u00e9ciale.<\/p>\n\n\n\n<p>Les parties, au cours des discussions, sont convenues des points suivants : la signature d\u2019un projet d\u2019ordonnance relatif \u00e0 la modification de Loi n\u00b02020-007 du 16 janvier 2018 ainsi que du projet d\u2019arr\u00eat\u00e9 interminist\u00e9riel relatif \u00e0 la transposition du personnel concern\u00e9 ; l\u2019alignement de l\u2019indice plafond A \u00e0 1 267 sur le salaire du mois de novembre ; le paiement des rappels diff\u00e9rentiels des mois de janvier \u00e0 octobre 2020 sur le salaire du mois de novembre ; le paiement de la premi\u00e8re moiti\u00e9 des arri\u00e9r\u00e9s de 2019 au mois de d\u00e9cembre 2020 ; le paiement des arri\u00e9r\u00e9s de la seconde moiti\u00e9 de 2019 au mois de mars 2021, l\u2019alignement de l\u2019indice plafond de la cat\u00e9gorie A \u00e0 1 382 \u00e0 compter du 1er janvier 2021 ; la reprise effective des cours et activit\u00e9s p\u00e9dagogiques dans les \u00e9coles de l\u2019enseignement secondaire, de l\u2019enseignement fondamental et de l\u2019\u00e9ducation pr\u00e9scolaire et sp\u00e9ciale pour compter du lundi 14 septembre 2020 sur toute l\u2019\u00e9tendue du territoire national.<br>Il faut rappeler qu\u2019une premi\u00e8re n\u00e9gociation entre le Comit\u00e9 National pour le Salut du Peuple et les Syndicats de l\u2019\u00e9ducation signataires du 15 octobre 2016 (SYPESCO, SYNEB, SYNEFCT, SYNESEC, SYLDEF, FENAREC, COSES) s\u2019\u00e9tait sold\u00e9e par un \u00e9chec entrainant une annulation de facto du calendrier des examens pour les classes concern\u00e9es. Cette fois-ci aura donc \u00e9t\u00e9 la bonne pour sortir l\u2019\u00e9cole du gu\u00eapier dans lequel elle \u00e9tait tomb\u00e9e. C\u2019est du moins ce qu\u2019esp\u00e8rent les \u00e9l\u00e8ves et les parents d\u2019\u00e9l\u00e8ves tourment\u00e9s par la perspective d\u2019une ann\u00e9e blanche qui se pr\u00e9cisait de plus en plus avec des enseignants qui avaient d\u00e9cid\u00e9 de ne plus rien conc\u00e9der.<br>Au regard des cons\u00e9quences f\u00e2cheuses de cette gr\u00e8ve des enseignants, il serait superflu de rappeler l\u2019imp\u00e9rieuse n\u00e9cessit\u00e9 pour les nouvelles autorit\u00e9s d\u2019honorer leurs engagements pour que plus jamais l\u2019\u00e9cole ne connaisse une telle turbulence.<\/p>\n\n\n\n<p>PAR B.D.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En prenant l\u2019Ordonnance n\u00b02020-002\/P-CNSP du 11 septembre 2020, le Comit\u00e9 National pour le Salut du Peuple (CNSP) met un terme<\/p>\n","protected":false},"author":1,"featured_media":1955,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecole"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecole: Tous en classe ! - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecole: Tous en classe ! - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"En prenant l\u2019Ordonnance n\u00b02020-002\/P-CNSP du 11 septembre 2020, le Comit\u00e9 National pour le Salut du Peuple (CNSP) met un terme\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-22T15:49:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/10\/OUANE-Moctar.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/22\\\/ecole-tous-en-classe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/22\\\/ecole-tous-en-classe\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Ecole: Tous en classe !\",\"datePublished\":\"2020-10-22T15:49:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/22\\\/ecole-tous-en-classe\\\/\"},\"wordCount\":424,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/22\\\/ecole-tous-en-classe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/OUANE-Moctar.jpeg\",\"articleSection\":[\"ACTIVITES\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/22\\\/ecole-tous-en-classe\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/22\\\/ecole-tous-en-classe\\\/\",\"name\":\"Ecole: Tous en classe ! - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/22\\\/ecole-tous-en-classe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/22\\\/ecole-tous-en-classe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/OUANE-Moctar.jpeg\",\"datePublished\":\"2020-10-22T15:49:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/22\\\/ecole-tous-en-classe\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/22\\\/ecole-tous-en-classe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/22\\\/ecole-tous-en-classe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/OUANE-Moctar.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/OUANE-Moctar.jpeg\",\"width\":680,\"height\":549},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/22\\\/ecole-tous-en-classe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecole: Tous en classe !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecole: Tous en classe ! - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/","og_locale":"fr_FR","og_type":"article","og_title":"Ecole: Tous en classe ! - REUSSITE INFO","og_description":"En prenant l\u2019Ordonnance n\u00b02020-002\/P-CNSP du 11 septembre 2020, le Comit\u00e9 National pour le Salut du Peuple (CNSP) met un terme","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/","og_site_name":"REUSSITE INFO","article_published_time":"2020-10-22T15:49:36+00:00","og_image":[{"width":680,"height":549,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/10\/OUANE-Moctar.jpeg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Ecole: Tous en classe !","datePublished":"2020-10-22T15:49:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/"},"wordCount":424,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/10\/OUANE-Moctar.jpeg","articleSection":["ACTIVITES"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/","name":"Ecole: Tous en classe ! - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/10\/OUANE-Moctar.jpeg","datePublished":"2020-10-22T15:49:36+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/10\/OUANE-Moctar.jpeg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/10\/OUANE-Moctar.jpeg","width":680,"height":549},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/22\/ecole-tous-en-classe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Ecole: Tous en classe !"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1954"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1954\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1955"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}