{"id":1929,"date":"2020-10-08T09:25:31","date_gmt":"2020-10-08T09:25:31","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=1929"},"modified":"2020-10-08T09:25:31","modified_gmt":"2020-10-08T09:25:31","slug":"vers-une-monnaie-unique-du-franc-cfa-a-leco","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/","title":{"rendered":"Vers une monnaie unique : du franc CFA \u00e0 l\u2019\u00e9co"},"content":{"rendered":"\n<p>Une \u00e9tape importante vers la monnaie unique a \u00e9t\u00e9 franchie le 21 d\u00e9cembre 2019, lorsque le Pr\u00e9sident ivoirien et actuel Pr\u00e9sident en exercice de l\u2019UEMOA, Alassane Ouattara, et le Pr\u00e9sident fran\u00e7ais, Emmanuel MACRON, ont annonc\u00e9 la r\u00e9forme du franc CFA, la monnaie commune aux huit pays membres de l\u2019UEMOA. 134 millions de personnes au B\u00e9nin, au Burkina Faso, en C\u00f4te d\u2019Ivoire, en Guin\u00e9e-Bissau, au Mali, au Niger, au S\u00e9n\u00e9gal et au Togo utilisent le franc CFA. Le franc CFA sera renomm\u00e9 \u00ab \u00e9co \u00bb ; la France se retirera de tous les organes de gouvernance et la moiti\u00e9 des r\u00e9serves de change ne seront plus d\u00e9tenues par la Banque de France. L\u2019\u00e9co continue cependant d\u2019avoir une parit\u00e9 fixe avec l\u2019euro et la France garde pour le moment son r\u00f4le de garant financier.<br>Cr\u00e9\u00e9 en 1945, sous le nom de \u00ab Franc des colonies fran\u00e7aises d\u2019Afrique \u00bb et devenu en 1958 \u00ab Franc de la Communaut\u00e9 financi\u00e8re africaine \u00bb, le changement de nom de la monnaie commune est hautement symbolique. Le projet de r\u00e9forme pr\u00e9voit de r\u00e9duire les liens financiers avec l\u2019ancienne puissance coloniale. Cependant, de nombreux \u00e9conomistes africains pensent qu\u2019il ne devrait plus y avoir aucun accord de coop\u00e9ration mon\u00e9taire entre la France et les pays africains. \u00ab Avec le maintien de cette garantie, en attendant l\u2019\u00e9co, nous voulons \u00e9viter la sp\u00e9culation et la fuite des capitaux \u00bb, a expliqu\u00e9 Alassane Ouattara. D\u2019autres voix critiques affirment que la r\u00e9forme du franc CFA ne va pas assez loin, notamment en ce qui concerne le taux de change fixe avec l\u2019euro qui rendrait les exportations ouest-africaines moins comp\u00e9titives.<br>Au niveau international, la r\u00e9forme du franc CFA a \u00e9t\u00e9 salu\u00e9e par la Banque africaine de d\u00e9veloppement ainsi que de nombreux autres partenaires financiers. Le FMI l\u2019a consid\u00e9r\u00e9e comme \u00ab un pas important dans la modernisation d\u2019accords de longue dur\u00e9e \u00bb entre l\u2019espace UEMOA et la France. Au niveau r\u00e9gional, la r\u00e9forme de la zone mon\u00e9taire UEMOA facilitera son int\u00e9gration dans la future zone mon\u00e9taire de la CEDEAO qui a d\u00e9j\u00e0 \u00e9t\u00e9 d\u00e9cid\u00e9e en 2003 avec notamment la cr\u00e9ation d\u2019une monnaie unique appel\u00e9e \u00e9galement \u00ab \u00e9co \u00bb. Lors de la 56e session ordinaire de l\u2019Autorit\u00e9 des chefs d\u2019\u00c9tat et de gouvernement, le 21 d\u00e9cembre 2019 \u00e0 Abuja, les responsables ouest-africains ont pris des mesures pour acc\u00e9l\u00e9rer la cr\u00e9ation de l\u2019Union mon\u00e9taire de la CEDEAO en 2020. Ils ont adopt\u00e9 le symbole de l\u2019\u00e9co, la monnaie unique de la CEDEAO et le nom de la Banque centrale de la CEDEAO : la Banque centrale de l\u2019Afrique de l\u2019Ouest (BCAO).<br>Les \u00e9conomies ouest-africaines peinent cependant \u00e0 remplir les crit\u00e8res de convergence, notamment un d\u00e9ficit public inf\u00e9rieur \u00e0 3 %, un taux d\u2019inflation inf\u00e9rieur \u00e0 10 % et une dette repr\u00e9sentant moins de 70 % du PIB national. L\u2019introduction d\u2019une monnaie unique a d\u00e9j\u00e0 \u00e9t\u00e9 report\u00e9e maintes fois. La r\u00e9forme du franc CFA ne repr\u00e9sente ainsi qu\u2019un pas important dans la construction de la nouvelle monnaie plus englobante de la CEDEAO et la question cruciale est de savoir si les \u00e9conomies anglophones rejoindront la nouvelle monnaie dans un futur proche. Si le g\u00e9ant \u00e9conomique qu\u2019est le Nig\u00e9ria a requis du temps pour analyser les implications de la r\u00e9forme du franc CFA, le Ghana, la deuxi\u00e8me \u00e9conomie la plus importante de la r\u00e9gion, a confirm\u00e9 son soutien. \u00ab C\u2019est une d\u00e9cision bienvenue que le Ghana applaudit chaleureusement. [\u2026] Nous, au Ghana, sommes d\u00e9termin\u00e9s \u00e0 faire ce que nous pourrons pour pouvoir rejoindre bient\u00f4t les \u00c9tats membres de l\u2019UEMOA dans leur usage de l\u2019Eco car nous pensons qu\u2019il permettra d\u2019\u00e9liminer les barri\u00e8res commerciales et mon\u00e9taires, de r\u00e9duire les co\u00fbts des transactions, de stimuler l\u2019activit\u00e9 \u00e9conomique et d\u2019\u00e9lever le niveau de vie de nos populations \u00bb, affirme un communiqu\u00e9 de presse du gouvernement<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une \u00e9tape importante vers la monnaie unique a \u00e9t\u00e9 franchie le 21 d\u00e9cembre 2019, lorsque le Pr\u00e9sident ivoirien et actuel<\/p>\n","protected":false},"author":1,"featured_media":1930,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vers une monnaie unique : du franc CFA \u00e0 l\u2019\u00e9co - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vers une monnaie unique : du franc CFA \u00e0 l\u2019\u00e9co - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"Une \u00e9tape importante vers la monnaie unique a \u00e9t\u00e9 franchie le 21 d\u00e9cembre 2019, lorsque le Pr\u00e9sident ivoirien et actuel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-08T09:25:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/10\/Franc-Eco-et-Cfa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"790\" \/>\n\t<meta property=\"og:image:height\" content=\"444\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/08\\\/vers-une-monnaie-unique-du-franc-cfa-a-leco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/08\\\/vers-une-monnaie-unique-du-franc-cfa-a-leco\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Vers une monnaie unique : du franc CFA \u00e0 l\u2019\u00e9co\",\"datePublished\":\"2020-10-08T09:25:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/08\\\/vers-une-monnaie-unique-du-franc-cfa-a-leco\\\/\"},\"wordCount\":696,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/08\\\/vers-une-monnaie-unique-du-franc-cfa-a-leco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Franc-Eco-et-Cfa.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/08\\\/vers-une-monnaie-unique-du-franc-cfa-a-leco\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/08\\\/vers-une-monnaie-unique-du-franc-cfa-a-leco\\\/\",\"name\":\"Vers une monnaie unique : du franc CFA \u00e0 l\u2019\u00e9co - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/08\\\/vers-une-monnaie-unique-du-franc-cfa-a-leco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/08\\\/vers-une-monnaie-unique-du-franc-cfa-a-leco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Franc-Eco-et-Cfa.jpg\",\"datePublished\":\"2020-10-08T09:25:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/08\\\/vers-une-monnaie-unique-du-franc-cfa-a-leco\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/08\\\/vers-une-monnaie-unique-du-franc-cfa-a-leco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/08\\\/vers-une-monnaie-unique-du-franc-cfa-a-leco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Franc-Eco-et-Cfa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Franc-Eco-et-Cfa.jpg\",\"width\":790,\"height\":444},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/10\\\/08\\\/vers-une-monnaie-unique-du-franc-cfa-a-leco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vers une monnaie unique : du franc CFA \u00e0 l\u2019\u00e9co\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vers une monnaie unique : du franc CFA \u00e0 l\u2019\u00e9co - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/","og_locale":"fr_FR","og_type":"article","og_title":"Vers une monnaie unique : du franc CFA \u00e0 l\u2019\u00e9co - REUSSITE INFO","og_description":"Une \u00e9tape importante vers la monnaie unique a \u00e9t\u00e9 franchie le 21 d\u00e9cembre 2019, lorsque le Pr\u00e9sident ivoirien et actuel","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/","og_site_name":"REUSSITE INFO","article_published_time":"2020-10-08T09:25:31+00:00","og_image":[{"width":790,"height":444,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/10\/Franc-Eco-et-Cfa.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Vers une monnaie unique : du franc CFA \u00e0 l\u2019\u00e9co","datePublished":"2020-10-08T09:25:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/"},"wordCount":696,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/10\/Franc-Eco-et-Cfa.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/","name":"Vers une monnaie unique : du franc CFA \u00e0 l\u2019\u00e9co - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/10\/Franc-Eco-et-Cfa.jpg","datePublished":"2020-10-08T09:25:31+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/10\/Franc-Eco-et-Cfa.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/10\/Franc-Eco-et-Cfa.jpg","width":790,"height":444},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/10\/08\/vers-une-monnaie-unique-du-franc-cfa-a-leco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Vers une monnaie unique : du franc CFA \u00e0 l\u2019\u00e9co"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1929"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1929\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1930"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}