{"id":1757,"date":"2020-08-28T16:21:07","date_gmt":"2020-08-28T16:21:07","guid":{"rendered":"https:\/\/www.lareussiteinfo.com\/?p=1757"},"modified":"2020-08-28T16:21:07","modified_gmt":"2020-08-28T16:21:07","slug":"sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers","status":"publish","type":"post","link":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/","title":{"rendered":"Sortie de crise : Le soutien ferme des partenaires techniques et financiers"},"content":{"rendered":"\n<p>Cette Table ronde se veut un appel pressant pour la mise en \u0153uvre de l\u2019agenda pour le d\u00e9veloppement du Mali<strong><em>. <\/em><\/strong>Les repr\u00e9sentants de l\u2019Union africaine, de la CEDEAO et les ambassadeurs d\u2019Allemagne et d\u2019Alg\u00e9rie ont rencontr\u00e9 hier les forces vives du Mali au cours d\u2019une table ronde.<\/p>\n\n\n\n<p>Relancer la mise en \u0153uvre de l\u2019Agenda pour le d\u00e9veloppement du Mali dans ce contexte de crise sociopolitique du pays marqu\u00e9e par la d\u00e9mission du pr\u00e9sident de la R\u00e9publique, Ibrahim Boubacar KE\u00cfTA : c\u2019est le sens qu\u2019il faut donner \u00e0 la table ronde qui a r\u00e9uni, hier \u00e0 l\u2019\u00c9cole de maintien de la paix, Alioune Blondin BEYE les forces vives du Mali autour des partenaires techniques et financiers de notre pays. C\u2019\u00e9tait en pr\u00e9sence de l\u2019ambassadeur de la R\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne, Dr Dietrich POHL, du repr\u00e9sentant de l\u2019Union africaine (UA), Pierre Buyoya et de celui de la Communaut\u00e9 \u00e9conomique des \u00e9tats de l\u2019Afrique de l\u2019ouest (CEDEOA), Hamidou BOLY. Le pr\u00e9sident du Comit\u00e9 de suivi de l\u2019Accord pour la paix et la r\u00e9conciliation (CSA), par ailleurs ambassadeur d\u2019Alg\u00e9rie, Boualem CHEBIHI, les repr\u00e9sentants de plusieurs d\u00e9partements minist\u00e9riels et de partis politiques ont \u00e9galement pris part \u00e0 cette rencontre.<\/p>\n\n\n\n<p>Dans son intervention, Pierre BUYOYA a rappel\u00e9 que l\u2019UA a suivi avec attention la crise sociopolitique de notre pays, essayant, de son mieux, de contribuer aux solutions. Selon l\u2019ancien pr\u00e9sident burundais, une fois les lignes directrices de la transition connues, l\u2019organisation accompagnera le Mali aux c\u00f4t\u00e9s de la CEDEAO et des autres partenaires internationaux pour que l\u2019ordre constitutionnel soit r\u00e9tabli.<\/p>\n\n\n\n<p>D\u2019apr\u00e8s Pierre BUYOYA, l\u2019organisation continentale a des exp\u00e9riences dans ce domaine, rappelant les m\u00e9canismes qui ont fait d\u00e9j\u00e0 leur preuve au Mali en 2012 et ailleurs \u00e0 d\u2019autres \u00e9poques. Selon lui, au-del\u00e0 du d\u00e9bat sur la transition, le Mali doit continuer \u00e0 vivre.<br>\u00abLe pays doit continuer \u00e0 faire face aux d\u00e9fis s\u00e9curitaire, de la lutte contre la Covid-19, de la crise humanitaire et \u00e0 ceux du d\u00e9veloppement\u00bb, a plaid\u00e9 Pierre BUYOYA, avant de rappeler \u00e0 tous les partenaires qu\u2019il faut garder \u00e0 l\u2019esprit les pr\u00e9occupations de la population malienne. Et d\u2019exhorter \u00e0 la poursuite des programmes de d\u00e9veloppement.<\/p>\n\n\n\n<p>Il a encourag\u00e9 les partenaires europ\u00e9ens et tous les autres \u00e0 poursuivre le soutien au peuple malien malgr\u00e9 les difficult\u00e9s du moment. \u00abLes besoins sont immenses et n\u2019ont pas chang\u00e9 \u00e0 l\u2019allure des changements politiques\u00bb, a soulign\u00e9 le repr\u00e9sentant de l\u2019Union africaine, assurant que son organisation ne manquera pas de contribuer aux efforts des autres. Pour l\u2019ambassadeur de la R\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne, la crise actuelle handicape lourdement le pays. Dr Dietrich POHL a indiqu\u00e9 que des solutions doivent \u00eatre trouv\u00e9es par \u2018\u2019le Mali et avec le Mali\u2019\u2019&nbsp;au niveau r\u00e9gional sur la base de la d\u00e9mocratie et conform\u00e9ment \u00e0 la Constitution.<\/p>\n\n\n\n<p>\u00abNous sommes aux c\u00f4t\u00e9s du peuple malien, de l\u2019UA et de la CEDEAO\u00bb, a rassur\u00e9 le diplomate allemand pour qui la Table ronde se veut un appel pressant aupr\u00e8s de toutes et de tous afin de relancer, de fa\u00e7on imm\u00e9diate, coordonn\u00e9e et soutenue, la mise en \u0153uvre de l\u2019Agenda pour le d\u00e9veloppement du Mali.<\/p>\n\n\n\n<p>Par ailleurs, l\u2019ambassadeur de la R\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne a invit\u00e9 les acteurs politiques et sociaux maliens \u00e0 assumer leur responsabilit\u00e9. Pour lui, les partenaires ont besoin de structures \u00e9tatiques qui travaillent dans la l\u00e9gitimit\u00e9 et la l\u00e9galit\u00e9, dans un Mali d\u00e9mocratique et constitutionaliste. \u00abLa bonne gouvernance et la lutte s\u00e9rieuse contre la corruption sont importantes pour permettre \u00e0 tous les segments de la population de participer pleinement au d\u00e9veloppement \u00e9conomique et social. Une paix et une s\u00e9curit\u00e9 durable en d\u00e9pendent \u00e9galement\u00bb, a-t-il estim\u00e9.<\/p>\n\n\n\n<p>Rappelant les efforts fournis par la CEDEAO pour juguler la crise, son repr\u00e9sentant dira que le souci de l\u2019organisation est que la situation ne perdure.&nbsp;Le souci des dirigeants de la CEDEAO, a poursuivi Hamidou BOLY, est que l\u2019ordre constitutionnel revienne, permettant au peuple de pouvoir revenir au-devant des d\u00e9cisions. \u00abNous allons \u0153uvrer dans ce sens pour que tr\u00e8s rapidement les mesures ou les sanctions qui ont \u00e9t\u00e9 mises en \u0153uvre soient lev\u00e9es le plus rapidement possible et que nous puissions faire le d\u00e9veloppement avec les partenaires qui sont ici\u00bb, a soulign\u00e9 Hamidou BOLY.<\/p>\n\n\n\n<p>Pour sa part, le pr\u00e9sident du CSA a rappel\u00e9 les acquis de l\u2019Accord pour la paix et la r\u00e9conciliation, avant d\u2019indiquer que cette crise sociopolitique a r\u00e9duit consid\u00e9rablement les activit\u00e9s de mise en \u0153uvre du document notamment en l\u2019absence d\u2019un gouvernement. Et d\u2019esp\u00e9rer vivement la reprise \u00e0 br\u00e8ve \u00e9ch\u00e9ance de ces activit\u00e9s.<\/p>\n\n\n\n<p>\u00abNous sommes d\u2019ores et d\u00e9j\u00e0 encourag\u00e9s par l\u2019appui \u00e0 l\u2019Accord exprim\u00e9 par le Comit\u00e9 national pour le salut du peuple\u00bb, a appr\u00e9ci\u00e9 Boualem CHEBIHI, avant d\u2019exhorter la communaut\u00e9 internationale dans son ensemble \u00e0 poursuivre son accompagnement aux strat\u00e9gies de d\u00e9veloppement valid\u00e9es par les autorit\u00e9s maliennes.<\/p>\n\n\n\n<p><strong>Bembablin DOUMBIA<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette Table ronde se veut un appel pressant pour la mise en \u0153uvre de l\u2019agenda pour le d\u00e9veloppement du Mali.<\/p>\n","protected":false},"author":1,"featured_media":1758,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sortie de crise : Le soutien ferme des partenaires techniques et financiers - REUSSITE INFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sortie de crise : Le soutien ferme des partenaires techniques et financiers - REUSSITE INFO\" \/>\n<meta property=\"og:description\" content=\"Cette Table ronde se veut un appel pressant pour la mise en \u0153uvre de l\u2019agenda pour le d\u00e9veloppement du Mali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/\" \/>\n<meta property=\"og:site_name\" content=\"REUSSITE INFO\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-28T16:21:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/08\/Atelier_agri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rdesign2622@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rdesign2622@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/08\\\/28\\\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/08\\\/28\\\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\\\/\"},\"author\":{\"name\":\"rdesign2622@gmail.com\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"headline\":\"Sortie de crise : Le soutien ferme des partenaires techniques et financiers\",\"datePublished\":\"2020-08-28T16:21:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/08\\\/28\\\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\\\/\"},\"wordCount\":906,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/08\\\/28\\\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Atelier_agri.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/08\\\/28\\\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\\\/\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/08\\\/28\\\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\\\/\",\"name\":\"Sortie de crise : Le soutien ferme des partenaires techniques et financiers - REUSSITE INFO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/08\\\/28\\\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/08\\\/28\\\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Atelier_agri.jpg\",\"datePublished\":\"2020-08-28T16:21:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/08\\\/28\\\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/08\\\/28\\\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/08\\\/28\\\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Atelier_agri.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Atelier_agri.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/2020\\\/08\\\/28\\\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sortie de crise : Le soutien ferme des partenaires techniques et financiers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/\",\"name\":\"REUSSITE INFO\",\"description\":\"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reussiteinfo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/#\\\/schema\\\/person\\\/6cfad15f910b3d52c1cd207be77df402\",\"name\":\"rdesign2622@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"contentUrl\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\",\"width\":145,\"height\":107,\"caption\":\"rdesign2622@gmail.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reussiteinfo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-REUSSITE-INFO.png\"},\"sameAs\":[\"http:\\\/\\\/reussiteinfo.com\"],\"url\":\"https:\\\/\\\/www.reussiteinfo.com\\\/index.php\\\/author\\\/rdesign2622gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sortie de crise : Le soutien ferme des partenaires techniques et financiers - REUSSITE INFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/","og_locale":"fr_FR","og_type":"article","og_title":"Sortie de crise : Le soutien ferme des partenaires techniques et financiers - REUSSITE INFO","og_description":"Cette Table ronde se veut un appel pressant pour la mise en \u0153uvre de l\u2019agenda pour le d\u00e9veloppement du Mali.","og_url":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/","og_site_name":"REUSSITE INFO","article_published_time":"2020-08-28T16:21:07+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/08\/Atelier_agri.jpg","type":"image\/jpeg"}],"author":"rdesign2622@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rdesign2622@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/#article","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/"},"author":{"name":"rdesign2622@gmail.com","@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"headline":"Sortie de crise : Le soutien ferme des partenaires techniques et financiers","datePublished":"2020-08-28T16:21:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/"},"wordCount":906,"publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/08\/Atelier_agri.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/","url":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/","name":"Sortie de crise : Le soutien ferme des partenaires techniques et financiers - REUSSITE INFO","isPartOf":{"@id":"https:\/\/www.reussiteinfo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/#primaryimage"},"image":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/08\/Atelier_agri.jpg","datePublished":"2020-08-28T16:21:07+00:00","breadcrumb":{"@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/#primaryimage","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/08\/Atelier_agri.jpg","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2020\/08\/Atelier_agri.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.reussiteinfo.com\/index.php\/2020\/08\/28\/sortie-de-crise-le-soutien-ferme-des-partenaires-techniques-et-financiers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reussiteinfo.com\/"},{"@type":"ListItem","position":2,"name":"Sortie de crise : Le soutien ferme des partenaires techniques et financiers"}]},{"@type":"WebSite","@id":"https:\/\/www.reussiteinfo.com\/#website","url":"https:\/\/www.reussiteinfo.com\/","name":"REUSSITE INFO","description":"JOURNAL D\u2019INFORMATION SUR L\u2019ECONOMIE ET LE CONTENU LOCAL EN AFRIQUE","publisher":{"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reussiteinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reussiteinfo.com\/#\/schema\/person\/6cfad15f910b3d52c1cd207be77df402","name":"rdesign2622@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","url":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","contentUrl":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png","width":145,"height":107,"caption":"rdesign2622@gmail.com"},"logo":{"@id":"https:\/\/www.reussiteinfo.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-REUSSITE-INFO.png"},"sameAs":["http:\/\/reussiteinfo.com"],"url":"https:\/\/www.reussiteinfo.com\/index.php\/author\/rdesign2622gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1757"}],"version-history":[{"count":0,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1758"}],"wp:attachment":[{"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reussiteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}